{"id":15350,"date":"2026-02-23T20:41:40","date_gmt":"2026-02-23T19:41:40","guid":{"rendered":"https:\/\/boskapszczola.pl\/?page_id=15350"},"modified":"2026-04-29T11:45:06","modified_gmt":"2026-04-29T09:45:06","slug":"plant-based-skincare-from-herbs-flowers","status":"publish","type":"page","link":"https:\/\/boskapszczola.pl\/en\/","title":{"rendered":"Boska pszczo\u0142a"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15350\" class=\"elementor elementor-15350 elementor-15349\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f625d80 e-con-full e-flex e-con e-parent\" data-id=\"f625d80\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-53fea18 e-con-full e-flex e-con e-child\" data-id=\"53fea18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6bd7dab e-con-full e-flex e-con e-child\" data-id=\"6bd7dab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f65891 elementor-widget elementor-widget-rating\" data-id=\"6f65891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"4.7\" role=\"img\" aria-label=\"Rated 4.7 out of 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\" style=\"--e-rating-icon-marked-width: 70%;\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-212f173 elementor-widget elementor-widget-text-editor\" data-id=\"212f173\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/boskapszczola.pl\/en\/opinions\/\">rating: <strong>4.90<\/strong> | 12.5K+ followers<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99eff19 e-con-full e-flex e-con e-child\" data-id=\"99eff19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2225fd4 elementor-widget elementor-widget-heading\" data-id=\"2225fd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LET YOUR SKIN BLOOM WITH HERBS &amp; FLOWERS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5f43a7 elementor-widget elementor-widget-text-editor\" data-id=\"e5f43a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Enjoy insanely soft and radiant skin, just like 1092+ of my customers<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a3f91 elementor-widget elementor-widget-button\" data-id=\"e4a3f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/boskapszczola.pl\/en\/store\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover your ritual<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f5e1ae e-flex e-con-boxed e-con e-parent\" data-id=\"4f5e1ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8944d60 e-con-full e-flex e-con e-child\" data-id=\"8944d60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28f8e8f e-con-full e-flex e-con e-child\" data-id=\"28f8e8f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3be474d elementor-widget elementor-widget-image\" data-id=\"3be474d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/elementor\/thumbs\/roslinne-kosmetyki-rjjcqbx3a74o3y306wej96m0xzpe05i7ta4v9eiol0.png\" title=\"ro\u015blinne kosmetyki\" alt=\"ro\u015blinne kosmetyki\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c20672 e-flex e-con-boxed e-con e-parent\" data-id=\"7c20672\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be95480 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"be95480\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline&quot;,&quot;highlighted_text&quot;:&quot;HERBS&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">FEED YOUR SKIN WITH<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">HERBS<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12b5ee3 e-flex e-con-boxed e-con e-parent\" data-id=\"12b5ee3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3836402 e-con-full e-flex e-con e-child\" data-id=\"3836402\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d0db8e elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2d0db8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><path fill=\"#38e53a\" d=\"M 679.664062 212.9375 C 678.347656 285.632812 676.886719 359.203125 651.582031 429.558594 C 629.058594 492.015625 599.074219 552.859375 560.605469 610.636719 C 548.171875 629.210938 509.265625 714.191406 487.472656 765.96875 C 480.742188 781.914062 457.195312 783.816406 447.6875 769.1875 C 408.636719 709.21875 153.402344 505.910156 116.835938 442.429688 C 94.019531 403.085938 91.238281 359.351562 88.605469 316.789062 C 84.511719 247.3125 81 174.617188 121.222656 111.429688 C 147.40625 70.328125 208.398438 49.851562 266.902344 74.277344 C 344.714844 106.75 350.566406 229.757812 360.074219 258.28125 C 368.265625 282.5625 391.523438 265.886719 397.078125 251.550781 C 407.027344 225.371094 403.808594 112.746094 453.832031 69.742188 C 488.496094 40.050781 553.730469 43.414062 597.757812 63.015625 C 641.78125 82.617188 668.402344 119.035156 676.300781 156.332031 C 680.25 175.054688 679.957031 194.070312 679.664062 212.9375 Z M 679.664062 212.9375 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ed518d\" d=\"M 679.8125 200.359375 C 679.8125 204.601562 679.664062 208.695312 679.664062 212.9375 C 679.664062 213.816406 679.664062 214.546875 679.664062 215.425781 C 678.640625 215.71875 677.617188 216.15625 676.445312 216.449219 C 629.058594 233.269531 585.324219 258.867188 545.976562 288.410156 C 508.679688 316.496094 474.746094 348.234375 442.277344 381.144531 C 461.289062 382.460938 480.304688 384.507812 499.171875 387.289062 C 543.785156 393.722656 587.808594 403.960938 630.519531 418.003906 C 637.980469 420.488281 645.4375 423.121094 652.898438 425.753906 C 652.460938 427.070312 652.019531 428.386719 651.582031 429.558594 C 650.410156 432.628906 649.242188 435.847656 648.070312 438.917969 C 581.8125 414.933594 511.753906 400.011719 440.960938 395.039062 C 445.492188 417.566406 449.296875 440.234375 452.660156 462.90625 C 468.3125 477.679688 482.792969 493.332031 496.101562 510.003906 C 521.699219 541.746094 542.761719 576.554688 558.996094 613.121094 C 556.507812 617.070312 553.4375 622.777344 549.925781 629.796875 C 540.710938 607.125 529.597656 585.183594 516.578125 564.269531 C 499.320312 536.480469 479.136719 510.445312 456.023438 486.75 C 456.902344 493.621094 457.78125 500.351562 458.511719 507.226562 C 463.777344 551.398438 466.996094 595.714844 469.1875 640.035156 C 470.210938 662.121094 470.945312 684.207031 471.527344 706.441406 C 472.113281 728.527344 472.40625 750.613281 472.40625 772.699219 C 472.40625 775.917969 469.773438 778.550781 466.554688 778.550781 C 463.628906 778.550781 461.289062 776.5 460.851562 773.722656 C 459.828125 768.308594 458.949219 762.753906 458.074219 757.339844 L 455.441406 740.957031 C 453.683594 729.988281 452.074219 719.164062 450.46875 708.195312 L 441.105469 642.667969 C 434.960938 599.082031 428.527344 555.640625 421.359375 512.636719 C 419.3125 500.789062 417.265625 488.941406 415.070312 477.09375 C 411.851562 486.308594 408.925781 495.523438 406.003906 504.886719 C 389.914062 557.6875 381.136719 639.597656 376.75 694.152344 C 372.214844 688.59375 360.660156 680.257812 356.125 674.992188 C 359.636719 639.742188 371.042969 579.917969 379.382812 545.253906 C 384.5 523.753906 390.644531 502.546875 397.664062 481.484375 C 401.175781 470.804688 405.125 460.128906 409.074219 449.597656 C 409.21875 449.304688 409.367188 448.867188 409.511719 448.574219 C 406.292969 432.191406 402.785156 415.808594 399.128906 399.574219 C 381.867188 403.816406 366.363281 413.761719 352.324219 423.855469 C 317.949219 448.132812 283.578125 473.878906 254.472656 503.714844 C 242.769531 515.710938 228.144531 536.480469 219.074219 550.226562 C 214.980469 547.449219 208.542969 541.746094 202.984375 535.308594 C 226.386719 500.351562 266.757812 470.511719 300.542969 444.476562 C 317.804688 431.167969 335.0625 417.710938 353.347656 405.71875 C 366.511719 397.085938 380.550781 389.773438 395.910156 385.972656 C 395.761719 385.53125 395.761719 385.09375 395.617188 384.507812 L 393.570312 376.171875 C 376.164062 369.296875 358.464844 363.007812 340.621094 357.011719 C 259.003906 329.660156 174.023438 312.105469 87.875 304.5 C 87.582031 299.820312 87.289062 295.140625 87.144531 290.3125 C 108.351562 292.214844 129.414062 294.554688 150.476562 297.480469 C 232.386719 309.179688 312.539062 329.949219 389.328125 359.203125 C 388.742188 357.011719 388.15625 354.816406 387.574219 352.621094 L 383.332031 336.824219 C 382.453125 333.460938 381.574219 329.949219 380.550781 326.585938 C 368.265625 306.988281 353.929688 288.410156 337.988281 271.152344 C 306.980469 237.949219 269.976562 209.71875 228.875 187.925781 C 190.261719 167.597656 147.988281 152.96875 104.109375 145.21875 C 105.863281 140.828125 107.765625 136.292969 109.960938 131.90625 C 133.363281 136.148438 156.472656 142.292969 178.707031 150.335938 C 193.476562 155.601562 207.8125 161.746094 221.855469 168.472656 C 221.414062 167.742188 220.976562 167.011719 220.683594 166.28125 C 209.128906 144.777344 202.402344 120.9375 199.476562 96.949219 C 198.160156 85.980469 196.402344 76.324219 195.820312 65.355469 C 200.792969 64.625 205.472656 64.1875 210.589844 64.039062 C 211.324219 76.179688 213.078125 86.710938 214.832031 98.851562 C 216.296875 109.382812 218.78125 120.5 222.144531 130.882812 C 228.144531 150.773438 237.359375 172.128906 254.617188 186.171875 C 272.167969 196.554688 288.84375 207.964844 304.640625 220.691406 C 329.359375 240.289062 351.589844 262.667969 370.753906 287.09375 C 370.3125 282.5625 370.167969 277.878906 370.605469 273.054688 C 370.898438 270.128906 371.335938 267.058594 371.921875 263.984375 C 372.652344 260.914062 373.386719 257.695312 374.847656 254.332031 L 374.847656 254.183594 C 376.601562 250.234375 380.992188 248.480469 384.941406 250.089844 C 385.230469 250.234375 385.523438 250.382812 385.816406 250.527344 C 389.035156 252.429688 391.523438 254.476562 393.863281 256.671875 C 396.203125 258.867188 398.394531 261.058594 400.296875 263.398438 C 404.101562 268.082031 407.320312 272.90625 409.953125 278.027344 C 410.976562 280.21875 412 282.269531 412.730469 284.460938 C 421.945312 268.375 432.183594 252.722656 443.152344 237.65625 C 458.511719 216.59375 475.625 196.554688 493.90625 177.6875 C 493.90625 177.542969 493.90625 177.25 493.90625 177.101562 C 496.394531 164.230469 498.734375 151.214844 500.636719 138.195312 C 504.730469 109.820312 504.585938 78.519531 500.34375 49.851562 C 505.171875 49.121094 510.875 48.535156 515.847656 48.242188 C 521.113281 84.664062 518.625 123.277344 512.335938 159.550781 C 522.28125 150.191406 532.667969 141.121094 543.34375 132.492188 C 568.503906 112.308594 595.414062 94.171875 623.792969 78.226562 C 628.03125 81.300781 631.980469 84.515625 635.785156 87.878906 C 624.960938 93.730469 614.285156 100.019531 604.046875 106.601562 C 563.382812 132.492188 526.523438 163.355469 494.347656 198.019531 C 464.507812 230.199219 439.058594 265.886719 418.582031 303.914062 L 420.191406 309.765625 C 421.796875 315.179688 423.113281 320.589844 424.578125 326 L 428.820312 342.238281 C 430.28125 347.648438 431.453125 353.0625 432.621094 358.621094 L 434.671875 367.6875 C 451.78125 350.429688 469.1875 333.609375 487.472656 317.519531 C 527.402344 282.121094 570.988281 249.796875 619.550781 225.515625 C 639.003906 215.71875 659.1875 207.234375 679.8125 200.359375 Z M 679.8125 200.359375 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#f99dc0\" d=\"M 474.746094 295.726562 C 474.160156 296.894531 473.429688 297.917969 472.699219 298.941406 C 471.675781 300.40625 470.503906 301.722656 469.1875 303.039062 C 467.871094 304.355469 466.410156 305.378906 464.800781 306.546875 C 463.484375 307.425781 461.730469 307.574219 459.972656 307.425781 C 458.804688 307.574219 457.488281 307.574219 456.316406 307.28125 C 454.5625 306.839844 452.660156 305.523438 451.78125 304.0625 C 450.757812 302.453125 450.46875 300.40625 451.050781 298.648438 C 452.222656 294.992188 453.683594 291.484375 455.441406 288.117188 C 456.316406 286.511719 457.195312 285.046875 458.511719 283.585938 C 459.972656 281.828125 462.167969 280.511719 464.363281 280.074219 C 466.996094 279.488281 470.210938 279.78125 472.554688 281.390625 C 473.871094 282.269531 475.1875 283.292969 475.917969 284.753906 C 476.941406 286.65625 477.378906 288.851562 476.792969 290.898438 C 476.355469 292.507812 475.625 294.117188 474.746094 295.726562 Z M 434.816406 188.65625 C 431.890625 187.050781 428.234375 187.195312 425.164062 188.65625 C 422.675781 189.972656 421.066406 192.460938 420.042969 194.949219 C 419.3125 196.703125 419.164062 198.605469 419.019531 200.359375 C 418.875 201.675781 418.875 203.136719 419.019531 204.453125 C 419.457031 208.550781 420.628906 212.5 422.824219 216.15625 C 423.847656 217.617188 425.457031 218.933594 427.355469 219.375 C 429.113281 219.8125 431.597656 219.667969 433.207031 218.644531 C 435.253906 217.328125 436.71875 215.277344 436.863281 213.085938 C 437.304688 212.5 437.59375 211.769531 437.886719 211.035156 C 438.765625 207.527344 439.351562 203.871094 439.644531 200.359375 C 439.9375 195.972656 439.351562 191.144531 434.816406 188.65625 Z M 491.566406 458.226562 C 492.738281 457.640625 493.613281 456.765625 494.347656 455.738281 C 495.078125 454.570312 495.371094 453.398438 495.371094 452.230469 C 495.808594 449.011719 495.371094 445.648438 494.492188 442.574219 C 493.324219 438.917969 491.273438 435.703125 488.640625 432.777344 C 487.472656 431.460938 485.132812 430.726562 483.375 430.726562 C 481.476562 430.726562 479.28125 431.460938 478.109375 432.777344 C 477.527344 433.359375 477.085938 433.945312 476.648438 434.675781 C 476.648438 434.675781 476.503906 434.675781 476.503906 434.824219 C 476.0625 435.261719 475.769531 435.703125 475.332031 436.285156 C 474.601562 437.457031 474.308594 438.625 474.308594 439.796875 C 473.871094 443.453125 474.894531 447.109375 476.503906 450.328125 C 478.109375 453.691406 480.890625 456.324219 484.109375 458.371094 C 486.15625 459.542969 489.375 459.398438 491.566406 458.226562 Z M 412.144531 556.515625 C 411.707031 554.910156 410.242188 553.152344 408.636719 552.277344 C 406.878906 551.398438 404.832031 550.960938 402.785156 551.542969 C 401.027344 552.128906 399.128906 553.152344 398.25 554.761719 C 396.347656 558.710938 395.324219 562.367188 394.886719 566.753906 C 394.59375 570.414062 395.03125 574.070312 396.203125 577.578125 C 397.078125 580.503906 400.152344 582.84375 403.515625 582.699219 C 404.832031 582.699219 406.148438 582.261719 407.320312 581.675781 C 409.074219 580.796875 410.097656 579.1875 410.828125 577.433594 C 412.875 572.019531 413.167969 566.023438 411.851562 560.464844 C 412.4375 559.296875 412.585938 557.980469 412.144531 556.515625 Z M 372.359375 484.40625 C 371.335938 482.945312 369.726562 481.628906 367.828125 481.191406 C 364.171875 480.457031 360.222656 480.457031 356.5625 481.628906 C 354.808594 482.214844 353.054688 482.800781 351.589844 483.824219 C 349.980469 484.847656 348.519531 485.871094 347.347656 487.1875 C 346.472656 488.066406 345.742188 489.089844 345.449219 490.257812 C 345.007812 491.722656 345.15625 493.332031 345.886719 494.792969 C 346.472656 495.964844 347.203125 496.839844 348.226562 497.570312 C 349.398438 498.449219 351.152344 499.179688 352.761719 499.035156 C 358.757812 498.597656 364.460938 496.988281 369.726562 494.207031 C 371.335938 493.332031 372.652344 491.722656 373.238281 489.964844 C 373.238281 489.820312 373.386719 489.527344 373.386719 489.382812 C 373.386719 489.234375 373.386719 489.089844 373.53125 488.941406 C 373.53125 488.796875 373.53125 488.648438 373.53125 488.648438 C 373.386719 487.1875 373.238281 485.722656 372.359375 484.40625 Z M 541.003906 343.113281 C 542.320312 342.824219 543.34375 342.238281 544.371094 341.359375 C 545.246094 340.480469 545.976562 339.457031 546.269531 338.289062 C 546.5625 336.972656 546.5625 335.800781 546.269531 334.484375 C 545.976562 333.316406 545.246094 332.292969 544.371094 331.414062 C 543.492188 330.828125 542.613281 330.097656 541.738281 329.511719 C 540.859375 329.074219 539.6875 328.632812 538.8125 328.195312 C 537.203125 327.609375 535.59375 327.464844 533.984375 327.316406 C 532.375 327.171875 530.765625 327.464844 529.15625 327.609375 C 527.546875 327.902344 525.941406 328.488281 524.625 329.21875 C 523.015625 329.949219 521.699219 331.851562 521.113281 333.460938 C 520.820312 334.191406 520.820312 334.925781 520.820312 335.65625 C 520.675781 337.117188 520.96875 338.582031 521.84375 339.75 C 522.28125 340.191406 522.574219 340.628906 523.015625 341.214844 C 523.890625 342.089844 525.0625 342.675781 526.378906 342.96875 C 527.257812 343.261719 528.28125 343.554688 529.15625 343.699219 C 530.621094 343.992188 532.230469 344.140625 533.839844 344.140625 C 535.445312 344.140625 536.910156 343.992188 538.519531 343.699219 C 539.105469 343.554688 540.128906 343.40625 541.003906 343.113281 Z M 312.390625 375.148438 C 313.269531 373.683594 313.707031 371.34375 313.125 369.734375 C 312.539062 367.980469 311.367188 366.371094 309.613281 365.492188 C 308.882812 365.054688 308.003906 364.910156 307.273438 364.617188 C 305.808594 363.300781 304.203125 362.128906 302.300781 361.398438 C 299.082031 360.082031 295.570312 359.058594 291.914062 359.496094 C 290.597656 359.496094 289.28125 359.789062 288.113281 360.519531 C 286.941406 361.105469 286.0625 361.984375 285.332031 363.007812 C 284.015625 365.203125 284.015625 367.980469 285.332031 370.175781 C 285.917969 371.199219 286.796875 372.222656 287.527344 373.097656 C 287.964844 373.539062 288.40625 374.125 288.988281 374.414062 C 290.011719 375.148438 291.039062 375.878906 292.0625 376.609375 C 293.230469 377.195312 294.402344 377.632812 295.71875 378.21875 C 297.621094 378.949219 299.667969 379.242188 301.570312 379.242188 C 303.617188 379.390625 305.664062 379.097656 307.566406 378.511719 C 309.613281 377.78125 311.367188 376.757812 312.390625 375.148438 Z M 334.476562 468.757812 C 334.1875 467.878906 333.601562 467.003906 332.871094 466.417969 C 332.429688 465.980469 331.84375 465.6875 331.40625 465.246094 C 330.238281 464.664062 328.921875 464.222656 327.605469 464.222656 C 324.238281 463.929688 320.875 464.953125 317.804688 466.269531 C 316.339844 467.003906 315.023438 467.878906 313.707031 468.902344 C 312.390625 469.925781 311.367188 471.242188 310.492188 472.414062 C 309.757812 473.585938 309.464844 474.753906 309.464844 475.925781 C 309.464844 476.949219 309.613281 477.824219 310.050781 478.703125 C 310.34375 479.582031 310.929688 480.3125 311.660156 480.898438 C 312.539062 481.773438 313.707031 482.359375 315.023438 482.652344 C 316.632812 482.945312 318.390625 483.238281 320.144531 483.238281 C 321.898438 483.238281 323.65625 482.945312 325.261719 482.652344 C 326.289062 482.507812 327.457031 482.066406 328.335938 481.773438 C 329.945312 481.191406 331.554688 480.605469 332.871094 479.582031 C 334.476562 478.558594 335.792969 477.242188 336.378906 475.339844 C 336.820312 473.585938 336.671875 471.390625 335.648438 469.925781 C 335.355469 469.636719 334.917969 469.195312 334.476562 468.757812 Z M 517.164062 204.894531 C 516.871094 204.015625 516.433594 203.136719 515.847656 202.554688 C 515.261719 201.820312 514.675781 201.238281 513.800781 200.796875 C 512.042969 199.921875 509.996094 199.480469 507.949219 200.066406 C 507.804688 200.066406 507.511719 200.214844 507.363281 200.214844 C 507.363281 200.214844 507.21875 200.214844 507.21875 200.214844 C 506.195312 200.214844 505.316406 200.503906 504.4375 201.089844 C 502.828125 202.113281 501.511719 203.429688 500.929688 205.332031 C 500.195312 207.820312 499.613281 210.304688 498.878906 212.792969 C 498.589844 213.667969 498.589844 214.695312 498.734375 215.570312 C 498.734375 216.449219 499.027344 217.328125 499.613281 218.203125 C 500.050781 218.644531 500.34375 219.082031 500.78125 219.667969 C 501.511719 220.398438 502.246094 220.835938 503.269531 221.128906 C 503.855469 221.421875 504.4375 221.566406 505.171875 221.566406 C 505.460938 221.714844 505.902344 221.714844 506.195312 221.714844 C 506.195312 221.714844 506.339844 221.714844 506.339844 221.714844 C 507.65625 221.714844 508.972656 221.421875 510.144531 220.691406 C 510.582031 220.25 511.167969 219.960938 511.605469 219.519531 C 512.484375 218.644531 513.214844 217.617188 513.507812 216.449219 C 513.652344 215.863281 513.800781 215.425781 514.09375 214.839844 C 514.238281 214.546875 514.386719 214.253906 514.53125 213.960938 C 514.675781 213.816406 514.824219 213.667969 514.96875 213.523438 C 516.285156 212.207031 517.164062 210.453125 517.164062 208.550781 C 517.164062 208.402344 517.164062 208.257812 517.164062 208.113281 C 517.164062 207.964844 517.164062 207.820312 517.164062 207.671875 C 517.601562 206.648438 517.457031 205.769531 517.164062 204.894531 Z M 268.074219 179.152344 C 268.367188 179.589844 268.660156 180.027344 268.953125 180.46875 C 269.242188 181.492188 269.828125 182.515625 270.707031 183.246094 C 272.023438 184.417969 274.070312 185.585938 275.972656 185.292969 C 276.117188 185.292969 276.265625 185.292969 276.410156 185.292969 C 276.996094 185.441406 277.582031 185.734375 278.164062 185.878906 C 280.359375 186.464844 282.554688 186.757812 284.746094 186.902344 C 287.089844 187.050781 289.28125 186.757812 291.476562 186.464844 C 292.0625 186.171875 292.644531 186.023438 293.230469 185.734375 C 294.109375 185.292969 294.839844 184.707031 295.277344 183.976562 C 295.863281 183.246094 296.304688 182.515625 296.59375 181.636719 C 297.179688 181.199219 297.621094 180.613281 298.058594 180.027344 C 298.9375 178.417969 299.375 176.371094 298.789062 174.617188 C 298.496094 174.03125 298.351562 173.445312 298.058594 173.007812 C 297.328125 171.984375 296.449219 171.105469 295.277344 170.519531 C 292.644531 168.621094 289.574219 167.304688 286.355469 166.570312 C 284.457031 166.132812 282.40625 165.839844 280.507812 165.695312 C 278.605469 165.546875 276.703125 165.839844 274.800781 165.988281 C 271.875 166.425781 269.097656 167.742188 267.488281 170.230469 C 266.320312 172.863281 266.464844 176.226562 268.074219 179.152344 Z M 254.761719 299.234375 C 254.761719 299.675781 254.617188 300.113281 254.617188 300.699219 C 254.617188 302.453125 255.054688 303.625 255.789062 305.230469 C 256.957031 307.425781 259.296875 309.035156 261.785156 309.765625 C 263.6875 310.351562 265.441406 310.058594 267.34375 309.914062 C 270.558594 309.621094 273.632812 309.328125 276.847656 309.035156 C 277.875 309.035156 278.898438 308.890625 279.773438 308.449219 C 280.652344 308.15625 281.53125 307.71875 282.261719 306.988281 C 283.578125 305.816406 284.601562 303.769531 284.457031 302.015625 C 284.308594 300.257812 283.722656 298.359375 282.261719 297.042969 C 282.113281 296.894531 281.96875 296.894531 281.824219 296.75 C 281.53125 296.015625 280.945312 295.433594 280.359375 294.992188 C 277.726562 292.945312 274.65625 291.191406 271.144531 290.75 C 269.976562 290.605469 268.804688 290.460938 267.78125 290.3125 C 266.609375 290.3125 265.441406 290.460938 264.269531 290.605469 C 263.832031 290.605469 263.246094 290.75 262.808594 290.898438 C 261.785156 291.191406 260.613281 291.628906 259.738281 292.214844 C 257.394531 293.675781 255.789062 295.578125 254.910156 298.066406 C 254.761719 298.210938 254.761719 298.796875 254.761719 299.234375 Z M 260.175781 251.699219 C 261.199219 252.136719 262.222656 252.722656 263.101562 253.308594 C 264.269531 254.183594 265.441406 255.210938 266.464844 256.378906 C 266.902344 256.964844 267.34375 257.402344 268.074219 257.84375 C 268.804688 258.425781 269.683594 258.867188 270.707031 259.160156 C 271.730469 259.449219 272.753906 259.449219 273.777344 259.304688 C 274.800781 259.304688 275.679688 259.011719 276.558594 258.425781 C 278.164062 257.402344 279.628906 256.085938 280.066406 254.183594 C 280.214844 253.601562 280.214844 252.867188 280.359375 252.285156 C 280.359375 250.96875 280.066406 249.796875 279.335938 248.773438 C 277.875 246.871094 276.265625 244.96875 274.363281 243.507812 C 272.460938 242.046875 270.414062 240.582031 268.074219 239.558594 C 267.195312 238.972656 266.320312 238.828125 265.292969 238.679688 C 264.269531 238.535156 263.246094 238.535156 262.222656 238.828125 C 261.199219 238.972656 260.320312 239.414062 259.589844 240.144531 C 258.710938 240.582031 258.128906 241.3125 257.6875 242.191406 C 256.8125 243.800781 256.371094 245.847656 256.957031 247.601562 C 257.25 249.066406 258.421875 250.820312 260.175781 251.699219 Z M 264.5625 421.804688 C 265.003906 420.929688 265.292969 420.050781 265.148438 419.027344 C 265.148438 417.273438 264.269531 415.222656 262.953125 414.054688 C 261.492188 412.882812 259.589844 411.859375 257.6875 412.007812 C 256.957031 412.152344 256.371094 412.152344 255.640625 412.300781 C 254.324219 412.589844 253.300781 413.175781 252.277344 414.054688 C 248.179688 417.125 244.230469 420.050781 240.136719 423.121094 C 239.40625 423.707031 238.820312 424.585938 238.527344 425.316406 C 238.089844 426.195312 237.796875 427.070312 237.941406 428.09375 C 237.941406 429.851562 238.820312 431.898438 240.136719 433.070312 C 241.597656 434.238281 243.5 435.261719 245.402344 435.117188 C 246.132812 434.96875 246.71875 434.96875 247.449219 434.824219 C 248.765625 434.53125 249.789062 433.945312 250.8125 433.070312 C 254.910156 429.996094 258.859375 427.070312 262.953125 424 C 263.6875 423.414062 264.269531 422.683594 264.5625 421.804688 Z M 552.707031 489.964844 C 551.828125 489.089844 550.660156 488.503906 549.34375 488.210938 C 549.050781 488.066406 548.902344 487.917969 548.609375 487.773438 C 548.464844 487.625 548.171875 487.332031 548.027344 487.1875 C 547.585938 486.601562 547.003906 486.015625 546.417969 485.578125 C 545.6875 484.992188 544.808594 484.554688 543.785156 484.261719 C 542.761719 483.96875 541.738281 483.96875 540.710938 484.117188 C 539.6875 484.117188 538.8125 484.40625 537.933594 484.992188 C 537.496094 485.433594 536.910156 485.722656 536.472656 486.164062 C 535.59375 487.039062 534.863281 488.066406 534.570312 489.234375 C 534.421875 489.820312 534.421875 490.550781 534.277344 491.136719 C 534.277344 492.453125 534.570312 493.621094 535.300781 494.648438 C 536.03125 495.523438 536.761719 496.546875 537.496094 497.28125 C 538.371094 498.15625 539.394531 498.742188 540.273438 499.472656 C 540.710938 499.765625 541.296875 500.058594 541.738281 500.351562 C 542.90625 500.9375 543.929688 501.375 545.246094 501.667969 C 546.269531 501.960938 547.292969 501.960938 548.320312 501.8125 C 549.34375 501.8125 550.21875 501.519531 551.097656 500.9375 C 551.976562 500.496094 552.707031 499.914062 553.144531 499.179688 C 553.875 498.449219 554.316406 497.71875 554.460938 496.839844 C 554.609375 496.253906 554.609375 495.523438 554.753906 494.9375 C 554.753906 493.621094 554.460938 492.453125 553.730469 491.429688 C 553.585938 490.84375 553.144531 490.40625 552.707031 489.964844 Z M 549.78125 217.179688 C 548.902344 217.617188 548.320312 218.351562 547.878906 219.226562 C 547.292969 220.105469 547.003906 220.835938 547.003906 221.859375 C 546.710938 222.738281 546.855469 223.761719 547.148438 224.640625 C 547.734375 226.394531 548.902344 228.003906 550.660156 228.882812 C 551.242188 229.175781 551.828125 229.320312 552.414062 229.613281 C 553.730469 229.90625 555.046875 229.90625 556.363281 229.613281 C 558.996094 229.175781 561.628906 228.882812 564.261719 228.441406 C 565.285156 228.296875 566.164062 227.859375 566.894531 227.125 C 567.773438 226.6875 568.355469 225.957031 568.796875 225.078125 C 569.378906 224.199219 569.671875 223.46875 569.671875 222.445312 C 569.964844 221.566406 569.820312 220.542969 569.527344 219.667969 C 568.941406 217.910156 567.773438 216.300781 566.015625 215.425781 C 565.429688 215.132812 564.847656 214.984375 564.261719 214.695312 C 562.945312 214.402344 561.628906 214.402344 560.3125 214.695312 C 557.679688 215.132812 555.046875 215.425781 552.414062 215.863281 C 551.390625 216.15625 550.511719 216.59375 549.78125 217.179688 Z M 458.21875 105.871094 C 458.949219 106.601562 459.679688 107.042969 460.707031 107.335938 C 461.582031 107.773438 462.605469 107.917969 463.628906 107.917969 C 464.363281 107.773438 464.945312 107.773438 465.679688 107.625 C 466.996094 107.335938 468.019531 106.75 469.042969 105.871094 C 469.480469 105.433594 469.773438 104.992188 470.210938 104.410156 C 470.945312 103.238281 471.238281 102.070312 471.238281 100.898438 C 471.238281 98.703125 471.238281 96.511719 471.238281 94.316406 C 471.238281 93.292969 471.089844 92.414062 470.652344 91.539062 C 470.359375 90.660156 469.773438 89.929688 469.042969 89.34375 C 468.3125 88.613281 467.578125 88.171875 466.554688 87.882812 C 465.679688 87.441406 464.65625 87.296875 463.628906 87.296875 C 462.898438 87.441406 462.3125 87.441406 461.582031 87.589844 C 460.265625 87.882812 459.242188 88.464844 458.21875 89.34375 C 457.78125 89.78125 457.488281 90.222656 457.046875 90.804688 C 456.316406 91.976562 456.023438 93.144531 456.023438 94.316406 C 456.023438 96.511719 456.023438 98.703125 456.023438 100.898438 C 456.023438 101.921875 456.171875 102.800781 456.609375 103.675781 C 457.046875 104.410156 457.488281 105.140625 458.21875 105.871094 Z M 253.886719 110.84375 C 254.324219 112.601562 255.789062 114.207031 257.394531 115.085938 C 258.273438 115.671875 259.152344 115.816406 260.175781 115.964844 C 261.199219 116.109375 262.222656 116.109375 263.246094 115.816406 C 265.003906 115.234375 266.902344 114.207031 267.78125 112.601562 C 268.660156 110.992188 269.097656 109.089844 268.511719 107.1875 C 267.636719 103.96875 266.609375 100.753906 265.734375 97.535156 C 265.292969 95.777344 263.832031 94.171875 262.222656 93.292969 C 261.34375 92.707031 260.46875 92.5625 259.445312 92.414062 C 258.421875 92.269531 257.394531 92.269531 256.371094 92.5625 C 254.617188 93.144531 252.714844 94.171875 251.839844 95.777344 C 250.960938 97.386719 250.523438 99.289062 251.105469 101.191406 C 251.984375 104.410156 253.007812 107.625 253.886719 110.84375 Z M 214.246094 388.3125 C 213.371094 387.433594 212.199219 386.847656 210.882812 386.554688 C 208.980469 386.261719 207.226562 385.972656 205.324219 386.261719 C 203.425781 386.410156 201.667969 386.703125 199.914062 387.289062 C 198.890625 387.433594 198.011719 387.871094 197.28125 388.605469 C 196.402344 389.042969 195.820312 389.773438 195.378906 390.652344 C 194.792969 391.527344 194.503906 392.261719 194.503906 393.285156 C 194.210938 394.160156 194.355469 395.1875 194.648438 396.0625 C 194.941406 396.648438 195.085938 397.234375 195.378906 397.671875 C 196.109375 398.695312 196.988281 399.574219 198.160156 400.160156 C 198.742188 400.453125 199.328125 400.597656 199.914062 400.890625 C 201.230469 401.183594 202.546875 401.183594 203.863281 400.890625 C 204.59375 400.597656 205.324219 400.453125 206.058594 400.304688 C 206.496094 400.304688 206.933594 400.304688 207.375 400.304688 C 208.25 400.453125 208.980469 400.453125 209.859375 400.304688 C 210.882812 400.304688 211.761719 400.011719 212.640625 399.425781 C 213.515625 398.988281 214.246094 398.402344 214.6875 397.671875 C 215.417969 396.941406 215.855469 396.210938 216.003906 395.332031 C 216.148438 394.746094 216.148438 394.015625 216.296875 393.429688 C 216.296875 392.113281 216.003906 390.945312 215.273438 389.921875 C 214.980469 389.1875 214.539062 388.75 214.246094 388.3125 Z M 283.429688 501.375 C 281.675781 500.496094 279.628906 500.058594 277.582031 500.644531 C 272.609375 502.105469 268.21875 504.445312 264.417969 507.8125 C 263.101562 508.980469 262.222656 511.027344 262.222656 512.785156 C 262.222656 513.808594 262.371094 514.683594 262.808594 515.5625 C 263.101562 516.441406 263.6875 517.171875 264.417969 517.757812 C 265.878906 518.925781 267.78125 519.949219 269.683594 519.804688 C 271.730469 519.65625 273.484375 519.074219 274.949219 517.757812 C 275.386719 517.464844 275.679688 517.171875 276.117188 516.734375 C 277.289062 515.855469 278.605469 515.269531 279.921875 514.683594 C 280.359375 514.539062 280.796875 514.390625 281.382812 514.246094 C 283.285156 513.660156 284.894531 512.636719 285.917969 511.027344 C 286.503906 510.152344 286.796875 509.417969 286.796875 508.394531 C 287.089844 507.519531 286.941406 506.496094 286.648438 505.617188 C 286.355469 503.863281 285.1875 502.253906 283.429688 501.375 Z M 326.140625 550.519531 C 324.679688 549.351562 322.777344 548.328125 320.875 548.472656 C 318.828125 548.617188 316.925781 549.203125 315.609375 550.519531 C 314.585938 551.542969 313.707031 552.566406 312.832031 553.738281 C 312.246094 554.46875 311.953125 555.199219 311.515625 555.933594 C 310.929688 557.25 310.34375 558.417969 309.90625 559.882812 C 309.613281 561.34375 309.320312 562.660156 309.320312 564.125 C 309.320312 565.148438 309.46875 566.023438 309.90625 566.902344 C 310.199219 567.78125 310.78125 568.511719 311.515625 569.097656 C 312.246094 569.828125 312.976562 570.265625 314 570.558594 C 314.878906 570.996094 315.902344 571.144531 316.925781 571.144531 C 318.828125 570.996094 320.875 570.414062 322.191406 569.097656 C 322.628906 568.65625 322.921875 568.21875 323.363281 567.632812 C 324.09375 566.609375 324.386719 565.292969 324.386719 564.125 C 324.53125 563.539062 324.679688 562.808594 324.972656 562.222656 C 325.261719 561.636719 325.554688 561.199219 325.996094 560.613281 C 326.140625 560.464844 326.140625 560.320312 326.289062 560.320312 C 327.605469 559.003906 328.480469 557.25 328.480469 555.347656 C 328.480469 554.324219 328.335938 553.445312 327.894531 552.566406 C 327.3125 551.835938 326.871094 551.105469 326.140625 550.519531 Z M 566.015625 453.839844 C 563.96875 453.398438 561.921875 452.816406 560.019531 452.230469 C 558.996094 451.789062 558.117188 451.351562 557.242188 450.914062 C 555.484375 450.035156 553.292969 449.742188 551.390625 450.183594 C 549.636719 450.621094 547.734375 451.9375 546.855469 453.398438 C 545.976562 455.007812 545.539062 457.054688 546.125 458.8125 C 546.710938 460.566406 547.878906 462.03125 549.636719 463.054688 C 551.828125 464.222656 554.167969 465.246094 556.507812 465.980469 C 558.265625 466.5625 560.164062 467.148438 562.066406 467.441406 C 563.089844 467.734375 564.113281 467.734375 565.140625 467.585938 C 566.164062 467.585938 567.039062 467.296875 567.917969 466.710938 C 568.796875 466.269531 569.527344 465.6875 569.964844 464.953125 C 570.695312 464.222656 571.136719 463.492188 571.28125 462.613281 C 571.722656 460.859375 571.574219 458.8125 570.550781 457.203125 C 569.527344 455.59375 567.917969 454.277344 566.015625 453.839844 Z M 174.609375 203.871094 C 174.609375 203.871094 174.609375 203.871094 174.464844 203.722656 C 174.464844 203.722656 174.464844 203.578125 174.316406 203.578125 C 174.316406 203.578125 174.316406 203.578125 174.316406 203.722656 C 174.023438 203.285156 173.585938 202.847656 173.292969 202.40625 C 172.5625 201.382812 171.832031 200.359375 171.246094 199.1875 C 170.953125 198.605469 170.660156 198.164062 170.367188 197.582031 C 170.222656 197.289062 170.074219 196.996094 169.929688 196.703125 C 169.929688 196.554688 169.78125 196.554688 169.78125 196.410156 C 169.34375 195.238281 168.90625 194.070312 168.46875 192.898438 C 167.882812 191.144531 165.835938 189.828125 163.785156 190.414062 C 161.886719 191 160.570312 192.898438 161.152344 194.800781 C 162.910156 200.359375 165.835938 205.332031 169.78125 209.71875 C 171.097656 211.183594 173.878906 211.035156 175.046875 209.71875 C 176.511719 208.257812 176.363281 206.210938 175.046875 204.746094 C 175.046875 204.308594 174.902344 204.164062 174.609375 203.871094 Z M 174.609375 203.871094 C 174.609375 203.871094 174.464844 203.722656 174.464844 203.722656 C 174.464844 203.578125 174.464844 203.722656 174.609375 203.871094 C 174.464844 203.722656 174.464844 203.722656 174.609375 203.871094 Z M 164.957031 360.082031 C 159.253906 360.960938 153.839844 363.59375 149.453125 367.25 C 147.988281 368.417969 147.988281 371.050781 149.453125 372.222656 C 151.0625 373.539062 153.253906 373.539062 154.71875 372.222656 C 155.15625 371.929688 155.59375 371.492188 156.035156 371.199219 C 156.179688 371.050781 156.328125 371.050781 156.472656 370.90625 C 156.765625 370.757812 156.910156 370.613281 157.203125 370.46875 C 158.226562 369.882812 159.398438 369.296875 160.421875 368.710938 C 160.714844 368.566406 160.859375 368.566406 161.152344 368.417969 C 161.152344 368.417969 161.007812 368.417969 161.007812 368.417969 C 161.007812 368.417969 161.152344 368.417969 161.152344 368.417969 C 161.152344 368.417969 161.152344 368.417969 161.300781 368.417969 C 161.59375 368.273438 161.445312 368.417969 161.300781 368.417969 C 161.445312 368.417969 161.445312 368.417969 161.59375 368.273438 C 162.175781 368.125 162.761719 367.835938 163.347656 367.6875 C 164.519531 367.394531 165.835938 367.101562 167.152344 366.808594 C 168.027344 366.664062 168.90625 365.933594 169.34375 365.203125 C 169.78125 364.46875 170.074219 363.300781 169.78125 362.421875 C 169.050781 360.519531 167.152344 359.644531 164.957031 360.082031 Z M 161.300781 368.273438 Z M 196.550781 449.742188 C 195.671875 449.597656 194.503906 449.597656 193.625 450.035156 C 191.285156 451.789062 189.238281 453.691406 187.628906 456.03125 C 186.164062 458.226562 185.140625 460.566406 184.554688 463.054688 C 184.410156 463.929688 184.410156 464.953125 184.996094 465.832031 C 185.433594 466.5625 186.3125 467.292969 187.1875 467.441406 C 189.089844 467.878906 191.429688 466.855469 191.871094 464.953125 C 192.160156 463.929688 192.453125 462.90625 192.894531 462.03125 C 193.476562 460.859375 194.210938 459.6875 195.085938 458.664062 C 196.109375 457.640625 197.136719 456.617188 198.304688 455.738281 C 198.160156 455.886719 197.867188 456.03125 197.71875 456.179688 C 198.453125 455.59375 199.183594 455.007812 199.476562 454.132812 C 199.769531 453.253906 199.621094 452.230469 199.035156 451.351562 C 198.304688 450.621094 197.425781 449.890625 196.550781 449.742188 Z M 544.078125 106.75 C 546.269531 106.601562 547.734375 105.140625 547.878906 103.238281 C 547.878906 102.652344 548.027344 101.921875 548.027344 101.335938 C 548.027344 101.335938 548.027344 101.042969 548.027344 100.898438 C 548.027344 100.605469 548.171875 100.3125 548.171875 100.167969 C 548.464844 98.851562 548.757812 97.535156 549.050781 96.363281 C 549.34375 95.195312 549.78125 93.878906 550.367188 92.707031 C 550.367188 92.707031 550.367188 92.5625 550.511719 92.5625 C 550.511719 92.5625 550.511719 92.5625 550.511719 92.414062 C 550.660156 92.121094 550.804688 91.828125 550.953125 91.539062 C 551.242188 90.953125 551.535156 90.367188 551.976562 89.78125 C 552.851562 88.171875 552.414062 85.832031 550.660156 84.957031 C 548.902344 84.078125 546.5625 84.515625 545.539062 86.273438 C 542.46875 91.539062 540.710938 97.386719 540.421875 103.238281 C 540.128906 105.140625 542.027344 106.894531 544.078125 106.75 Z M 618.234375 353.0625 C 616.625 351.453125 614.578125 350.136719 612.527344 349.113281 C 611.359375 348.527344 610.1875 348.089844 608.871094 347.796875 C 607.554688 347.355469 606.238281 347.210938 604.777344 347.0625 C 603.898438 346.917969 602.730469 347.503906 602.144531 348.089844 C 601.558594 348.671875 600.972656 349.695312 600.972656 350.574219 C 600.972656 351.453125 601.265625 352.476562 602.144531 353.0625 C 602.4375 353.207031 602.582031 353.5 602.875 353.644531 C 603.167969 353.792969 603.605469 353.9375 604.046875 354.085938 C 605.363281 354.230469 606.679688 354.671875 607.996094 355.109375 C 609.164062 355.546875 610.1875 356.132812 611.066406 356.863281 C 611.652344 357.304688 612.238281 357.742188 612.820312 358.328125 C 614.136719 359.644531 616.769531 359.644531 618.085938 358.328125 C 619.695312 356.71875 619.695312 354.523438 618.234375 353.0625 Z M 509.558594 591.914062 C 509.410156 591.621094 509.265625 591.328125 509.121094 591.183594 C 508.972656 590.890625 508.828125 590.449219 508.828125 590.160156 C 508.828125 589.71875 508.828125 589.425781 508.828125 588.988281 C 508.828125 588.695312 508.972656 588.402344 509.121094 588.109375 C 509.265625 587.816406 509.410156 587.527344 509.703125 587.234375 C 510.289062 586.5 510.289062 585.332031 510.144531 584.453125 C 509.851562 583.578125 509.265625 582.699219 508.386719 582.40625 C 507.511719 581.96875 506.488281 581.820312 505.460938 582.113281 C 504.4375 582.40625 503.855469 582.992188 503.269531 583.722656 C 500.195312 587.816406 501.074219 594.253906 505.023438 597.617188 C 505.753906 598.203125 506.632812 598.640625 507.65625 598.640625 C 508.535156 598.640625 509.703125 598.203125 510.289062 597.617188 C 511.605469 596.300781 511.898438 593.960938 510.289062 592.644531 C 509.851562 592.351562 509.703125 592.058594 509.558594 591.914062 Z M 421.359375 645.300781 C 421.359375 645.15625 421.359375 645.15625 421.359375 645.007812 C 421.359375 644.714844 421.359375 644.421875 421.214844 644.128906 C 421.066406 642.8125 421.066406 641.644531 421.066406 640.328125 C 421.066406 639.15625 421.066406 637.988281 421.214844 636.671875 C 421.214844 636.085938 421.359375 635.5 421.359375 634.914062 C 421.359375 634.769531 421.359375 634.625 421.359375 634.476562 C 421.359375 634.183594 421.507812 633.746094 421.507812 633.453125 C 421.796875 631.699219 421.066406 629.503906 418.875 629.066406 C 417.117188 628.625 414.632812 629.648438 414.191406 631.550781 C 413.167969 637.402344 413.167969 643.253906 414.339844 648.957031 C 414.632812 650.710938 417.117188 652.027344 419.019531 651.445312 C 421.066406 650.859375 422.089844 649.105469 421.652344 647.054688 C 421.507812 646.617188 421.359375 646.03125 421.359375 645.300781 Z M 493.46875 628.1875 C 492.738281 626.433594 489.8125 625.992188 488.347656 626.871094 C 486.449219 628.042969 486.15625 629.941406 487.03125 631.699219 C 489.375 636.671875 491.714844 641.644531 494.054688 646.617188 C 494.785156 648.371094 497.710938 648.8125 499.171875 647.933594 C 501.074219 646.761719 501.367188 644.863281 500.488281 643.105469 C 498.148438 638.28125 495.808594 633.308594 493.46875 628.1875 Z M 493.46875 628.1875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#fceed6\" d=\"M 500.929688 247.3125 C 500.488281 245.554688 500.636719 243.363281 501.660156 241.898438 C 506.777344 234.292969 516.871094 230.488281 526.230469 232.683594 C 529.449219 233.414062 531.789062 236.339844 531.789062 239.414062 C 531.789062 244.824219 527.839844 249.503906 522.722656 251.550781 C 520.234375 252.578125 517.457031 253.015625 514.675781 252.867188 C 512.777344 252.722656 511.019531 252.578125 509.121094 252.136719 C 507.511719 252.285156 505.902344 251.992188 504.4375 251.261719 C 502.828125 250.675781 501.511719 248.917969 500.929688 247.3125 Z M 471.238281 144.925781 C 471.089844 144.484375 471.089844 144.046875 470.945312 143.753906 C 470.652344 142.875 470.210938 141.851562 469.628906 141.121094 C 468.605469 139.660156 467.140625 138.050781 465.386719 137.320312 C 463.046875 136.292969 460.414062 135.855469 457.78125 136.585938 C 455.292969 137.320312 453.097656 138.925781 451.78125 141.121094 C 450.027344 143.902344 449.882812 147.117188 450.175781 150.191406 C 450.464844 153.699219 450.90625 157.066406 451.78125 160.429688 C 452.222656 162.183594 453.683594 163.792969 455.292969 164.671875 C 456.902344 165.546875 459.242188 165.988281 461.144531 165.402344 C 462.167969 165.109375 463.046875 164.671875 463.777344 164.085938 C 465.824219 163.648438 467.871094 162.476562 468.894531 160.722656 C 469.921875 158.964844 470.359375 156.917969 469.773438 155.015625 C 470.359375 153.847656 470.945312 152.675781 471.238281 151.359375 C 471.527344 149.019531 471.527344 147.117188 471.238281 144.925781 Z M 510.289062 371.050781 C 512.921875 372.367188 515.992188 373.390625 519.066406 373.097656 C 522.574219 372.953125 526.230469 371.785156 528.71875 369.296875 C 530.328125 367.6875 531.058594 365.640625 530.765625 363.445312 C 530.472656 361.253906 529.15625 359.496094 527.109375 358.328125 C 523.015625 355.988281 518.625 354.085938 514.238281 352.328125 C 512.628906 351.746094 509.851562 352.183594 508.386719 353.0625 C 507.949219 353.207031 507.65625 353.5 507.21875 353.792969 C 505.753906 354.230469 504.585938 354.960938 503.5625 355.839844 C 502.097656 357.15625 501.222656 359.203125 501.222656 361.253906 C 501.222656 363.445312 502.246094 365.203125 503.707031 366.808594 C 504.4375 367.542969 505.316406 367.980469 506.046875 368.566406 C 506.488281 368.859375 506.925781 369.148438 507.21875 369.441406 C 508.535156 370.027344 509.410156 370.613281 510.289062 371.050781 Z M 373.09375 441.257812 C 367.972656 440.089844 362.5625 440.820312 357.878906 443.308594 C 353.199219 445.648438 349.835938 449.597656 348.226562 454.277344 C 347.496094 456.324219 348.226562 458.664062 349.542969 460.421875 C 350.859375 462.03125 353.199219 463.347656 355.394531 463.199219 C 359.34375 462.90625 362.855469 462.03125 366.363281 460.273438 C 367.972656 459.542969 369.4375 458.371094 371.042969 457.347656 C 372.070312 456.617188 373.09375 455.59375 373.96875 454.714844 C 374.117188 454.570312 374.117188 454.570312 374.261719 454.421875 C 374.410156 454.277344 374.703125 454.277344 374.847656 454.132812 C 376.457031 453.253906 377.917969 451.644531 378.359375 449.890625 C 378.796875 448.132812 378.648438 446.085938 377.625 444.476562 C 376.457031 442.867188 374.992188 441.699219 373.09375 441.257812 Z M 487.910156 542.328125 C 487.472656 541.746094 487.03125 541.304688 486.59375 540.71875 C 486.59375 540.574219 486.449219 540.574219 486.449219 540.429688 C 485.570312 538.964844 483.667969 537.648438 481.914062 537.210938 C 480.160156 536.769531 477.671875 536.917969 476.0625 537.941406 C 475.769531 538.085938 475.476562 538.378906 475.1875 538.527344 C 473.429688 539.402344 472.113281 540.867188 471.527344 542.914062 C 470.945312 544.816406 471.238281 547.011719 472.40625 548.617188 C 473.136719 549.789062 474.160156 550.8125 475.476562 551.542969 C 475.476562 551.542969 475.625 551.542969 475.625 551.691406 C 477.085938 554.324219 478.695312 557.101562 480.160156 559.734375 C 481.035156 561.199219 482.9375 562.660156 484.691406 562.953125 C 485.425781 563.097656 486.007812 563.097656 486.742188 563.246094 C 487.765625 563.246094 488.789062 563.097656 489.664062 562.660156 C 491.128906 562.074219 492.445312 561.050781 493.324219 559.734375 C 494.347656 557.980469 494.640625 556.226562 494.054688 554.324219 C 492.738281 549.933594 490.835938 545.839844 487.910156 542.328125 Z M 329.210938 310.351562 C 328.335938 312.398438 328.480469 314.59375 329.652344 316.640625 C 334.1875 324.246094 342.375 330.242188 351.589844 332.144531 C 353.492188 332.582031 355.6875 332.4375 357.441406 331.414062 C 359.050781 330.535156 360.511719 328.925781 360.953125 327.171875 C 361.390625 325.417969 361.246094 323.371094 360.222656 321.761719 C 359.34375 320.589844 358.171875 319.421875 356.710938 318.835938 C 356.855469 317.371094 356.5625 316.054688 355.6875 314.738281 C 353.640625 311.667969 350.714844 309.035156 347.203125 307.574219 C 346.03125 307.132812 344.863281 306.695312 343.691406 306.257812 C 342.523438 305.964844 341.207031 305.816406 339.890625 305.671875 C 337.988281 305.523438 335.941406 305.671875 334.039062 306.109375 C 331.84375 306.695312 330.089844 308.449219 329.210938 310.351562 Z M 314.585938 209.71875 C 315.171875 210.890625 315.757812 211.914062 316.632812 212.9375 C 318.679688 215.71875 320.875 218.203125 323.65625 220.25 C 324.386719 220.984375 325.117188 221.421875 326.140625 221.714844 C 327.019531 222.152344 328.042969 222.300781 329.066406 222.300781 C 330.96875 222.300781 333.160156 221.566406 334.332031 220.25 C 335.0625 219.519531 335.792969 218.644531 336.085938 217.617188 C 337.109375 216.742188 337.84375 215.71875 338.136719 214.546875 C 338.28125 213.960938 338.28125 213.230469 338.425781 212.644531 C 338.425781 211.328125 338.136719 210.160156 337.402344 209.136719 C 336.085938 206.503906 334.769531 203.871094 333.308594 201.238281 C 332.429688 199.628906 331.40625 198.164062 330.238281 196.847656 C 329.503906 195.972656 328.628906 195.386719 327.605469 194.800781 C 326.726562 194.214844 325.554688 193.777344 324.53125 193.632812 C 321.167969 193.046875 317.65625 193.632812 315.171875 195.972656 C 312.539062 198.3125 311.808594 201.820312 312.683594 205.039062 C 312.976562 206.503906 313.855469 208.113281 314.585938 209.71875 Z M 346.472656 395.1875 C 347.058594 394.601562 347.640625 393.871094 348.226562 393.136719 C 349.691406 392.261719 351.007812 390.652344 351.445312 389.042969 C 351.882812 387.289062 351.738281 385.238281 350.714844 383.628906 C 349.691406 382.023438 348.082031 380.851562 346.179688 380.414062 C 337.695312 378.074219 327.605469 381.875 323.507812 389.335938 C 322.339844 391.382812 322.191406 393.429688 323.070312 395.625 C 323.945312 397.671875 325.703125 399.136719 327.894531 399.71875 C 331.40625 400.597656 335.355469 400.597656 338.71875 399.425781 C 340.328125 398.84375 342.085938 398.257812 343.546875 397.234375 C 344.570312 396.648438 345.59375 396.0625 346.472656 395.1875 Z M 319.265625 280.953125 C 318.535156 279.636719 317.65625 278.464844 316.78125 277.296875 C 315.902344 276.125 314.878906 275.101562 313.707031 274.078125 C 310.78125 271.738281 307.859375 270.128906 304.203125 268.957031 C 301.714844 268.226562 298.644531 269.105469 296.886719 270.714844 C 294.988281 272.46875 294.253906 275.101562 294.988281 277.585938 C 296.15625 281.535156 298.351562 284.902344 301.128906 287.972656 C 302.152344 289.144531 303.324219 290.167969 304.492188 291.042969 C 306.25 292.359375 307.859375 293.53125 309.757812 294.410156 C 311.660156 295.285156 313.5625 295.578125 315.609375 295.140625 C 317.363281 294.699219 319.265625 293.382812 320.144531 291.921875 C 321.023438 290.3125 321.460938 288.265625 320.875 286.511719 C 320.730469 286.070312 320.582031 285.632812 320.289062 285.195312 C 320.289062 284.902344 320.289062 284.753906 320.4375 284.460938 C 320.289062 283.144531 319.851562 281.976562 319.265625 280.953125 Z M 300.542969 420.78125 C 300.835938 420.34375 301.277344 419.90625 301.570312 419.464844 C 301.859375 419.320312 302.152344 419.320312 302.445312 419.171875 C 303.324219 418.882812 304.203125 418.441406 304.933594 417.710938 C 306.25 416.394531 307.273438 414.640625 307.125 412.738281 C 307.125 411.859375 306.835938 410.835938 306.542969 409.957031 C 306.6875 409.082031 306.542969 408.351562 306.394531 407.472656 C 305.808594 405.71875 304.640625 404.109375 302.886719 403.230469 C 301.128906 402.351562 298.9375 401.914062 297.035156 402.5 C 295.277344 403.085938 293.671875 403.667969 292.207031 404.691406 C 291.328125 405.277344 290.304688 406.007812 289.429688 406.886719 C 288.550781 407.617188 287.820312 408.640625 287.089844 409.519531 C 286.0625 410.835938 285.332031 412.445312 284.601562 414.054688 C 284.015625 415.664062 283.722656 417.417969 283.578125 419.171875 C 283.429688 421.660156 285.039062 424 287.378906 425.316406 C 289.574219 426.488281 292.792969 426.632812 294.988281 425.316406 C 297.035156 424.144531 299.082031 422.683594 300.542969 420.78125 Z M 511.3125 421.367188 C 509.558594 421.660156 507.65625 423.121094 506.777344 424.585938 C 505.902344 426.046875 505.460938 428.386719 506.046875 429.996094 C 506.632812 431.753906 507.804688 433.359375 509.558594 434.238281 C 510.726562 434.824219 511.898438 435.117188 513.214844 435.117188 C 519.359375 437.894531 525.792969 439.503906 532.523438 439.941406 C 533.691406 440.089844 535.300781 439.503906 536.324219 438.917969 C 537.789062 438.1875 538.8125 437.019531 539.394531 435.554688 C 540.566406 433.070312 540.128906 429.703125 537.789062 427.804688 C 534.277344 424.878906 530.035156 422.683594 525.5 421.515625 C 520.820312 420.34375 515.992188 420.34375 511.3125 421.367188 Z M 514.238281 467.292969 C 513.507812 466.5625 512.777344 466.125 511.753906 465.832031 C 510.875 465.394531 509.851562 465.246094 508.828125 465.246094 C 508.679688 465.246094 508.386719 465.246094 508.242188 465.246094 C 507.65625 464.953125 507.21875 464.808594 506.632812 464.664062 C 504.730469 464.222656 502.539062 464.371094 500.78125 465.394531 C 499.171875 466.269531 497.710938 467.878906 497.273438 469.636719 C 496.980469 471.242188 496.6875 472.851562 496.6875 474.460938 C 496.6875 476.070312 496.980469 477.535156 497.273438 479.140625 C 497.5625 480.605469 498.296875 482.066406 499.027344 483.53125 C 499.464844 484.40625 500.195312 485.140625 500.78125 485.871094 C 501.074219 486.164062 501.367188 486.457031 501.660156 486.75 C 502.390625 487.332031 503.121094 488.066406 504.144531 488.355469 C 505.460938 488.941406 506.488281 489.382812 507.949219 489.527344 C 509.410156 489.671875 510.144531 489.820312 511.753906 489.382812 C 512.484375 489.234375 513.214844 488.941406 513.945312 488.503906 C 514.675781 488.210938 515.261719 487.625 515.847656 487.1875 C 516.285156 486.894531 516.578125 486.457031 516.871094 486.015625 C 517.164062 485.578125 517.457031 485.285156 517.75 484.847656 C 518.625 483.089844 518.773438 482.214844 519.066406 480.3125 C 519.210938 478.851562 518.917969 477.386719 518.773438 475.925781 C 518.335938 472.558594 516.433594 469.636719 514.238281 467.292969 Z M 289.867188 138.195312 C 290.011719 138.34375 290.011719 138.488281 290.160156 138.636719 C 290.160156 138.78125 290.304688 138.925781 290.304688 139.074219 C 290.304688 139.367188 290.304688 139.660156 290.304688 139.953125 C 290.304688 140.976562 290.453125 141.851562 290.890625 142.730469 C 291.183594 143.609375 291.769531 144.339844 292.5 144.925781 C 293.230469 145.65625 293.960938 146.09375 294.988281 146.386719 C 295.863281 146.824219 296.886719 146.972656 297.910156 146.972656 C 298.644531 146.824219 299.226562 146.824219 299.960938 146.679688 C 301.277344 146.386719 302.300781 145.800781 303.324219 144.925781 C 303.761719 144.484375 304.054688 144.046875 304.492188 143.460938 C 305.226562 142.292969 305.519531 141.121094 305.519531 139.953125 C 305.519531 138.78125 305.371094 137.464844 305.226562 136.292969 C 305.078125 135.710938 304.933594 134.980469 304.785156 134.394531 C 304.347656 133.222656 303.910156 132.199219 303.175781 131.175781 C 302.445312 130.152344 301.714844 129.128906 300.835938 128.398438 C 300.105469 127.664062 299.375 127.226562 298.351562 126.933594 C 297.472656 126.496094 296.449219 126.347656 295.425781 126.347656 C 294.402344 126.347656 293.378906 126.496094 292.5 126.933594 C 291.621094 127.226562 290.746094 127.664062 290.011719 128.398438 C 289.574219 128.835938 289.28125 129.273438 288.84375 129.859375 C 288.113281 131.03125 287.820312 132.199219 287.820312 133.371094 C 287.964844 133.953125 287.964844 134.6875 288.113281 135.269531 C 288.40625 136.441406 288.988281 137.320312 289.867188 138.195312 Z M 231.070312 272.90625 C 226.972656 272.03125 222.878906 271.152344 218.636719 270.273438 C 216.734375 269.835938 214.539062 269.980469 212.785156 271.007812 C 211.175781 271.882812 209.714844 273.492188 209.273438 275.246094 C 208.835938 277.003906 208.980469 279.050781 210.007812 280.660156 C 211.03125 282.121094 212.640625 283.4375 214.539062 283.878906 C 218.636719 284.753906 222.730469 285.632812 226.972656 286.511719 C 228.875 286.949219 231.070312 286.800781 232.824219 285.777344 C 234.433594 284.902344 235.894531 283.292969 236.335938 281.535156 C 236.773438 279.78125 236.625 277.734375 235.601562 276.125 C 234.433594 274.664062 232.96875 273.347656 231.070312 272.90625 Z M 261.492188 370.027344 C 260.320312 369.441406 259.003906 369.003906 257.6875 369.003906 C 252.570312 368.566406 247.597656 368.859375 242.625 369.882812 C 240.867188 370.175781 238.96875 371.636719 238.089844 373.101562 C 237.210938 374.5625 236.773438 376.902344 237.359375 378.511719 C 237.941406 380.265625 239.113281 381.875 240.867188 382.753906 C 241.453125 383.046875 242.039062 383.191406 242.625 383.484375 C 243.941406 383.777344 245.257812 383.777344 246.574219 383.484375 C 247.304688 383.339844 247.890625 383.191406 248.621094 383.191406 C 251.691406 382.898438 254.617188 382.898438 257.6875 383.191406 C 259.445312 383.339844 261.785156 382.3125 262.953125 381.144531 C 264.269531 379.972656 265.292969 377.925781 265.148438 376.171875 C 265.003906 374.417969 264.417969 372.515625 262.953125 371.199219 C 262.515625 370.757812 262.078125 370.46875 261.492188 370.027344 Z M 318.828125 508.6875 C 317.363281 507.519531 315.464844 506.496094 313.5625 506.640625 C 311.660156 506.785156 309.613281 507.371094 308.296875 508.6875 C 306.542969 510.445312 304.933594 512.34375 303.46875 514.394531 C 302.300781 516 301.277344 517.609375 300.398438 519.21875 C 299.8125 520.097656 299.519531 520.828125 299.519531 521.851562 C 299.226562 522.730469 299.375 523.753906 299.667969 524.632812 C 299.960938 525.507812 300.398438 526.386719 300.984375 526.972656 C 301.570312 527.703125 302.152344 528.289062 303.03125 528.726562 C 304.785156 529.605469 306.832031 530.042969 308.882812 529.457031 C 310.636719 528.871094 312.539062 527.847656 313.414062 526.238281 C 314.441406 524.339844 315.609375 522.582031 316.925781 520.828125 C 317.511719 520.097656 318.242188 519.367188 318.972656 518.632812 C 320.289062 517.316406 321.167969 515.5625 321.167969 513.660156 C 321.167969 512.636719 321.023438 511.761719 320.582031 510.882812 C 319.996094 510.003906 319.558594 509.273438 318.828125 508.6875 Z M 354.957031 538.964844 C 354.957031 538.527344 354.957031 538.085938 354.957031 537.648438 C 355.101562 537.0625 355.246094 536.480469 355.539062 535.894531 C 355.832031 535.015625 355.832031 533.992188 355.6875 533.113281 C 355.6875 532.238281 355.394531 531.359375 354.808594 530.480469 C 354.371094 529.605469 353.640625 529.019531 352.90625 528.433594 C 352.175781 527.847656 351.296875 527.410156 350.273438 527.117188 C 348.375 526.679688 346.179688 526.824219 344.425781 527.847656 C 343.984375 528.289062 343.398438 528.582031 342.960938 529.019531 C 342.085938 529.898438 341.351562 530.921875 341.058594 532.089844 C 340.769531 532.820312 340.476562 533.699219 340.328125 534.429688 C 340.035156 535.746094 339.890625 537.210938 339.890625 538.527344 C 339.890625 539.84375 340.183594 541.304688 340.476562 542.621094 C 340.769531 543.9375 341.351562 545.253906 341.9375 546.425781 C 342.375 547.300781 343.109375 547.886719 343.839844 548.472656 C 344.570312 549.058594 345.449219 549.496094 346.472656 549.789062 C 347.496094 550.082031 348.519531 550.082031 349.542969 549.933594 C 350.566406 549.933594 351.445312 549.644531 352.324219 549.058594 C 353.929688 548.035156 355.394531 546.71875 355.832031 544.816406 C 355.980469 544.230469 355.980469 543.5 356.125 542.914062 C 356.125 541.890625 355.980469 541.011719 355.539062 540.136719 C 355.246094 539.84375 355.101562 539.402344 354.957031 538.964844 Z M 563.238281 190.265625 C 564.113281 189.828125 564.699219 189.097656 565.140625 188.21875 C 565.722656 187.339844 566.015625 186.609375 566.015625 185.585938 C 566.308594 184.707031 566.164062 183.683594 565.871094 182.808594 C 565.578125 182.222656 565.429688 181.636719 565.140625 181.199219 C 564.40625 180.175781 563.53125 179.296875 562.359375 178.710938 C 561.773438 178.417969 561.191406 178.273438 560.605469 177.980469 C 559.289062 177.6875 557.972656 177.6875 556.65625 177.980469 C 554.316406 178.417969 551.976562 178.859375 549.636719 179.296875 C 548.609375 179.445312 547.734375 179.882812 547.003906 180.613281 C 546.125 181.050781 545.539062 181.785156 545.101562 182.660156 C 544.515625 183.539062 544.222656 184.269531 544.222656 185.292969 C 543.929688 186.171875 544.078125 187.195312 544.371094 188.074219 C 544.660156 188.65625 544.808594 189.242188 545.101562 189.683594 C 545.832031 190.707031 546.710938 191.582031 547.878906 192.167969 C 548.464844 192.460938 549.050781 192.605469 549.636719 192.898438 C 550.953125 193.191406 552.269531 193.191406 553.585938 192.898438 C 555.925781 192.460938 558.265625 192.023438 560.605469 191.582031 C 561.773438 191.289062 562.507812 190.851562 563.238281 190.265625 Z M 203.425781 213.085938 C 205.03125 215.132812 206.789062 217.179688 208.980469 218.789062 C 209.714844 219.519531 210.445312 219.960938 211.46875 220.25 C 212.347656 220.691406 213.371094 220.835938 214.394531 220.835938 C 215.417969 220.835938 216.441406 220.691406 217.320312 220.25 C 218.195312 219.960938 219.074219 219.519531 219.804688 218.789062 C 221.121094 217.472656 222.144531 215.71875 222 213.816406 C 221.855469 212.0625 221.269531 210.011719 219.804688 208.84375 C 218.488281 207.820312 217.464844 206.796875 216.441406 205.625 C 215.5625 204.453125 214.832031 203.285156 214.246094 202.113281 C 213.957031 201.382812 213.664062 200.652344 213.078125 200.066406 C 212.492188 199.335938 211.90625 198.75 211.03125 198.3125 C 210.152344 197.726562 209.273438 197.582031 208.25 197.433594 C 207.226562 197.289062 206.203125 197.289062 205.179688 197.582031 C 203.425781 198.164062 201.523438 199.1875 200.644531 200.796875 C 200.351562 201.382812 200.207031 201.96875 199.914062 202.40625 C 199.621094 203.722656 199.621094 204.894531 199.914062 206.210938 C 200.644531 208.550781 201.816406 210.890625 203.425781 213.085938 Z M 181.046875 252.136719 C 180.167969 251.261719 178.996094 250.675781 177.679688 250.382812 C 174.171875 249.945312 170.660156 249.503906 167.152344 249.066406 C 166.125 248.773438 165.101562 248.773438 164.078125 248.917969 C 163.054688 248.917969 162.175781 249.210938 161.300781 249.796875 C 160.421875 250.234375 159.691406 250.820312 159.253906 251.550781 C 158.519531 252.285156 158.082031 253.015625 157.9375 253.894531 C 157.496094 255.648438 157.644531 257.695312 158.667969 259.304688 C 159.105469 259.742188 159.398438 260.183594 159.835938 260.765625 C 160.714844 261.644531 161.886719 262.230469 163.203125 262.523438 C 166.710938 262.960938 170.222656 263.398438 173.730469 263.839844 C 174.757812 264.132812 175.78125 264.132812 176.804688 263.984375 C 177.828125 263.984375 178.707031 263.691406 179.582031 263.109375 C 180.460938 262.667969 181.191406 262.082031 181.628906 261.351562 C 182.363281 260.621094 182.800781 259.890625 182.945312 259.011719 C 183.386719 257.257812 183.238281 255.210938 182.214844 253.601562 C 181.777344 253.015625 181.484375 252.578125 181.046875 252.136719 Z M 591.027344 326.441406 C 590.152344 325.5625 588.980469 324.976562 587.664062 324.6875 C 585.03125 323.808594 582.542969 323.371094 579.765625 323.078125 C 577.71875 322.785156 575.523438 322.785156 573.476562 323.078125 C 572.453125 323.078125 571.429688 323.222656 570.550781 323.660156 C 569.671875 323.953125 568.796875 324.394531 568.0625 325.125 C 566.746094 326.292969 565.722656 328.34375 565.871094 330.097656 C 566.015625 331.851562 566.601562 333.753906 568.0625 335.070312 C 569.378906 336.242188 571.429688 337.410156 573.328125 337.117188 C 575.085938 336.972656 576.695312 336.972656 578.449219 336.972656 C 580.203125 337.265625 581.8125 337.703125 583.570312 338.289062 C 584.59375 338.582031 585.617188 338.582031 586.640625 338.433594 C 587.664062 338.433594 588.542969 338.140625 589.417969 337.558594 C 591.027344 336.679688 592.492188 335.070312 592.929688 333.316406 C 593.367188 331.558594 593.222656 329.511719 592.199219 327.902344 C 591.757812 327.464844 591.464844 327.027344 591.027344 326.441406 Z M 580.058594 375.441406 C 581.667969 374.5625 583.128906 372.953125 583.570312 371.199219 C 584.007812 369.441406 583.859375 367.394531 582.835938 365.785156 C 581.8125 364.175781 580.203125 363.152344 578.304688 362.570312 C 574.207031 361.253906 570.113281 360.082031 566.015625 358.765625 C 564.261719 358.179688 561.773438 358.621094 560.164062 359.496094 C 558.558594 360.375 557.09375 361.984375 556.65625 363.738281 C 556.21875 365.492188 556.363281 367.542969 557.386719 369.152344 C 558.410156 370.757812 560.019531 371.785156 561.921875 372.367188 C 566.015625 373.683594 570.113281 374.855469 574.207031 376.171875 C 576.109375 376.757812 578.449219 376.316406 580.058594 375.441406 Z M 207.519531 336.972656 C 206.347656 336.679688 205.179688 336.386719 204.007812 335.949219 C 202.109375 335.070312 200.351562 334.191406 198.597656 333.023438 C 198.453125 332.875 198.160156 332.730469 198.011719 332.582031 C 196.550781 331.414062 194.792969 330.535156 192.746094 330.535156 C 190.84375 330.535156 188.652344 331.265625 187.480469 332.582031 C 186.164062 333.898438 185.140625 335.65625 185.289062 337.558594 C 185.433594 339.3125 186.019531 341.359375 187.480469 342.53125 C 192.160156 346.332031 197.574219 349.113281 203.570312 350.574219 C 205.472656 351.011719 207.664062 350.867188 209.421875 349.84375 C 211.03125 348.964844 212.492188 347.355469 212.929688 345.601562 C 213.371094 343.847656 213.222656 341.796875 212.199219 340.191406 C 211.03125 338.726562 209.421875 337.410156 207.519531 336.972656 Z M 235.308594 452.230469 C 234.285156 450.765625 232.675781 449.449219 230.777344 449.011719 C 228.875 448.574219 226.679688 448.71875 224.925781 449.742188 C 223.460938 450.621094 222 451.644531 220.828125 452.816406 C 219.660156 453.984375 218.488281 455.300781 217.464844 456.472656 C 216.734375 457.347656 216.148438 458.226562 215.710938 459.25 C 214.980469 460.714844 214.246094 462.320312 213.664062 463.785156 C 213.371094 464.664062 213.371094 465.6875 213.515625 466.5625 C 213.515625 467.441406 213.808594 468.320312 214.394531 469.195312 C 214.832031 470.074219 215.5625 470.660156 216.296875 471.242188 C 217.027344 471.828125 217.90625 472.269531 218.929688 472.558594 C 220.828125 473 223.023438 472.851562 224.777344 471.828125 C 226.386719 470.804688 227.703125 469.488281 228.289062 467.585938 C 228.4375 467.292969 228.582031 467.003906 228.726562 466.5625 C 229.167969 465.6875 229.753906 464.808594 230.335938 463.929688 C 231.070312 463.054688 231.945312 462.320312 232.824219 461.738281 C 233.703125 461.296875 234.285156 460.714844 234.871094 459.980469 C 235.601562 459.25 236.042969 458.519531 236.1875 457.640625 C 236.480469 456.765625 236.480469 455.738281 236.335938 454.863281 C 236.1875 453.839844 235.894531 452.960938 235.308594 452.230469 Z M 585.175781 428.828125 C 581.667969 428.09375 578.15625 427.363281 574.644531 426.632812 C 572.746094 426.195312 570.550781 426.339844 568.796875 427.363281 C 567.917969 427.804688 567.1875 428.386719 566.746094 429.121094 C 566.015625 429.851562 565.578125 430.582031 565.429688 431.460938 C 564.992188 433.214844 565.140625 435.261719 566.164062 436.871094 C 567.1875 438.335938 568.796875 439.652344 570.695312 440.089844 C 574.207031 440.820312 577.71875 441.550781 581.226562 442.285156 C 583.128906 442.722656 585.324219 442.574219 587.078125 441.550781 C 587.957031 441.113281 588.6875 440.527344 589.125 439.796875 C 589.859375 439.066406 590.296875 438.335938 590.441406 437.457031 C 590.882812 435.703125 590.734375 433.652344 589.710938 432.042969 C 588.6875 430.582031 587.078125 429.121094 585.175781 428.828125 Z M 604.921875 221.128906 C 605.945312 221.128906 606.972656 220.984375 607.847656 220.542969 C 608.726562 220.25 609.605469 219.8125 610.335938 219.082031 C 611.066406 218.496094 611.652344 217.617188 611.945312 216.886719 C 612.382812 216.011719 612.675781 215.132812 612.527344 214.109375 C 612.382812 212.351562 611.796875 210.453125 610.335938 209.136719 C 609.894531 208.695312 609.3125 208.402344 608.871094 207.964844 C 607.703125 207.378906 606.386719 206.941406 605.070312 206.941406 C 600.972656 206.796875 596.585938 207.234375 592.636719 208.113281 C 590.882812 208.550781 589.125 209.867188 588.101562 211.328125 C 587.519531 212.207031 587.226562 212.9375 587.226562 213.960938 C 586.933594 214.839844 587.078125 215.863281 587.371094 216.742188 C 587.957031 218.496094 589.125 220.105469 590.882812 220.984375 C 592.636719 221.859375 594.683594 222.152344 596.730469 221.714844 C 597.609375 221.421875 598.632812 221.277344 599.511719 221.128906 C 601.265625 220.984375 603.023438 220.984375 604.921875 221.128906 Z M 187.042969 127.957031 C 187.042969 127.664062 186.894531 127.371094 186.894531 127.082031 C 186.75 126.496094 186.457031 125.910156 185.871094 125.472656 C 183.09375 122.105469 180.167969 118.890625 177.390625 115.523438 C 176.804688 114.792969 175.632812 114.5 174.757812 114.5 C 173.878906 114.5 172.707031 114.941406 172.125 115.523438 C 171.390625 116.257812 170.953125 117.132812 170.953125 118.011719 C 170.953125 118.304688 171.097656 118.597656 171.097656 118.890625 C 171.246094 119.472656 171.539062 120.058594 172.125 120.5 C 174.902344 123.863281 177.828125 127.082031 180.605469 130.445312 C 181.191406 131.175781 182.363281 131.46875 183.238281 131.46875 C 184.117188 131.46875 185.289062 131.03125 185.871094 130.445312 C 186.605469 129.714844 187.1875 128.835938 187.042969 127.957031 Z M 175.046875 396.648438 C 174.171875 396.210938 173 395.917969 172.125 396.355469 C 170.953125 396.792969 169.636719 397.378906 168.613281 398.109375 C 167.589844 398.84375 166.417969 399.574219 165.542969 400.597656 C 163.785156 402.5 162.46875 404.691406 161.738281 407.035156 C 161.445312 407.910156 161.59375 408.933594 162.175781 409.8125 C 162.617188 410.542969 163.492188 411.273438 164.371094 411.421875 C 166.417969 411.859375 168.46875 410.835938 169.050781 408.933594 C 169.199219 408.640625 169.34375 408.203125 169.492188 407.910156 C 169.78125 407.179688 170.222656 406.59375 170.660156 406.007812 C 171.246094 405.425781 171.832031 404.839844 172.414062 404.402344 C 173.148438 403.960938 174.023438 403.523438 174.757812 403.085938 C 174.609375 403.230469 174.316406 403.230469 174.171875 403.375 C 175.046875 403.085938 175.78125 402.644531 176.363281 401.769531 C 176.804688 401.035156 177.097656 399.867188 176.804688 398.988281 C 176.363281 397.964844 175.78125 397.085938 175.046875 396.648438 Z M 588.6875 180.175781 C 589.859375 181.785156 592.050781 182.367188 593.808594 181.492188 C 597.609375 179.589844 601.414062 177.6875 605.214844 175.785156 C 606.972656 174.910156 607.703125 172.570312 606.53125 170.960938 C 605.363281 169.351562 603.167969 168.765625 601.414062 169.644531 C 597.609375 171.546875 593.808594 173.445312 590.003906 175.347656 C 588.394531 176.226562 587.664062 178.566406 588.6875 180.175781 Z M 580.9375 150.042969 C 581.8125 150.484375 582.835938 150.628906 583.859375 150.335938 C 584.886719 150.042969 585.46875 149.457031 586.054688 148.726562 C 588.6875 145.21875 591.46875 141.851562 594.097656 138.34375 C 594.683594 137.609375 594.683594 136.441406 594.539062 135.5625 C 594.246094 134.6875 593.660156 133.808594 592.78125 133.515625 C 591.90625 133.078125 590.882812 132.929688 589.859375 133.222656 C 588.832031 133.515625 588.25 134.101562 587.664062 134.832031 C 585.03125 138.34375 582.253906 141.707031 579.621094 145.21875 C 579.035156 145.949219 579.035156 147.117188 579.179688 147.996094 C 579.472656 148.726562 580.058594 149.605469 580.9375 150.042969 Z M 566.894531 305.523438 C 568.796875 306.402344 570.84375 305.816406 572.011719 304.207031 C 572.453125 303.625 572.890625 303.039062 573.328125 302.597656 C 573.476562 302.308594 573.769531 302.160156 573.914062 301.867188 C 573.914062 301.867188 574.0625 301.722656 574.0625 301.722656 C 574.355469 301.28125 574.0625 301.722656 573.914062 301.867188 C 574.0625 301.722656 574.207031 301.574219 574.207031 301.429688 C 575.085938 300.40625 576.109375 299.234375 577.132812 298.210938 C 579.035156 296.164062 581.226562 294.117188 583.421875 292.359375 C 584.886719 291.191406 584.886719 288.558594 583.421875 287.386719 C 581.8125 286.070312 579.621094 286.070312 578.15625 287.386719 C 573.476562 291.335938 569.234375 295.871094 565.578125 300.699219 C 564.40625 302.308594 565.140625 304.648438 566.894531 305.523438 Z M 573.914062 301.867188 Z M 616.476562 389.921875 C 615.746094 389.773438 615.015625 389.628906 614.285156 389.335938 C 613.40625 389.042969 612.675781 388.605469 611.945312 388.019531 C 611.359375 387.578125 610.628906 386.996094 610.1875 386.410156 C 610.042969 386.261719 609.894531 386.117188 609.75 385.824219 C 609.164062 385.09375 608.433594 384.507812 607.554688 384.214844 C 606.679688 383.921875 605.507812 384.070312 604.628906 384.507812 C 603.753906 384.945312 603.167969 385.679688 602.875 386.554688 C 602.582031 387.433594 602.730469 388.457031 603.3125 389.335938 C 605.800781 392.992188 609.894531 395.769531 614.429688 396.648438 C 615.453125 396.792969 616.476562 396.792969 617.355469 396.355469 C 618.085938 395.917969 618.820312 395.039062 619.109375 394.308594 C 619.402344 393.429688 619.257812 392.40625 618.671875 391.527344 C 618.234375 390.796875 617.355469 390.066406 616.476562 389.921875 Z M 627.59375 309.035156 C 622.476562 309.179688 617.210938 310.207031 612.527344 312.105469 C 611.652344 312.546875 610.773438 312.839844 610.335938 313.714844 C 609.894531 314.445312 609.605469 315.617188 609.894531 316.496094 C 610.1875 317.371094 610.773438 318.105469 611.652344 318.542969 C 612.527344 318.980469 613.699219 319.273438 614.578125 318.835938 C 616.769531 317.957031 619.109375 317.226562 621.304688 316.789062 C 621.890625 316.640625 622.476562 316.496094 622.914062 316.496094 C 623.207031 316.496094 623.644531 316.347656 623.9375 316.347656 C 624.085938 316.347656 624.085938 316.347656 624.230469 316.347656 C 624.667969 316.347656 624.523438 316.347656 623.9375 316.347656 C 624.375 316.203125 625.253906 316.203125 625.691406 316.203125 C 626.277344 316.203125 626.863281 316.054688 627.449219 316.054688 C 629.351562 315.910156 631.25 314.445312 631.25 312.546875 C 631.398438 310.789062 629.789062 309.035156 627.59375 309.035156 Z M 541.738281 535.894531 C 541.589844 535.601562 541.445312 535.308594 541.296875 535.015625 C 541.296875 534.871094 541.003906 534.429688 541.003906 534.136719 C 540.859375 533.992188 540.859375 533.699219 540.710938 533.554688 C 540.566406 532.96875 540.273438 532.53125 540.128906 531.945312 C 539.394531 529.898438 538.957031 527.847656 538.664062 525.65625 C 538.519531 524.777344 537.640625 523.898438 536.910156 523.605469 C 536.03125 523.167969 534.863281 523.023438 533.984375 523.316406 C 533.105469 523.605469 532.230469 524.046875 531.789062 524.921875 C 531.351562 525.800781 531.207031 526.679688 531.351562 527.703125 C 532.082031 532.382812 533.691406 536.769531 536.03125 540.867188 C 536.910156 542.476562 539.542969 543.0625 541.152344 542.183594 C 542.90625 541.160156 543.492188 539.113281 542.46875 537.355469 C 542.175781 536.917969 541.882812 536.480469 541.738281 535.894531 Z M 414.191406 603.613281 C 413.460938 603.03125 412.585938 602.589844 411.558594 602.589844 C 410.683594 602.589844 409.511719 602.882812 408.925781 603.613281 C 405.5625 607.5625 403.078125 612.097656 402.054688 617.070312 C 401.613281 618.828125 402.636719 621.019531 404.6875 621.460938 C 406.585938 621.898438 408.925781 620.875 409.367188 618.972656 C 409.660156 617.949219 409.953125 616.777344 410.242188 615.753906 C 410.390625 615.167969 410.683594 614.730469 410.828125 614.144531 C 410.828125 614.144531 410.828125 614 410.976562 614 C 411.121094 613.851562 411.121094 613.707031 411.269531 613.414062 C 411.707031 612.390625 412.292969 611.511719 412.875 610.636719 C 413.167969 610.195312 413.460938 609.757812 413.902344 609.320312 C 414.046875 609.027344 414.191406 608.878906 414.339844 608.589844 C 414.484375 608.441406 414.484375 608.441406 414.632812 608.296875 C 414.632812 608.296875 414.484375 608.441406 414.484375 608.441406 C 415.070312 607.710938 415.507812 606.980469 415.507812 605.957031 C 415.214844 605.222656 414.925781 604.199219 414.191406 603.613281 Z M 492.882812 684.355469 C 492.589844 683.769531 492.445312 683.183594 492.296875 682.746094 C 491.859375 681.722656 491.714844 680.550781 491.421875 679.378906 C 491.421875 679.234375 491.421875 679.089844 491.273438 678.941406 C 491.273438 679.089844 491.273438 679.234375 491.273438 679.378906 C 491.128906 679.234375 491.128906 678.648438 491.128906 678.355469 C 491.128906 677.773438 490.980469 677.1875 490.980469 676.601562 C 490.980469 675.429688 490.980469 674.261719 491.273438 673.238281 C 491.421875 672.359375 490.835938 671.335938 490.105469 670.75 C 489.519531 670.164062 488.347656 669.726562 487.472656 669.726562 C 486.449219 669.726562 485.425781 670.019531 484.839844 670.75 C 484.109375 671.480469 483.816406 672.214844 483.667969 673.238281 C 482.9375 678.503906 484.109375 683.914062 486.59375 688.742188 C 487.472656 690.351562 490.105469 690.9375 491.714844 690.058594 C 493.46875 689.035156 494.054688 686.988281 493.03125 685.230469 C 493.175781 684.9375 493.03125 684.644531 492.882812 684.355469 Z M 427.648438 671.628906 C 426.773438 671.191406 425.746094 671.042969 424.722656 671.335938 C 423.699219 671.628906 423.113281 672.214844 422.53125 672.945312 C 419.605469 676.601562 417.265625 680.84375 415.949219 685.378906 C 415.363281 687.132812 416.679688 689.328125 418.582031 689.765625 C 420.628906 690.203125 422.675781 689.179688 423.261719 687.277344 C 423.699219 686.109375 424.140625 684.792969 424.578125 683.621094 C 425.746094 681.136719 427.210938 678.648438 428.964844 676.457031 C 429.550781 675.722656 429.550781 674.554688 429.40625 673.675781 C 429.113281 672.945312 428.378906 672.066406 427.648438 671.628906 Z M 253.15625 144.632812 C 254.910156 145.507812 257.394531 145.070312 258.273438 143.316406 C 259.152344 141.707031 258.859375 139.367188 256.957031 138.488281 C 256.371094 138.195312 255.640625 137.757812 255.054688 137.464844 C 254.761719 137.320312 254.617188 137.171875 254.324219 137.027344 C 254.179688 136.878906 254.03125 136.878906 253.886719 136.734375 C 253.300781 136.292969 252.863281 135.855469 252.421875 135.417969 C 252.128906 135.125 251.984375 134.976562 251.691406 134.6875 C 251.546875 134.539062 251.546875 134.394531 251.398438 134.394531 C 250.523438 133.371094 249.789062 132.199219 249.207031 131.03125 C 249.207031 131.03125 249.207031 131.03125 249.207031 130.882812 C 249.207031 130.882812 249.207031 130.738281 249.207031 130.738281 C 249.058594 130.445312 248.914062 130.152344 248.914062 129.859375 C 248.621094 129.128906 248.472656 128.542969 248.328125 127.8125 C 247.890625 126.054688 245.546875 124.738281 243.648438 125.324219 C 241.597656 125.910156 240.574219 127.664062 241.015625 129.714844 C 242.332031 135.855469 247.011719 141.558594 253.15625 144.632812 Z M 253.15625 144.632812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t100% natural, herbal skincare\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSheer goodness for your skin. No artificial fragrances, preservatives or dyes \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c10c38 e-con-full e-flex e-con e-child\" data-id=\"3c10c38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b99e19 elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7b99e19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"47bf30cd6d\"><path d=\"M 37.152344 19.476562 L 771 19.476562 L 771 791.976562 L 37.152344 791.976562 Z M 37.152344 19.476562 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><g clip-path=\"url(#47bf30cd6d)\"><path fill=\"#ff00d3\" d=\"M 721.402344 634.851562 C 680.941406 574.441406 629.050781 521.757812 569.285156 480.507812 C 561.101562 474.789062 552.453125 469.226562 543.652344 464.285156 C 558.476562 463.355469 575.773438 460.882812 596.46875 456.09375 C 652.21875 443.425781 718.46875 415.460938 770.820312 392.441406 C 705.496094 372.820312 636.621094 364.785156 568.359375 368.957031 C 576.234375 363.550781 584.574219 357.214844 593.53125 349.953125 C 637.855469 313.800781 684.957031 259.570312 721.710938 215.691406 C 650.054688 227.742188 580.714844 253.390625 518.480469 290.78125 C 516.007812 292.171875 513.535156 293.714844 511.21875 295.261719 C 518.015625 281.820312 524.808594 265.441406 531.296875 244.738281 C 548.4375 190.199219 557.859375 118.820312 564.191406 61.964844 C 515.390625 107.542969 474.464844 161.617188 443.886719 220.945312 C 443.117188 213.839844 442.1875 206.113281 440.953125 197.925781 C 432.152344 141.378906 408.984375 73.242188 389.683594 19.476562 C 363.890625 87.457031 351.074219 160.226562 352 232.84375 C 352.15625 245.664062 352.925781 258.796875 354.625 271.621094 C 346.132812 259.878906 335.320312 247.210938 320.960938 232.6875 C 280.808594 192.054688 222.121094 150.492188 174.867188 118.203125 C 193.863281 188.347656 226.136719 254.9375 269.378906 313.183594 C 272.3125 317.046875 275.246094 320.90625 278.335938 324.769531 C 270.152344 322.296875 261.195312 319.980469 251.15625 317.816406 C 195.25 305.613281 123.441406 302.523438 66.300781 301.132812 C 115.5625 345.472656 172.085938 381.007812 233.085938 406.191406 C 221.503906 410.054688 208.6875 415.308594 194.171875 422.257812 C 142.4375 446.671875 83.75 488.386719 37.730469 522.222656 C 110.160156 527.628906 183.667969 519.132812 253.007812 497.5 C 261.964844 494.71875 270.921875 491.628906 279.878906 488.078125 C 268.761719 502.910156 257.488281 522.53125 245.90625 550.496094 C 223.976562 603.332031 208.222656 673.476562 196.796875 729.558594 C 250.691406 687.691406 297.175781 636.085938 333.160156 578.148438 C 333.003906 587.730469 333.3125 598.082031 334.085938 609.667969 C 337.792969 666.679688 354.78125 736.667969 369.296875 791.976562 C 400.957031 726.625 420.257812 655.246094 425.820312 582.785156 C 425.972656 580.003906 426.28125 577.070312 426.4375 574.289062 C 433.386719 587.730469 442.960938 602.5625 456.085938 619.863281 C 490.679688 665.441406 543.34375 714.417969 585.8125 752.582031 C 577.007812 686.300781 556.625 621.71875 526.046875 562.390625 C 532.222656 565.945312 539.019531 569.652344 546.429688 573.359375 C 597.394531 598.851562 666.269531 619.554688 721.402344 634.851562 Z M 378.410156 441.570312 C 377.480469 443.734375 376.554688 445.898438 375.472656 448.0625 C 374.855469 441.417969 373.773438 434.929688 372.078125 428.441406 C 380.414062 426.429688 388.445312 423.496094 396.324219 419.632812 L 400.492188 407.425781 C 396.011719 403.71875 392 400.164062 388.136719 396.613281 L 397.867188 389.042969 C 394.777344 379.308594 392.460938 370.191406 390.453125 361.539062 C 393.078125 364.476562 395.859375 367.410156 398.949219 370.039062 L 411.765625 369.421875 C 412.074219 368.339844 412.539062 367.101562 412.847656 366.023438 C 414.082031 370.8125 415.472656 375.601562 417.324219 380.390625 L 428.136719 385.179688 C 426.28125 390.125 424.890625 395.222656 423.8125 400.320312 L 430.761719 411.136719 C 433.078125 410.671875 435.394531 410.207031 437.710938 409.746094 C 431.996094 414.6875 426.589844 420.097656 421.804688 426.121094 L 423.195312 438.945312 C 425.355469 439.5625 427.363281 440.027344 429.527344 440.644531 L 423.347656 450.222656 C 424.121094 451.152344 424.738281 452.078125 425.511719 453.160156 C 420.878906 451.304688 416.089844 449.761719 411.148438 448.523438 L 400.957031 454.550781 C 398.019531 450.222656 394.777344 446.050781 391.070312 442.191406 Z M 378.410156 441.570312 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#fffa00\" d=\"M 516.316406 361.078125 C 511.527344 357.832031 505.660156 356.441406 499.945312 355.980469 C 477.246094 353.816406 455.007812 361.851562 435.546875 374.054688 C 440.488281 368.800781 445.585938 363.703125 450.527344 358.449219 C 462.109375 346.398438 474.464844 332.804688 475.855469 316.117188 C 476.320312 311.019531 475.546875 305.613281 472.148438 301.75 C 468.289062 297.421875 461.800781 296.03125 456.242188 297.269531 C 450.527344 298.503906 445.585938 301.902344 441.261719 305.765625 C 431.070312 314.726562 423.65625 326.007812 418.40625 338.519531 C 420.566406 324.152344 421.496094 309.011719 414.390625 296.496094 C 411.921875 292.015625 408.214844 288 403.273438 286.609375 C 397.710938 285.0625 391.535156 287.691406 387.519531 291.863281 C 383.503906 296.03125 381.34375 301.59375 379.953125 307.3125 C 376.09375 322.453125 377.019531 338.058594 380.878906 353.199219 C 378.410156 350.726562 375.78125 348.410156 373.3125 345.9375 C 361.265625 334.347656 347.675781 321.988281 330.996094 320.597656 C 325.902344 320.136719 320.496094 320.90625 316.636719 324.304688 C 312.3125 328.167969 310.921875 334.65625 312.15625 340.21875 C 313.390625 345.9375 316.789062 350.878906 320.652344 355.207031 C 330.996094 366.949219 344.433594 374.984375 359.257812 380.234375 C 358.488281 380.234375 357.714844 380.234375 356.941406 380.234375 C 340.109375 380.234375 321.886719 380.542969 308.757812 391.203125 C 304.742188 394.449219 301.347656 398.777344 300.882812 403.875 C 300.421875 409.589844 303.816406 415.308594 308.605469 418.550781 C 313.390625 421.796875 319.261719 423.03125 324.976562 423.496094 C 338.101562 424.578125 351.074219 422.414062 363.429688 417.777344 C 359.257812 420.25 355.089844 422.570312 350.917969 425.039062 C 336.402344 433.539062 320.960938 443.117188 314.9375 458.722656 C 313.082031 463.511719 312.3125 468.917969 314.472656 473.554688 C 316.945312 478.804688 322.8125 481.894531 328.527344 482.207031 C 334.242188 482.515625 339.953125 480.660156 345.207031 478.1875 C 362.039062 470.15625 375.011719 456.558594 384.894531 440.492188 C 384.429688 442.5 384.121094 444.507812 383.660156 446.671875 C 380.414062 463.203125 377.328125 481.125 385.203125 495.957031 C 387.519531 500.4375 391.226562 504.609375 396.011719 506.152344 C 401.574219 507.851562 407.75 505.378906 411.765625 501.363281 C 415.933594 497.347656 418.25 491.785156 419.796875 486.222656 C 422.265625 477.726562 423.195312 469.074219 422.886719 460.421875 C 428.136719 470 434.777344 478.652344 444.351562 483.597656 C 448.828125 485.914062 454.234375 487.304688 459.023438 485.757812 C 464.582031 483.90625 468.289062 478.496094 469.214844 472.78125 C 470.296875 467.0625 469.058594 461.195312 467.207031 455.785156 C 463.347656 444.507812 457.015625 434.464844 448.984375 425.660156 C 451.300781 427.511719 453.460938 429.367188 455.777344 431.21875 C 466.898438 440.179688 479.253906 449.453125 494.078125 447.90625 C 498.558594 447.441406 503.34375 445.742188 506.585938 441.882812 C 510.292969 437.554688 511.21875 431.066406 509.832031 425.96875 C 508.441406 420.714844 505.351562 416.699219 501.800781 413.144531 C 495.3125 406.65625 487.4375 402.175781 478.945312 399.238281 C 492.070312 398.929688 505.199219 396.921875 515.390625 388.886719 C 519.40625 385.796875 522.800781 381.472656 523.421875 376.371094 C 524.5 370.039062 521.105469 364.476562 516.316406 361.078125 Z M 419.949219 398.003906 C 419.332031 398.464844 418.871094 398.777344 418.40625 399.394531 L 420.566406 401.710938 C 418.25 400.320312 416.089844 398.929688 413.773438 397.695312 L 416.089844 398.003906 C 417.324219 398.003906 418.5625 398.003906 419.949219 398.003906 Z M 420.414062 215.382812 C 422.886719 215.230469 425.664062 217.703125 425.355469 220.328125 C 425.046875 223.882812 424.738281 227.589844 424.890625 231.144531 C 424.890625 232.996094 425.046875 234.695312 425.203125 236.550781 C 425.203125 237.476562 425.355469 238.25 425.355469 239.175781 C 425.355469 239.640625 425.511719 240.105469 425.511719 240.722656 C 425.511719 241.03125 425.664062 242.265625 425.511719 241.183594 C 425.664062 242.574219 425.664062 243.65625 425.046875 244.894531 C 424.429688 245.976562 423.347656 246.746094 422.113281 247.210938 C 420.878906 247.519531 419.332031 247.367188 418.40625 246.746094 C 417.480469 246.128906 416.246094 244.894531 416.089844 243.8125 C 415.007812 236.085938 414.699219 228.363281 415.625 220.484375 C 415.78125 217.546875 417.480469 215.382812 420.414062 215.382812 Z M 369.605469 176.296875 C 369.914062 169.960938 370.222656 163.625 370.53125 157.445312 C 370.6875 154.664062 372.695312 152.65625 375.472656 152.503906 C 378.097656 152.347656 380.570312 154.820312 380.414062 157.445312 C 380.105469 163.78125 379.796875 170.117188 379.488281 176.296875 C 379.335938 179.078125 377.328125 181.085938 374.546875 181.238281 C 371.921875 181.394531 369.453125 178.921875 369.605469 176.296875 Z M 402.191406 141.378906 C 401.574219 138.753906 402.964844 136.125 405.589844 135.351562 C 408.058594 134.582031 410.992188 136.28125 411.609375 138.753906 C 413.464844 146.632812 415.316406 154.355469 417.015625 162.234375 C 417.632812 164.863281 416.246094 167.488281 413.617188 168.261719 C 411.148438 169.035156 408.214844 167.335938 407.597656 164.863281 C 405.898438 156.984375 404.042969 149.257812 402.191406 141.378906 Z M 486.511719 259.109375 C 487.4375 256.480469 489.753906 255.089844 492.535156 255.707031 C 495.003906 256.328125 496.859375 259.261719 495.929688 261.734375 C 493.769531 267.757812 491.605469 273.785156 489.445312 279.808594 C 488.519531 282.4375 486.203125 283.828125 483.421875 283.210938 C 480.953125 282.589844 479.097656 279.65625 480.023438 277.183594 C 482.1875 271.160156 484.347656 265.132812 486.511719 259.109375 Z M 465.199219 212.910156 C 469.214844 206.578125 473.847656 200.707031 479.097656 195.453125 C 480.953125 193.445312 484.039062 193.597656 486.046875 195.453125 C 488.054688 197.308594 487.902344 200.550781 486.046875 202.40625 C 483.578125 204.878906 481.261719 207.503906 479.097656 210.285156 C 478.789062 210.59375 478.636719 210.902344 478.324219 211.210938 C 478.171875 211.367188 478.171875 211.519531 478.015625 211.675781 C 477.554688 212.292969 476.9375 213.066406 476.472656 213.683594 C 475.390625 215.074219 474.464844 216.621094 473.539062 218.011719 C 471.996094 220.328125 469.214844 221.101562 466.898438 219.710938 C 464.582031 218.320312 463.808594 215.074219 465.199219 212.910156 Z M 512.457031 227.28125 C 511.683594 226.042969 511.839844 224.808594 511.992188 223.574219 C 512.917969 216.464844 514 209.359375 514.925781 202.40625 C 515.234375 199.625 518.632812 198.390625 520.949219 199.007812 C 522.183594 199.316406 523.265625 200.242188 523.882812 201.324219 C 524.65625 202.558594 524.5 203.796875 524.347656 205.03125 C 523.421875 212.140625 522.339844 219.246094 521.414062 226.199219 C 521.105469 228.980469 517.707031 230.214844 515.390625 229.597656 C 514.15625 229.289062 513.074219 228.207031 512.457031 227.28125 Z M 513.382812 139.832031 C 516.78125 133.808594 520.796875 128.089844 525.273438 122.839844 C 527.125 120.828125 530.371094 121.140625 532.222656 122.839844 C 533.148438 123.609375 533.613281 125.15625 533.613281 126.238281 C 533.613281 127.628906 532.996094 128.710938 532.222656 129.636719 C 531.140625 130.871094 530.214844 131.953125 529.289062 133.191406 C 529.132812 133.34375 529.132812 133.5 528.980469 133.652344 C 528.671875 133.960938 528.515625 134.273438 528.207031 134.582031 C 527.746094 135.199219 527.28125 135.816406 526.816406 136.433594 C 524.964844 139.0625 523.265625 141.84375 521.722656 144.621094 C 520.332031 147.09375 517.242188 147.558594 515.082031 146.324219 C 512.765625 145.242188 512.148438 141.996094 513.382812 139.832031 Z M 515.542969 319.515625 C 521.722656 314.574219 528.207031 310.09375 535.003906 306.230469 C 537.320312 304.839844 540.253906 305.765625 541.644531 307.929688 C 543.035156 310.09375 542.105469 313.335938 539.945312 314.574219 C 536.703125 316.425781 533.613281 318.28125 530.679688 320.445312 C 529.132812 321.527344 527.746094 322.453125 526.199219 323.535156 C 525.429688 324.152344 524.65625 324.617188 524.039062 325.234375 C 523.882812 325.234375 523.882812 325.386719 523.730469 325.386719 C 523.730469 325.386719 523.730469 325.386719 523.574219 325.386719 C 523.265625 325.695312 522.800781 326.007812 522.492188 326.316406 C 521.414062 327.242188 520.332031 327.707031 519.097656 327.707031 C 517.859375 327.707031 516.625 327.085938 515.699219 326.316406 C 514.773438 325.542969 514.308594 323.996094 514.308594 322.914062 C 514 321.835938 514.617188 320.136719 515.542969 319.515625 Z M 551.21875 361.386719 C 550.292969 360.613281 549.828125 359.070312 549.828125 357.988281 C 549.828125 356.90625 550.292969 355.207031 551.21875 354.589844 C 554.308594 352.117188 557.085938 349.179688 559.710938 346.089844 C 561.257812 344.082031 562.492188 342.074219 563.726562 339.910156 C 565.117188 337.4375 568.207031 336.976562 570.367188 338.210938 C 572.683594 339.449219 573.300781 342.691406 572.066406 344.855469 C 568.515625 351.191406 563.726562 356.90625 558.011719 361.539062 C 556.933594 362.46875 555.851562 362.929688 554.617188 362.929688 C 553.378906 362.929688 552.144531 362.3125 551.21875 361.386719 Z M 568.515625 312.101562 C 567.589844 311.328125 567.125 309.785156 567.125 308.703125 C 567.125 307.621094 567.589844 305.921875 568.515625 305.304688 C 573.300781 301.59375 577.933594 297.578125 582.257812 293.40625 C 584.265625 291.550781 587.199219 291.550781 589.207031 293.40625 C 591.0625 295.105469 591.0625 298.503906 589.207031 300.359375 C 584.882812 304.53125 580.25 308.546875 575.464844 312.253906 C 574.847656 312.875 574.074219 313.335938 573.300781 313.492188 C 572.839844 313.492188 572.375 313.644531 572.066406 313.644531 C 570.675781 313.644531 569.441406 313.027344 568.515625 312.101562 Z M 619.167969 275.175781 C 618.859375 276.257812 617.933594 277.648438 616.851562 278.109375 C 610.675781 280.890625 604.652344 283.980469 598.785156 287.382812 C 596.46875 288.769531 593.53125 287.84375 592.144531 285.679688 C 590.753906 283.519531 591.679688 280.273438 593.839844 279.039062 C 599.710938 275.640625 605.734375 272.394531 611.910156 269.769531 C 613.144531 269.148438 614.382812 268.996094 615.617188 269.304688 C 616.851562 269.613281 617.933594 270.539062 618.550781 271.621094 C 619.324219 272.394531 619.476562 273.941406 619.167969 275.175781 Z M 646.195312 272.085938 C 645.886719 271.46875 645.730469 270.847656 645.730469 270.230469 C 645.730469 269.613281 645.886719 268.996094 646.195312 268.378906 C 646.347656 267.757812 646.65625 267.296875 647.273438 266.832031 C 648.972656 265.132812 650.828125 263.277344 652.527344 261.578125 C 653.453125 260.652344 654.6875 260.1875 655.921875 260.1875 C 657.160156 260.1875 658.394531 260.808594 659.320312 261.578125 C 659.785156 262.042969 660.09375 262.507812 660.402344 263.125 C 660.710938 263.742188 660.867188 264.359375 660.867188 264.976562 C 660.867188 265.597656 660.710938 266.214844 660.402344 266.832031 C 660.246094 267.449219 659.9375 267.914062 659.320312 268.378906 C 657.621094 270.078125 655.769531 271.929688 654.070312 273.628906 C 653.144531 274.558594 651.910156 275.019531 650.671875 275.019531 C 649.4375 275.019531 648.203125 274.402344 647.273438 273.628906 C 646.8125 273.167969 646.503906 272.703125 646.195312 272.085938 Z M 387.828125 73.242188 C 387.210938 70.617188 388.601562 67.992188 391.226562 67.21875 C 393.695312 66.445312 396.785156 68.144531 397.25 70.617188 C 398.175781 75.097656 399.257812 79.734375 400.183594 84.214844 C 400.800781 86.839844 399.410156 89.464844 396.785156 90.238281 C 394.316406 91.011719 391.226562 89.3125 390.761719 86.839844 C 389.683594 82.359375 388.753906 77.722656 387.828125 73.242188 Z M 212.238281 195.453125 C 210.847656 193.136719 211.777344 190.199219 213.9375 188.808594 C 216.101562 187.417969 219.34375 188.347656 220.578125 190.507812 C 224.285156 196.84375 227.992188 203.179688 231.699219 209.511719 C 233.085938 211.832031 232.160156 214.765625 230 216.15625 C 227.835938 217.546875 224.59375 216.621094 223.359375 214.457031 C 219.652344 208.121094 215.945312 201.789062 212.238281 195.453125 Z M 233.859375 182.476562 C 232.160156 180.3125 232.007812 177.6875 233.859375 175.523438 C 235.558594 173.667969 239.109375 173.515625 240.808594 175.523438 C 246.058594 181.703125 251.15625 187.882812 256.40625 194.0625 C 258.105469 196.226562 258.261719 198.851562 256.40625 201.015625 C 254.707031 202.871094 251.15625 203.023438 249.457031 201.015625 C 244.207031 194.835938 238.957031 188.65625 233.859375 182.476562 Z M 257.023438 253.390625 C 257.796875 255.089844 258.570312 256.636719 259.496094 258.179688 C 259.957031 258.953125 260.421875 259.726562 261.039062 260.496094 C 261.347656 260.808594 261.503906 261.269531 261.8125 261.578125 C 261.8125 261.578125 261.964844 261.734375 261.964844 261.734375 C 263.046875 263.125 264.28125 264.359375 265.519531 265.597656 C 266.136719 266.214844 266.90625 266.832031 267.527344 267.449219 C 267.679688 267.605469 267.835938 267.605469 267.988281 267.757812 C 268.296875 268.070312 268.605469 268.222656 268.914062 268.53125 C 271.230469 270.078125 272.003906 272.703125 270.613281 275.175781 C 269.996094 276.257812 268.761719 277.183594 267.679688 277.492188 C 266.597656 277.800781 264.902344 277.648438 263.972656 277.03125 C 257.332031 272.394531 251.929688 266.058594 248.683594 258.488281 C 248.066406 257.253906 247.914062 256.015625 248.222656 254.78125 C 248.53125 253.546875 249.457031 252.464844 250.539062 251.847656 C 251.621094 251.226562 253.164062 251.074219 254.246094 251.382812 C 255.171875 251.382812 256.5625 252.308594 257.023438 253.390625 Z M 303.355469 256.328125 C 301.808594 254.007812 303.046875 250.917969 305.054688 249.683594 C 306.132812 249.066406 307.679688 248.910156 308.757812 249.21875 C 309.996094 249.527344 310.921875 250.457031 311.695312 251.535156 C 316.019531 257.71875 320.496094 264.050781 324.820312 270.230469 C 326.363281 272.550781 325.128906 275.640625 323.121094 276.875 C 322.039062 277.492188 320.496094 277.648438 319.414062 277.339844 C 318.179688 277.03125 317.253906 276.101562 316.480469 275.019531 C 312.15625 268.839844 307.832031 262.660156 303.355469 256.328125 Z M 295.941406 317.355469 C 294.242188 319.207031 290.691406 319.207031 288.992188 317.355469 C 284.511719 312.410156 280.652344 306.847656 278.027344 300.824219 C 277.410156 299.585938 277.253906 298.351562 277.5625 297.113281 C 277.871094 295.878906 278.800781 294.796875 279.878906 294.179688 C 280.960938 293.5625 282.503906 293.40625 283.585938 293.714844 C 284.667969 294.023438 286.058594 294.953125 286.519531 296.03125 C 288.375 300.050781 290.535156 303.757812 293.160156 307.15625 C 294.089844 308.238281 295.015625 309.472656 295.941406 310.554688 C 297.792969 312.410156 297.792969 315.191406 295.941406 317.355469 Z M 387.367188 573.515625 C 384.738281 573.667969 382.421875 571.199219 382.421875 568.570312 C 382.421875 560.535156 382.886719 552.347656 383.660156 544.3125 C 383.96875 541.535156 385.667969 539.523438 388.601562 539.371094 C 391.070312 539.214844 393.695312 541.6875 393.542969 544.3125 C 392.769531 552.347656 392.460938 560.535156 392.308594 568.570312 C 392.308594 571.351562 390.144531 573.359375 387.367188 573.515625 Z M 374.546875 623.417969 C 372.078125 623.574219 369.453125 621.101562 369.605469 618.472656 C 370.070312 613.222656 370.378906 607.8125 370.839844 602.5625 C 370.996094 599.78125 373.003906 597.769531 375.78125 597.617188 C 378.253906 597.460938 380.878906 599.933594 380.726562 602.5625 C 380.261719 607.8125 379.953125 613.222656 379.488281 618.472656 C 379.179688 621.253906 377.328125 623.265625 374.546875 623.417969 Z M 358.949219 643.65625 C 359.566406 646.285156 358.175781 648.910156 355.550781 649.683594 C 353.082031 650.457031 349.992188 648.757812 349.53125 646.285156 C 347.832031 638.40625 346.59375 630.371094 345.667969 622.335938 C 345.359375 619.554688 348.140625 617.546875 350.609375 617.394531 C 353.390625 617.238281 355.242188 619.710938 355.550781 622.335938 C 355.707031 623.417969 355.707031 624.34375 355.859375 625.425781 C 355.859375 625.890625 356.015625 626.355469 356.015625 626.816406 C 356.015625 626.972656 356.015625 626.972656 356.015625 627.125 C 356.015625 627.125 356.015625 627.28125 356.015625 627.28125 C 356.324219 629.136719 356.480469 630.988281 356.789062 632.6875 C 357.40625 636.394531 358.175781 640.105469 358.949219 643.65625 Z M 401.417969 673.632812 C 399.71875 680.429688 397.867188 687.226562 396.167969 694.023438 C 395.550781 696.652344 392.617188 698.042969 390.144531 697.425781 C 387.519531 696.804688 386.128906 693.871094 386.746094 691.398438 C 388.445312 684.601562 390.300781 677.800781 392 671.003906 C 392.617188 668.378906 395.550781 666.988281 398.019531 667.605469 C 400.648438 668.222656 402.035156 671.160156 401.417969 673.632812 Z M 389.21875 717.816406 C 388.753906 726.625 386.4375 735.121094 382.578125 742.847656 C 381.34375 745.320312 378.097656 745.78125 375.9375 744.546875 C 373.464844 743.308594 373.003906 740.066406 374.238281 737.902344 C 374.703125 737.128906 375.011719 736.203125 375.472656 735.277344 C 375.472656 735.121094 375.628906 734.96875 375.628906 734.8125 C 375.628906 734.8125 375.628906 734.660156 375.78125 734.660156 C 375.9375 734.347656 376.09375 733.886719 376.246094 733.578125 C 376.863281 731.878906 377.480469 730.023438 377.945312 728.167969 C 378.410156 726.316406 378.871094 724.460938 379.179688 722.609375 C 379.179688 722.296875 379.335938 721.835938 379.335938 721.527344 C 379.335938 721.21875 379.488281 720.753906 379.488281 720.597656 C 379.644531 719.671875 379.644531 718.746094 379.644531 717.816406 C 379.796875 715.035156 381.804688 713.027344 384.585938 712.875 C 386.902344 712.71875 389.371094 715.191406 389.21875 717.816406 Z M 319.570312 531.492188 C 317.097656 535.199219 314.9375 539.0625 312.929688 543.078125 C 312.464844 544.003906 312.003906 545.085938 311.539062 546.015625 C 311.539062 546.167969 311.074219 547.09375 311.074219 547.09375 C 310.921875 547.558594 310.765625 548.023438 310.613281 548.484375 C 309.839844 550.496094 309.066406 552.65625 308.449219 554.664062 C 307.679688 557.292969 305.054688 558.683594 302.425781 558.066406 C 299.957031 557.445312 298.257812 554.511719 299.03125 552.039062 C 301.964844 543.078125 305.980469 534.273438 311.230469 526.390625 C 312.773438 524.074219 315.554688 523.300781 317.871094 524.691406 C 320.03125 525.929688 320.960938 529.328125 319.570312 531.492188 Z M 283.894531 565.328125 C 281.734375 571.96875 279.417969 578.457031 277.253906 585.101562 C 276.328125 587.730469 274.011719 589.121094 271.230469 588.5 C 268.761719 587.882812 266.90625 584.949219 267.835938 582.476562 C 269.996094 575.832031 272.3125 569.34375 274.476562 562.699219 C 275.402344 560.074219 277.71875 558.683594 280.5 559.300781 C 282.96875 559.765625 284.667969 562.855469 283.894531 565.328125 Z M 237.71875 647.828125 C 236.175781 654.628906 234.632812 661.425781 233.085938 668.222656 C 232.46875 670.851562 229.535156 672.242188 227.066406 671.621094 C 224.4375 671.003906 223.050781 668.070312 223.667969 665.597656 C 225.210938 658.800781 226.753906 652 228.300781 645.203125 C 228.917969 642.578125 231.851562 641.1875 234.324219 641.804688 C 236.949219 642.421875 238.339844 645.359375 237.71875 647.828125 Z M 512.148438 545.242188 C 512.917969 547.867188 511.21875 550.496094 508.75 551.265625 C 506.125 552.039062 503.5 550.339844 502.726562 547.867188 C 499.792969 537.824219 496.859375 527.78125 493.921875 517.742188 C 493.152344 515.113281 494.851562 512.488281 497.320312 511.714844 C 499.945312 510.941406 502.570312 512.640625 503.34375 515.113281 C 506.277344 525.15625 509.210938 535.199219 512.148438 545.242188 Z M 499.792969 614.921875 C 500.253906 616.15625 499.945312 617.546875 499.328125 618.628906 C 498.710938 619.710938 497.476562 620.636719 496.394531 620.945312 C 495.3125 621.253906 493.613281 621.101562 492.6875 620.484375 C 485.277344 614.765625 479.253906 607.503906 475.390625 598.851562 C 474.3125 596.382812 474.773438 593.753906 477.089844 592.210938 C 478.171875 591.589844 479.714844 591.4375 480.796875 591.746094 C 481.878906 592.054688 483.269531 592.980469 483.730469 594.0625 C 484.65625 596.070312 485.585938 597.925781 486.664062 599.78125 C 487.128906 600.707031 487.746094 601.480469 488.363281 602.40625 C 488.671875 602.871094 488.980469 603.179688 489.289062 603.640625 C 489.445312 603.796875 489.601562 603.953125 489.601562 604.105469 C 489.601562 604.105469 489.601562 604.261719 489.753906 604.261719 C 490.0625 604.570312 489.910156 604.414062 489.753906 604.261719 C 490.371094 604.878906 490.988281 605.804688 491.605469 606.421875 C 492.226562 607.195312 492.996094 607.96875 493.769531 608.742188 C 494.542969 609.511719 495.3125 610.132812 496.085938 610.902344 C 496.394531 611.214844 496.859375 611.523438 497.167969 611.832031 C 497.320312 611.984375 497.628906 612.140625 497.785156 612.292969 C 498.246094 612.757812 498.09375 612.601562 497.628906 612.292969 C 498.558594 612.757812 499.328125 613.683594 499.792969 614.921875 Z M 489.445312 603.953125 C 489.445312 603.953125 489.445312 603.796875 489.445312 603.953125 C 489.445312 603.953125 489.601562 603.953125 489.445312 603.953125 C 489.601562 603.953125 489.601562 603.953125 489.445312 603.953125 Z M 99.964844 504.917969 C 100.738281 507.390625 99.039062 510.480469 96.570312 510.941406 C 94.40625 511.40625 92.246094 512.023438 90.238281 512.949219 C 87.613281 514.03125 85.296875 515.578125 82.980469 517.277344 C 81.898438 518.050781 80.355469 518.050781 79.273438 517.742188 C 78.039062 517.429688 76.957031 516.503906 76.339844 515.421875 C 75.722656 514.339844 75.566406 512.796875 75.875 511.714844 C 76.183594 510.324219 77.109375 509.550781 78.191406 508.78125 C 82.824219 505.226562 88.382812 502.753906 94.097656 501.519531 C 96.722656 500.898438 99.195312 502.136719 99.964844 504.917969 Z M 184.132812 465.054688 C 184.90625 467.527344 183.207031 470.464844 180.734375 471.082031 C 178.726562 471.699219 176.875 472.316406 175.019531 473.089844 C 171.933594 474.480469 168.84375 476.179688 166.0625 478.1875 C 163.746094 479.734375 160.660156 478.496094 159.421875 476.488281 C 158.804688 475.40625 158.652344 473.863281 158.960938 472.78125 C 159.269531 471.546875 160.195312 470.617188 161.277344 469.84375 C 166.527344 466.292969 172.242188 463.511719 178.417969 461.8125 C 180.734375 460.882812 183.359375 462.582031 184.132812 465.054688 Z M 222.894531 470.773438 C 222.277344 471.699219 221.042969 472.78125 219.960938 473.089844 C 215.328125 474.015625 210.847656 475.097656 206.523438 476.644531 C 203.898438 477.570312 201.273438 475.5625 200.503906 473.246094 C 200.191406 472.007812 200.347656 470.464844 200.964844 469.535156 C 201.582031 468.453125 202.664062 467.683594 203.898438 467.21875 C 208.378906 465.675781 212.855469 464.59375 217.335938 463.664062 C 218.726562 463.355469 219.960938 463.511719 221.042969 464.128906 C 222.121094 464.746094 222.894531 465.828125 223.359375 467.0625 C 223.820312 468.300781 223.511719 469.84375 222.894531 470.773438 Z M 246.367188 432.609375 C 246.523438 435.082031 244.050781 437.710938 241.425781 437.554688 C 236.332031 437.246094 231.234375 437.402344 226.136719 438.019531 C 225.828125 438.019531 225.675781 438.019531 225.367188 438.171875 C 223.976562 438.328125 222.894531 438.328125 221.660156 437.710938 C 220.578125 437.089844 219.804688 436.011719 219.34375 434.773438 C 219.035156 433.539062 219.1875 431.992188 219.804688 431.066406 C 220.425781 430.140625 221.660156 429.058594 222.742188 428.75 C 228.917969 427.820312 235.25 427.359375 241.425781 427.820312 C 244.207031 427.820312 246.214844 429.828125 246.367188 432.609375 Z M 276.484375 475.253906 C 270.460938 478.804688 264.128906 481.894531 257.796875 484.523438 C 256.5625 484.988281 255.171875 484.523438 254.089844 484.058594 C 253.007812 483.441406 252.238281 482.359375 251.773438 481.125 C 251.464844 479.886719 251.621094 478.34375 252.238281 477.414062 C 253.007812 476.179688 253.9375 475.714844 255.171875 475.253906 C 255.171875 475.253906 255.015625 475.253906 255.015625 475.40625 C 255.171875 475.253906 255.480469 475.253906 255.632812 475.097656 C 256.097656 474.945312 256.40625 474.789062 256.871094 474.636719 C 257.640625 474.324219 258.261719 474.015625 259.03125 473.707031 C 260.421875 473.089844 261.964844 472.316406 263.355469 471.699219 C 266.289062 470.308594 269.070312 468.765625 271.851562 467.066406 C 274.167969 465.675781 277.101562 466.601562 278.492188 468.765625 C 279.726562 470.773438 278.800781 474.015625 276.484375 475.253906 Z M 284.976562 434.621094 C 285.132812 437.246094 282.660156 439.71875 280.035156 439.5625 C 274.011719 439.253906 267.835938 439.410156 261.8125 439.871094 C 259.03125 440.027344 257.023438 437.402344 256.871094 434.929688 C 256.714844 432.148438 259.1875 430.140625 261.8125 429.984375 C 267.835938 429.519531 274.011719 429.367188 280.035156 429.675781 C 282.816406 429.828125 284.824219 431.839844 284.976562 434.621094 Z M 232.316406 385.953125 C 232.933594 383.480469 235.867188 381.78125 238.339844 382.554688 C 241.582031 383.632812 244.824219 384.40625 248.222656 385.023438 C 248.992188 385.179688 249.921875 385.332031 250.691406 385.332031 C 250.691406 385.332031 250.691406 385.332031 250.539062 385.332031 C 250.691406 385.332031 250.691406 385.332031 250.847656 385.332031 C 251.308594 385.332031 251.929688 385.488281 252.390625 385.488281 C 254.089844 385.644531 255.632812 385.796875 257.332031 385.796875 C 260.113281 385.953125 262.121094 387.960938 262.273438 390.742188 C 262.429688 393.367188 259.957031 395.683594 257.332031 395.683594 C 250.074219 395.53125 242.664062 394.296875 235.710938 392.132812 C 233.085938 391.203125 231.699219 388.578125 232.316406 385.953125 Z M 331.460938 284.289062 C 329.917969 281.972656 331.152344 278.882812 333.160156 277.648438 C 334.242188 277.03125 335.785156 276.875 336.867188 277.183594 C 338.101562 277.492188 339.027344 278.421875 339.800781 279.5 C 343.042969 284.445312 346.285156 289.390625 349.53125 294.179688 C 351.074219 296.496094 349.839844 299.585938 347.832031 300.824219 C 346.75 301.441406 345.207031 301.59375 344.125 301.285156 C 342.890625 300.976562 341.960938 300.050781 341.191406 298.96875 C 337.945312 294.179688 334.703125 289.234375 331.460938 284.289062 Z M 271.230469 352.578125 C 271.386719 352.578125 271.386719 352.578125 271.230469 352.578125 C 271.230469 352.578125 271.078125 352.425781 271.078125 352.425781 C 271.230469 352.425781 271.230469 352.578125 271.230469 352.578125 Z M 283.742188 350.570312 C 285.75 352.425781 285.441406 355.515625 283.742188 357.523438 C 281.886719 359.53125 278.644531 359.378906 276.792969 357.523438 C 275.402344 356.132812 273.859375 354.898438 272.46875 353.660156 C 272.160156 353.351562 271.695312 353.042969 271.386719 352.734375 C 271.386719 352.734375 271.386719 352.734375 271.542969 352.734375 C 271.542969 352.734375 271.386719 352.578125 271.386719 352.578125 C 271.230469 352.425781 271.230469 352.425781 271.230469 352.425781 C 271.230469 352.425781 271.078125 352.425781 271.078125 352.269531 C 270.304688 351.652344 269.535156 351.1875 268.761719 350.570312 C 265.519531 348.410156 262.273438 346.398438 258.722656 344.855469 C 256.253906 343.617188 255.789062 340.375 257.023438 338.210938 C 258.261719 335.738281 261.347656 335.277344 263.664062 336.511719 C 271.078125 339.910156 277.871094 344.855469 283.742188 350.570312 Z M 239.726562 349.335938 C 232.777344 345.007812 225.984375 340.375 219.34375 335.585938 C 217.179688 334.039062 216.253906 331.414062 217.644531 328.941406 C 218.878906 326.777344 222.277344 325.695312 224.285156 327.242188 C 230.925781 332.03125 237.71875 336.667969 244.667969 340.992188 C 246.988281 342.539062 247.757812 345.320312 246.367188 347.636719 C 245.289062 349.800781 241.890625 350.726562 239.726562 349.335938 Z M 144.441406 337.285156 C 144.132812 337.285156 143.980469 337.285156 143.671875 337.128906 C 142.28125 336.976562 141.199219 336.667969 140.273438 335.738281 C 139.347656 334.8125 138.882812 333.578125 138.882812 332.339844 C 138.882812 331.105469 139.5 329.714844 140.273438 328.941406 C 141.046875 328.167969 142.589844 327.394531 143.671875 327.550781 C 150.15625 328.324219 156.488281 329.558594 162.511719 331.878906 C 165.136719 332.804688 166.527344 335.121094 165.910156 337.902344 C 165.292969 340.375 162.355469 342.226562 159.886719 341.300781 C 155.097656 339.292969 149.847656 338.058594 144.441406 337.285156 Z M 613.144531 401.867188 C 612.527344 404.644531 609.59375 405.726562 607.121094 405.265625 C 606.8125 405.265625 606.660156 405.265625 606.351562 405.109375 C 606.351562 405.109375 606.195312 405.109375 605.886719 405.109375 C 605.425781 405.109375 604.960938 404.957031 604.34375 404.957031 C 603.417969 404.800781 602.335938 404.800781 601.410156 404.644531 C 599.402344 404.492188 597.238281 404.492188 595.230469 404.335938 C 591.0625 404.335938 586.738281 404.644531 582.566406 405.109375 C 579.789062 405.417969 577.78125 402.636719 577.625 400.164062 C 577.625 398.929688 578.242188 397.539062 579.015625 396.765625 C 580.097656 395.683594 581.179688 395.53125 582.414062 395.375 C 591.371094 394.140625 600.480469 394.449219 609.4375 395.683594 C 612.527344 396.304688 613.761719 399.546875 613.144531 401.867188 Z M 571.140625 439.410156 C 572.066406 438.480469 573.300781 438.171875 574.539062 438.019531 C 581.796875 437.089844 589.207031 436.164062 596.46875 435.238281 C 599.246094 434.929688 601.253906 437.710938 601.410156 440.179688 C 601.410156 441.417969 600.792969 442.808594 600.019531 443.582031 C 599.09375 444.507812 597.855469 444.816406 596.621094 444.972656 C 589.363281 445.898438 581.949219 446.824219 574.691406 447.753906 C 571.914062 448.0625 569.90625 445.28125 569.75 442.808594 C 569.59375 441.726562 570.214844 440.335938 571.140625 439.410156 Z M 640.480469 395.222656 C 634.148438 393.214844 627.816406 391.359375 621.484375 389.351562 C 618.859375 388.578125 617.46875 385.953125 618.085938 383.324219 C 618.707031 380.851562 621.640625 379.152344 624.109375 379.925781 C 630.441406 381.933594 636.773438 383.789062 643.105469 385.796875 C 645.730469 386.570312 647.121094 389.195312 646.503906 391.824219 C 646.039062 394.296875 642.949219 395.996094 640.480469 395.222656 Z M 664.726562 417.933594 C 666.117188 420.097656 665.1875 423.496094 663.027344 424.578125 C 653.144531 429.519531 642.640625 433.382812 631.832031 435.699219 C 629.207031 436.320312 626.582031 434.929688 625.808594 432.300781 C 625.035156 429.828125 626.734375 426.738281 629.207031 426.277344 C 634.304688 425.195312 639.398438 423.804688 644.339844 421.949219 C 649.28125 420.25 653.296875 418.550781 658.085938 416.078125 C 660.402344 414.996094 663.183594 415.617188 664.726562 417.933594 Z M 718.777344 404.644531 C 713.527344 406.5 708.277344 408.199219 702.871094 410.054688 C 700.246094 410.980469 697.621094 408.972656 696.847656 406.65625 C 696.074219 404.027344 697.773438 401.402344 700.246094 400.628906 C 705.496094 398.777344 710.746094 397.074219 716.152344 395.222656 C 718.777344 394.296875 721.402344 396.304688 722.175781 398.621094 C 723.101562 401.09375 721.25 403.71875 718.777344 404.644531 Z M 548.285156 523.765625 C 541.179688 518.820312 534.539062 513.105469 528.671875 506.769531 C 526.816406 504.761719 526.816406 501.828125 528.671875 499.820312 C 530.371094 497.964844 533.921875 497.964844 535.621094 499.820312 C 538.398438 502.753906 541.335938 505.6875 544.421875 508.316406 C 545.96875 509.707031 547.511719 510.941406 549.210938 512.332031 C 549.363281 512.488281 549.519531 512.640625 549.675781 512.640625 C 550.136719 512.949219 550.445312 513.261719 550.910156 513.570312 C 551.679688 514.1875 552.453125 514.804688 553.378906 515.269531 C 555.695312 516.8125 556.46875 519.441406 555.078125 521.910156 C 553.84375 524.230469 550.445312 525.3125 548.285156 523.765625 Z M 587.046875 534.734375 C 581.640625 529.328125 576.082031 524.074219 570.675781 518.667969 C 568.667969 516.8125 568.824219 513.722656 570.675781 511.714844 C 572.53125 509.707031 575.773438 509.859375 577.625 511.714844 C 583.03125 517.121094 588.589844 522.375 593.996094 527.78125 C 596.003906 529.636719 595.847656 532.726562 593.996094 534.734375 C 592.144531 536.742188 588.898438 536.589844 587.046875 534.734375 Z M 607.121094 562.238281 C 606.503906 564.863281 603.570312 566.253906 601.101562 565.636719 C 590.597656 562.855469 580.871094 557.757812 572.375 550.804688 C 570.214844 549.105469 570.675781 545.703125 572.375 543.851562 C 574.230469 541.84375 577.316406 542.152344 579.324219 543.851562 C 579.789062 544.160156 580.097656 544.46875 580.558594 544.777344 C 580.558594 544.777344 581.488281 545.550781 581.640625 545.550781 C 582.566406 546.324219 583.648438 546.941406 584.574219 547.558594 C 586.582031 548.949219 588.746094 550.03125 590.90625 551.265625 C 591.988281 551.886719 593.070312 552.347656 594.152344 552.8125 C 594.304688 552.964844 594.613281 552.964844 594.769531 553.121094 C 594.769531 553.121094 594.921875 553.121094 595.078125 553.277344 C 595.695312 553.429688 596.15625 553.738281 596.777344 553.894531 C 599.09375 554.820312 601.410156 555.4375 603.726562 556.054688 C 606.351562 556.828125 607.742188 559.609375 607.121094 562.238281 Z M 651.90625 582.941406 C 651.90625 582.941406 651.753906 582.941406 651.753906 582.785156 C 651.753906 582.785156 651.90625 582.941406 651.90625 582.941406 Z M 657.003906 589.582031 C 656.386719 592.054688 653.296875 593.910156 650.980469 592.980469 C 642.949219 589.890625 635.691406 585.71875 629.207031 580.3125 C 627.042969 578.613281 627.507812 575.214844 629.207031 573.359375 C 629.980469 572.433594 631.523438 571.96875 632.605469 571.96875 C 633.992188 571.96875 635.074219 572.589844 636 573.359375 C 636.464844 573.667969 636.773438 573.976562 637.238281 574.289062 C 637.390625 574.441406 637.546875 574.441406 637.699219 574.597656 C 638.472656 575.058594 639.089844 575.679688 639.863281 576.140625 C 641.40625 577.222656 642.949219 578.148438 644.496094 579.078125 C 646.039062 580.003906 647.738281 580.929688 649.4375 581.703125 C 650.210938 582.011719 650.980469 582.320312 651.597656 582.628906 C 651.445312 582.476562 651.289062 582.476562 651.597656 582.628906 C 651.597656 582.628906 651.753906 582.628906 651.753906 582.628906 C 651.90625 582.628906 652.0625 582.785156 652.21875 582.785156 C 652.679688 582.941406 652.988281 583.09375 653.453125 583.25 C 656.230469 584.640625 657.777344 586.800781 657.003906 589.582031 Z M 549.828125 669.460938 C 547.046875 662.660156 544.421875 655.863281 541.644531 649.066406 C 540.5625 646.4375 542.722656 643.8125 545.039062 643.039062 C 546.277344 642.730469 547.820312 642.886719 548.746094 643.503906 C 549.984375 644.121094 550.445312 645.203125 551.0625 646.4375 C 553.84375 653.238281 556.46875 660.035156 559.25 666.832031 C 560.328125 669.460938 558.167969 672.085938 555.851562 672.859375 C 554.617188 673.167969 553.070312 673.011719 552.144531 672.394531 C 550.910156 671.777344 550.445312 670.695312 549.828125 669.460938 Z M 566.199219 700.976562 C 568.207031 702.832031 568.050781 705.921875 566.199219 707.929688 C 564.34375 709.9375 561.101562 709.785156 559.25 707.929688 C 555.078125 703.757812 550.910156 699.742188 546.585938 695.570312 C 544.578125 693.714844 544.730469 690.625 546.585938 688.617188 C 548.4375 686.609375 551.679688 686.761719 553.535156 688.617188 C 557.703125 692.789062 561.875 696.804688 566.199219 700.976562 Z M 466.898438 524.847656 C 467.207031 526.238281 467.050781 527.472656 466.433594 528.554688 C 465.816406 529.636719 464.734375 530.410156 463.5 530.871094 C 462.265625 531.183594 460.722656 531.027344 459.792969 530.410156 C 458.867188 529.792969 457.785156 528.554688 457.476562 527.472656 C 457.015625 524.691406 456.242188 522.066406 455.160156 519.59375 C 454.390625 517.894531 453.617188 516.351562 452.691406 514.804688 C 451.300781 512.488281 452.226562 509.550781 454.390625 508.160156 C 456.707031 506.769531 459.792969 507.699219 461.03125 509.859375 C 463.808594 514.339844 465.972656 519.59375 466.898438 524.847656 Z M 526.199219 410.207031 C 525.738281 410.207031 525.117188 410.207031 524.65625 410.054688 C 524.191406 409.898438 523.882812 409.746094 523.421875 409.589844 C 522.339844 408.972656 521.566406 407.890625 521.105469 406.65625 C 520.796875 405.417969 520.949219 403.875 521.566406 402.945312 C 522.183594 402.019531 523.421875 400.785156 524.5 400.628906 C 528.980469 400.011719 533.457031 399.703125 537.9375 400.164062 C 539.328125 400.320312 540.40625 400.628906 541.335938 401.554688 C 542.261719 402.484375 542.722656 403.71875 542.722656 404.957031 C 542.722656 406.191406 542.105469 407.582031 541.335938 408.355469 C 540.5625 409.125 539.019531 409.898438 537.9375 409.746094 C 534.078125 409.589844 530.0625 409.746094 526.199219 410.207031 Z M 496.242188 328.167969 C 496.703125 328.324219 497.011719 328.476562 497.476562 328.632812 C 498.558594 329.25 499.328125 330.332031 499.792969 331.566406 C 500.101562 332.804688 499.945312 334.347656 499.328125 335.277344 C 498.710938 336.203125 497.476562 337.285156 496.394531 337.59375 C 495.160156 337.746094 494.078125 338.058594 492.996094 338.519531 C 491.917969 338.984375 490.988281 339.601562 490.0625 340.21875 C 489.601562 340.683594 488.980469 341.148438 488.519531 341.609375 C 487.59375 342.539062 486.355469 343 485.121094 343 C 483.886719 343 482.648438 342.382812 481.722656 341.609375 C 480.796875 340.839844 480.332031 339.292969 480.332031 338.210938 C 480.332031 336.976562 480.953125 335.738281 481.722656 334.8125 C 483.269531 333.113281 485.277344 331.722656 487.28125 330.640625 C 489.289062 329.558594 491.605469 328.785156 493.921875 328.324219 C 494.542969 328.015625 495.3125 328.015625 496.242188 328.167969 Z M 305.980469 376.992188 C 302.890625 376.21875 299.957031 375.445312 296.867188 374.671875 C 295.632812 374.363281 294.550781 373.4375 293.933594 372.355469 C 293.160156 371.273438 293.160156 369.882812 293.46875 368.648438 C 293.78125 367.410156 294.707031 366.332031 295.785156 365.710938 C 296.867188 365.09375 298.257812 364.941406 299.492188 365.25 C 302.582031 366.019531 305.515625 366.792969 308.605469 367.566406 C 309.839844 367.875 310.921875 368.800781 311.539062 369.882812 C 312.3125 370.964844 312.3125 372.355469 312.003906 373.59375 C 311.695312 374.828125 310.765625 375.910156 309.6875 376.527344 C 308.605469 377.144531 307.214844 377.300781 305.980469 376.992188 Z M 367.289062 280.890625 C 366.980469 273.167969 368.832031 265.441406 372.539062 258.644531 C 373.929688 256.171875 377.019531 255.707031 379.179688 256.945312 C 381.496094 258.179688 382.113281 261.425781 380.878906 263.589844 C 380.414062 264.359375 380.105469 265.132812 379.644531 265.90625 C 379.644531 265.90625 379.488281 266.058594 379.488281 266.214844 C 379.335938 266.523438 379.179688 266.988281 379.027344 267.296875 C 378.410156 268.839844 377.945312 270.386719 377.636719 271.929688 C 377.480469 272.703125 377.328125 273.628906 377.171875 274.558594 C 377.171875 274.710938 377.171875 274.710938 377.171875 274.867188 C 377.019531 275.484375 377.171875 275.328125 377.171875 274.558594 C 377.019531 274.867188 377.019531 275.640625 377.019531 275.949219 C 376.863281 277.492188 376.863281 279.191406 377.019531 280.890625 C 377.171875 283.671875 374.703125 285.679688 372.078125 285.835938 C 369.453125 285.835938 367.445312 283.363281 367.289062 280.890625 Z M 323.738281 495.800781 C 319.570312 501.363281 315.246094 506.769531 311.074219 512.332031 C 309.378906 514.496094 306.597656 515.113281 304.28125 513.570312 C 302.117188 512.179688 301.5 508.78125 303.046875 506.769531 C 307.214844 501.207031 311.539062 495.800781 315.707031 490.238281 C 317.40625 488.078125 320.1875 487.457031 322.503906 489.003906 C 324.511719 490.394531 325.285156 493.792969 323.738281 495.800781 Z M 323.738281 495.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#a8ce72\" d=\"M 374.394531 238.25 C 371.769531 230.523438 370.53125 222.335938 370.6875 214.300781 C 370.6875 211.519531 372.847656 209.511719 375.628906 209.359375 C 378.253906 209.203125 380.570312 211.675781 380.570312 214.300781 C 380.570312 216.15625 380.570312 218.164062 380.726562 220.019531 C 380.726562 220.945312 380.878906 221.871094 381.035156 222.800781 C 381.035156 223.109375 381.1875 223.574219 381.1875 223.882812 C 381.1875 224.191406 381.34375 224.652344 381.34375 224.652344 C 381.960938 228.363281 382.886719 232.070312 384.121094 235.625 C 385.050781 238.25 383.042969 240.875 380.726562 241.648438 C 377.789062 242.574219 375.320312 240.722656 374.394531 238.25 Z M 393.695312 198.234375 C 393.851562 201.015625 394.316406 203.640625 395.085938 206.269531 C 395.703125 208.742188 398.640625 210.441406 401.109375 209.667969 C 403.582031 208.894531 405.28125 206.269531 404.507812 203.640625 C 404.199219 202.40625 403.890625 201.015625 403.734375 199.78125 C 403.425781 197 403.425781 194.371094 403.734375 191.589844 C 403.734375 191.898438 403.582031 192.207031 403.582031 192.519531 C 403.734375 191.128906 403.734375 190.046875 403.117188 188.808594 C 402.5 187.726562 401.417969 186.800781 400.183594 186.492188 C 398.949219 186.183594 397.558594 186.339844 396.476562 186.957031 C 395.550781 187.574219 394.46875 188.65625 394.160156 189.890625 C 393.695312 192.828125 393.542969 195.453125 393.695312 198.234375 Z M 391.691406 131.179688 C 394.316406 130.410156 395.703125 127.78125 395.085938 125.15625 C 394.625 123.300781 394.316406 121.449219 394.007812 119.59375 C 394.007812 119.441406 393.851562 118.976562 393.851562 118.820312 C 393.851562 118.359375 393.695312 118.050781 393.695312 117.585938 C 393.542969 116.660156 393.542969 115.730469 393.386719 114.648438 C 393.234375 112.796875 393.234375 110.941406 393.234375 109.089844 C 394.316406 107.851562 394.777344 106.308594 394.160156 104.609375 C 393.851562 103.679688 393.542969 102.753906 393.386719 101.828125 C 392.769531 99.507812 390.453125 97.964844 387.984375 98.273438 C 385.359375 98.582031 383.96875 100.589844 383.660156 103.0625 C 382.730469 111.25 383.503906 119.59375 385.359375 127.628906 C 386.285156 130.253906 389.21875 131.953125 391.691406 131.179688 Z M 471.066406 240.257812 C 468.90625 239.023438 465.507812 239.484375 464.425781 241.957031 C 461.339844 248.292969 458.40625 254.628906 455.316406 260.960938 C 454.234375 263.277344 454.542969 266.367188 457.015625 267.605469 C 459.175781 268.839844 462.574219 268.378906 463.65625 265.90625 C 466.742188 259.570312 469.679688 253.238281 472.765625 246.902344 C 474.003906 244.738281 473.539062 241.648438 471.066406 240.257812 Z M 496.085938 210.132812 C 493.304688 209.511719 490.988281 210.902344 490.0625 213.53125 C 487.746094 219.554688 485.585938 225.582031 483.269531 231.761719 C 482.339844 234.234375 484.195312 237.324219 486.664062 237.785156 C 489.445312 238.40625 491.761719 237.015625 492.6875 234.386719 C 495.003906 228.363281 497.167969 222.335938 499.484375 216.15625 C 500.410156 213.839844 498.558594 210.75 496.085938 210.132812 Z M 502.261719 183.558594 C 504.425781 184.792969 507.824219 184.328125 508.902344 181.859375 C 510.757812 178.148438 512.917969 174.75 515.390625 171.351562 C 516.472656 170.117188 517.550781 168.726562 518.632812 167.488281 C 520.332031 165.636719 520.640625 162.390625 518.632812 160.535156 C 516.78125 158.835938 513.535156 158.527344 511.683594 160.535156 C 507.203125 165.324219 503.34375 170.886719 500.410156 176.757812 C 499.792969 177.996094 499.484375 179.230469 499.945312 180.46875 C 500.410156 181.859375 501.335938 183.09375 502.261719 183.558594 Z M 538.863281 343.308594 C 540.253906 343.308594 541.179688 342.691406 542.261719 341.917969 C 541.953125 342.074219 541.796875 342.382812 541.488281 342.539062 C 546.429688 338.675781 551.679688 335.277344 557.242188 332.1875 C 559.558594 330.949219 560.484375 327.707031 558.941406 325.542969 C 557.394531 323.226562 554.617188 322.453125 552.300781 323.84375 C 546.277344 327.085938 540.71875 330.949219 535.3125 335.121094 C 534.386719 335.894531 533.921875 337.4375 533.921875 338.519531 C 533.921875 339.757812 534.386719 341.148438 535.3125 341.917969 C 536.238281 342.691406 537.472656 343.308594 538.863281 343.308594 Z M 563.882812 294.796875 C 569.75 291.089844 575.617188 287.382812 581.488281 283.671875 C 583.648438 282.28125 584.730469 279.191406 583.1875 277.03125 C 581.796875 274.867188 578.863281 273.785156 576.546875 275.328125 C 570.675781 279.039062 564.808594 282.746094 558.941406 286.453125 C 556.777344 287.84375 555.695312 290.933594 557.242188 293.097656 C 558.632812 295.105469 561.566406 296.1875 563.882812 294.796875 Z M 593.070312 326.777344 C 598.164062 322.144531 602.644531 316.890625 606.503906 311.328125 C 607.121094 310.246094 607.277344 308.703125 606.96875 307.621094 C 606.660156 306.539062 605.734375 305.304688 604.652344 304.683594 C 602.179688 303.292969 599.554688 304.222656 598.011719 306.382812 C 597.238281 307.464844 596.46875 308.546875 595.539062 309.785156 C 592.605469 313.492188 589.515625 316.890625 585.964844 319.980469 C 584.113281 321.679688 584.113281 325.234375 585.964844 326.933594 C 588.128906 328.632812 591.0625 328.632812 593.070312 326.777344 Z M 636.773438 275.792969 C 635.691406 275.175781 634.304688 274.867188 633.066406 275.328125 C 631.988281 275.640625 630.597656 276.410156 630.132812 277.648438 C 628.742188 280.738281 627.042969 283.671875 625.035156 286.453125 C 624.265625 287.535156 623.339844 288.460938 622.410156 289.390625 C 620.558594 291.242188 620.402344 294.488281 622.410156 296.34375 C 624.265625 298.042969 627.507812 298.351562 629.359375 296.34375 C 633.222656 292.324219 636.464844 287.691406 638.628906 282.589844 C 639.246094 281.355469 639.554688 280.121094 639.089844 278.882812 C 638.628906 277.648438 637.855469 276.410156 636.773438 275.792969 Z M 630.132812 261.117188 C 637.546875 258.335938 644.804688 255.707031 652.21875 252.925781 C 654.6875 252 656.542969 249.527344 655.613281 246.902344 C 654.84375 244.585938 652.21875 242.574219 649.589844 243.503906 C 642.179688 246.285156 634.921875 248.910156 627.507812 251.691406 C 625.035156 252.617188 623.183594 255.089844 624.109375 257.71875 C 624.882812 260.035156 627.507812 262.042969 630.132812 261.117188 Z M 672.757812 250.917969 C 673.992188 250.917969 675.382812 250.457031 676.152344 249.527344 C 676.925781 248.757812 677.699219 247.984375 678.46875 247.210938 C 679.550781 246.4375 680.785156 245.664062 682.023438 245.046875 C 682.332031 244.894531 682.640625 244.738281 682.949219 244.738281 C 684.183594 244.277344 685.265625 243.65625 685.882812 242.421875 C 686.5 241.339844 686.808594 239.796875 686.347656 238.714844 C 686.039062 237.476562 685.265625 236.394531 684.03125 235.777344 C 682.949219 235.160156 681.558594 234.851562 680.324219 235.316406 C 676 236.703125 671.984375 239.175781 669.050781 242.574219 C 668.125 243.503906 667.660156 244.738281 667.660156 245.976562 C 667.660156 247.210938 668.125 248.601562 669.050781 249.375 C 670.285156 250.300781 671.519531 250.917969 672.757812 250.917969 Z M 213.320312 174.441406 C 214.09375 175.523438 214.863281 176.296875 216.253906 176.757812 C 217.488281 177.066406 219.035156 176.914062 219.960938 176.296875 C 221.96875 175.058594 223.359375 171.816406 221.660156 169.652344 C 219.035156 166.253906 216.71875 162.855469 214.710938 159.300781 C 213.628906 157.445312 212.703125 155.59375 211.777344 153.738281 C 211.3125 152.8125 210.847656 151.882812 210.386719 150.957031 C 210.230469 150.492188 209.921875 150.03125 209.769531 149.566406 C 209.613281 149.257812 209.613281 149.101562 209.460938 148.792969 C 208.996094 147.558594 208.378906 146.632812 207.144531 145.859375 C 206.0625 145.242188 204.515625 144.933594 203.4375 145.394531 C 201.121094 146.167969 198.957031 148.949219 200.039062 151.421875 C 203.4375 159.453125 207.761719 167.179688 213.320312 174.441406 Z M 256.5625 234.386719 C 257.332031 235.316406 258.878906 235.777344 259.957031 235.777344 C 261.195312 235.777344 262.585938 235.316406 263.355469 234.386719 C 264.28125 233.460938 264.902344 232.222656 264.746094 230.988281 C 264.746094 229.597656 264.128906 228.515625 263.355469 227.589844 C 262.585938 226.664062 261.8125 225.582031 261.039062 224.652344 C 258.570312 221.410156 256.253906 217.855469 254.089844 214.300781 C 252.699219 212.140625 249.613281 211.058594 247.449219 212.601562 C 245.289062 213.992188 244.207031 216.929688 245.75 219.246094 C 248.839844 224.5 252.546875 229.597656 256.5625 234.386719 Z M 287.449219 230.679688 C 288.21875 231.605469 289.765625 232.070312 290.84375 232.070312 C 292.082031 232.070312 293.46875 231.605469 294.242188 230.679688 C 295.167969 229.753906 295.785156 228.515625 295.632812 227.28125 C 295.632812 226.816406 295.476562 226.351562 295.476562 226.042969 C 295.167969 225.273438 294.859375 224.5 294.242188 223.882812 C 290.691406 219.402344 286.675781 215.382812 282.195312 211.675781 C 281.117188 210.75 280.035156 210.285156 278.800781 210.285156 C 277.5625 210.285156 276.175781 210.75 275.402344 211.675781 C 274.476562 212.601562 273.859375 213.839844 274.011719 215.074219 C 274.011719 216.3125 274.476562 217.703125 275.402344 218.472656 C 279.878906 222.183594 283.894531 226.199219 287.449219 230.679688 Z M 271.230469 257.097656 C 274.476562 261.117188 278.027344 264.824219 281.886719 268.378906 C 282.816406 269.304688 284.050781 269.769531 285.285156 269.769531 C 286.519531 269.769531 287.910156 269.304688 288.683594 268.378906 C 289.609375 267.449219 290.226562 266.214844 290.074219 264.976562 C 290.074219 263.742188 289.609375 262.351562 288.683594 261.578125 C 284.820312 258.027344 281.269531 254.316406 278.027344 250.300781 C 277.253906 249.375 275.710938 248.910156 274.628906 248.910156 C 273.394531 248.910156 272.003906 249.375 271.230469 250.300781 C 270.304688 251.226562 269.6875 252.464844 269.84375 253.699219 C 269.84375 254.164062 269.996094 254.628906 269.996094 254.9375 C 270.152344 255.863281 270.613281 256.480469 271.230469 257.097656 Z M 310.921875 301.75 C 312.621094 303.601562 316.171875 303.601562 317.871094 301.75 C 319.722656 299.742188 319.722656 296.804688 317.871094 294.796875 C 315.863281 292.480469 313.855469 290.160156 312.003906 287.84375 C 310.765625 286.144531 309.53125 284.445312 308.296875 282.746094 C 307.523438 281.664062 306.597656 280.890625 305.363281 280.429688 C 304.125 280.121094 302.582031 280.273438 301.65625 280.890625 C 300.574219 281.511719 299.648438 282.589844 299.339844 283.828125 C 299.03125 285.0625 299.03125 286.453125 299.800781 287.535156 C 303.199219 292.632812 306.90625 297.421875 310.921875 301.75 Z M 365.746094 567.796875 C 365.28125 563.007812 365.28125 558.21875 365.746094 553.429688 C 365.746094 553.277344 365.746094 553.121094 365.746094 553.121094 C 365.746094 552.964844 365.746094 552.8125 365.746094 552.65625 C 365.898438 552.039062 365.898438 551.421875 366.054688 550.804688 C 366.207031 549.722656 366.515625 548.484375 366.824219 547.40625 C 367.445312 544.933594 368.214844 542.613281 368.988281 540.296875 C 369.914062 537.824219 368.0625 534.734375 365.589844 534.273438 C 362.8125 533.652344 360.492188 535.042969 359.566406 537.671875 C 356.015625 547.25 354.625 557.757812 355.859375 567.796875 C 356.171875 570.269531 357.867188 572.898438 360.804688 572.742188 C 363.273438 572.589844 366.054688 570.425781 365.746094 567.796875 Z M 414.238281 527.320312 C 411.765625 527.320312 409.140625 529.636719 409.292969 532.261719 C 410.375 543.386719 410.222656 554.820312 408.832031 565.789062 C 408.523438 568.417969 409.449219 571.042969 412.230469 571.816406 C 414.546875 572.433594 417.941406 571.042969 418.25 568.417969 C 419.949219 556.367188 420.257812 544.316406 419.179688 532.261719 C 418.871094 529.484375 417.015625 527.320312 414.238281 527.320312 Z M 404.351562 601.480469 C 401.417969 601.632812 399.71875 603.640625 399.410156 606.421875 C 399.410156 606.578125 399.410156 606.886719 399.257812 607.042969 C 399.257812 607.503906 399.101562 607.96875 399.101562 608.585938 C 398.949219 609.511719 398.792969 610.285156 398.640625 611.214844 C 398.328125 613.066406 398.019531 614.921875 397.558594 616.773438 C 396.785156 620.484375 395.859375 624.191406 394.777344 627.746094 C 394.007812 630.214844 395.703125 633.152344 398.175781 633.769531 C 400.800781 634.386719 403.425781 632.996094 404.199219 630.371094 C 406.515625 622.492188 408.058594 614.457031 409.140625 606.421875 C 409.605469 603.953125 406.824219 601.480469 404.351562 601.480469 Z M 377.171875 652.929688 C 374.703125 653.082031 372.078125 655.089844 372.230469 657.871094 C 372.695312 663.898438 372.539062 670.078125 371.769531 676.101562 C 371.613281 677.183594 372.386719 678.730469 373.15625 679.503906 C 374.085938 680.429688 375.472656 681.046875 376.554688 680.890625 C 377.789062 680.890625 379.179688 680.429688 379.953125 679.503906 C 380.878906 678.421875 381.1875 677.339844 381.34375 676.101562 C 382.113281 670.078125 382.269531 664.050781 381.804688 657.871094 C 381.960938 655.246094 379.953125 652.773438 377.171875 652.929688 Z M 368.214844 696.652344 C 367.597656 694.179688 364.664062 692.480469 362.191406 693.253906 C 359.566406 694.023438 358.023438 696.652344 358.796875 699.277344 C 360.496094 705.613281 362.039062 711.945312 363.738281 718.28125 C 364.355469 720.753906 367.289062 722.453125 369.761719 721.679688 C 372.386719 720.90625 373.929688 718.28125 373.15625 715.65625 C 371.457031 709.320312 369.914062 702.984375 368.214844 696.652344 Z M 279.570312 539.988281 C 282.042969 540.144531 284.976562 538.289062 284.824219 535.507812 C 284.824219 533.34375 284.824219 531.027344 285.132812 528.863281 C 285.285156 527.78125 285.441406 526.703125 285.59375 525.621094 C 285.59375 525.3125 285.75 525.15625 285.75 524.847656 C 285.75 524.847656 285.75 524.539062 285.902344 524.382812 C 285.902344 524.230469 285.902344 524.074219 285.902344 524.074219 C 286.058594 523.765625 286.058594 523.457031 286.210938 523.148438 C 286.828125 520.984375 287.449219 518.976562 288.375 516.96875 C 288.527344 516.503906 288.835938 516.039062 288.992188 515.421875 C 289.144531 515.113281 289.300781 514.804688 289.457031 514.496094 C 290.074219 513.570312 290.535156 512.488281 291.152344 511.558594 C 292.542969 509.398438 292.234375 506.152344 289.917969 504.761719 C 287.757812 503.371094 284.511719 503.679688 283.125 506 C 277.871094 514.496094 274.9375 524.539062 275.246094 534.734375 C 275.09375 537.207031 276.636719 539.832031 279.570312 539.988281 Z M 328.988281 545.703125 C 326.210938 545.085938 323.894531 546.632812 322.96875 549.105469 C 320.960938 554.355469 318.023438 560.226562 314.628906 565.328125 C 311.230469 570.425781 307.523438 574.90625 303.046875 579.386719 C 301.191406 581.238281 301.191406 584.484375 303.046875 586.339844 C 304.898438 588.191406 308.140625 588.191406 309.996094 586.339844 C 319.878906 576.605469 327.601562 564.707031 332.542969 551.730469 C 333.3125 549.257812 331.304688 546.167969 328.988281 545.703125 Z M 257.796875 552.195312 C 254.089844 559.300781 251.308594 567.027344 249.765625 574.90625 C 249.304688 577.378906 250.539062 580.3125 253.164062 580.929688 C 255.632812 581.550781 258.722656 580.160156 259.1875 577.53125 C 259.957031 573.824219 260.886719 570.269531 262.121094 566.71875 C 262.429688 565.789062 262.738281 565.015625 263.046875 564.089844 C 263.203125 563.625 263.355469 563.164062 263.511719 562.855469 C 263.511719 562.699219 263.511719 562.699219 263.664062 562.699219 C 263.664062 562.546875 263.664062 562.546875 263.820312 562.390625 C 264.589844 560.691406 265.363281 558.992188 266.289062 557.292969 C 267.527344 554.976562 266.90625 551.886719 264.589844 550.648438 C 262.273438 549.257812 259.1875 549.722656 257.796875 552.195312 Z M 289.917969 593.753906 C 287.449219 592.363281 284.824219 593.289062 283.277344 595.453125 C 278.800781 601.789062 274.476562 608.277344 269.996094 614.613281 C 268.605469 616.773438 269.535156 620.175781 271.695312 621.253906 C 274.167969 622.644531 276.792969 621.71875 278.335938 619.554688 C 282.816406 613.222656 287.140625 606.734375 291.617188 600.398438 C 293.160156 598.390625 292.082031 594.835938 289.917969 593.753906 Z M 252.699219 629.597656 C 255.324219 622.335938 258.105469 615.074219 260.730469 607.8125 C 261.65625 605.34375 259.804688 602.25 257.332031 601.789062 C 254.554688 601.171875 252.238281 602.5625 251.308594 605.1875 C 248.683594 612.449219 245.90625 619.710938 243.28125 626.972656 C 242.351562 629.445312 244.207031 632.535156 246.675781 632.996094 C 249.457031 633.617188 251.773438 632.226562 252.699219 629.597656 Z M 264.589844 646.285156 C 263.355469 645.976562 261.964844 645.976562 260.886719 646.746094 C 256.253906 649.839844 252.390625 653.855469 249.457031 658.488281 C 248.839844 659.570312 248.683594 661.117188 248.992188 662.199219 C 249.304688 663.28125 250.230469 664.515625 251.308594 665.132812 C 253.78125 666.371094 256.5625 665.75 257.949219 663.433594 C 258.414062 662.816406 258.878906 662.042969 259.339844 661.425781 C 260.886719 659.417969 262.738281 657.5625 264.746094 656.019531 C 265.054688 655.707031 265.519531 655.554688 265.828125 655.246094 C 266.90625 654.472656 267.679688 653.546875 268.144531 652.308594 C 268.453125 651.074219 268.296875 649.527344 267.679688 648.601562 C 266.90625 647.367188 265.828125 646.4375 264.589844 646.285156 Z M 450.527344 546.324219 C 449.292969 543.695312 448.675781 542.152344 447.59375 539.371094 C 446.667969 536.742188 445.742188 534.273438 444.96875 531.644531 C 444.195312 529.171875 441.570312 527.320312 438.945312 528.246094 C 436.476562 529.019531 434.621094 531.644531 435.546875 534.273438 C 438.945312 545.242188 443.886719 555.902344 450.066406 565.636719 C 451.453125 567.796875 454.542969 568.878906 456.707031 567.335938 C 458.867188 565.945312 459.949219 563.007812 458.402344 560.691406 C 455.46875 556.210938 452.84375 551.265625 450.527344 546.324219 Z M 486.355469 558.835938 C 485.429688 556.984375 484.65625 555.128906 483.886719 553.277344 C 483.886719 553.277344 483.578125 552.65625 483.578125 552.503906 C 483.421875 552.039062 483.269531 551.574219 482.960938 551.265625 C 482.496094 550.339844 482.1875 549.414062 481.878906 548.484375 C 481.414062 547.25 480.796875 546.324219 479.5625 545.550781 C 478.480469 544.933594 476.9375 544.625 475.855469 545.085938 C 473.539062 545.859375 471.375 548.640625 472.457031 551.113281 C 475.699219 559.300781 479.253906 567.335938 483.269531 575.058594 C 484.503906 577.378906 487.902344 578.148438 489.910156 576.757812 C 492.226562 575.214844 492.996094 572.433594 491.605469 570.117188 C 489.753906 566.253906 488.054688 562.546875 486.355469 558.835938 Z M 516.472656 608.121094 C 519.097656 607.351562 520.484375 604.722656 519.867188 602.097656 C 518.015625 593.910156 516.472656 585.566406 515.082031 577.070312 C 514.773438 574.597656 511.375 572.898438 509.058594 573.667969 C 506.277344 574.597656 505.199219 576.914062 505.660156 579.695312 C 506.894531 588.039062 508.441406 596.382812 510.449219 604.722656 C 510.910156 607.195312 514 609.050781 516.472656 608.121094 Z M 518.015625 636.550781 C 517.242188 635.46875 516.472656 634.695312 515.082031 634.234375 C 513.84375 633.925781 512.300781 634.078125 511.375 634.695312 C 509.367188 635.933594 507.976562 639.175781 509.675781 641.339844 C 514.464844 647.675781 519.097656 654.164062 523.730469 660.808594 C 525.121094 662.96875 528.054688 664.050781 530.371094 662.507812 C 532.53125 661.117188 533.765625 658.027344 532.070312 655.863281 C 527.589844 649.375 522.957031 642.886719 518.015625 636.550781 Z M 146.140625 476.953125 C 145.371094 474.636719 142.746094 472.472656 140.117188 473.554688 C 132.550781 476.488281 125.140625 479.425781 117.570312 482.359375 C 115.253906 483.285156 113.246094 485.757812 114.175781 488.386719 C 114.945312 490.703125 117.570312 492.867188 120.199219 491.785156 C 127.765625 488.847656 135.175781 485.914062 142.746094 482.976562 C 145.214844 482.207031 147.070312 479.734375 146.140625 476.953125 Z M 149.539062 496.265625 C 146.449219 497.039062 143.515625 497.65625 140.429688 498.429688 C 138.882812 498.738281 137.492188 499.199219 135.949219 499.507812 C 135.640625 499.664062 135.175781 499.664062 134.867188 499.820312 C 134.097656 499.507812 133.476562 499.199219 132.550781 499.199219 C 131.160156 499.199219 129.773438 499.820312 128.84375 500.746094 C 126.992188 502.753906 126.683594 505.691406 128.382812 507.851562 C 129.925781 509.859375 132.398438 510.324219 134.714844 509.859375 C 135.949219 509.707031 137.03125 509.242188 138.265625 509.089844 C 142.898438 508.007812 147.53125 506.925781 152.320312 505.84375 C 154.789062 505.226562 156.488281 502.289062 155.714844 499.820312 C 154.789062 497.039062 152.164062 495.648438 149.539062 496.265625 Z M 186.601562 491.628906 C 183.824219 492.558594 181.042969 493.484375 178.265625 494.410156 C 176.875 494.875 175.484375 495.339844 174.09375 495.800781 C 173.476562 495.957031 173.011719 496.265625 172.394531 496.417969 C 171.46875 496.265625 170.542969 496.265625 169.769531 496.417969 C 166.992188 497.191406 165.292969 500.128906 166.0625 502.910156 C 166.992188 505.84375 169.925781 507.078125 172.859375 506.617188 C 173.941406 506.460938 175.019531 506 175.949219 505.6875 C 180.425781 504.144531 184.75 502.753906 189.230469 501.207031 C 191.699219 500.4375 193.550781 497.808594 192.625 495.183594 C 191.855469 492.558594 189.230469 490.703125 186.601562 491.628906 Z M 205.136719 443.582031 C 199.113281 443.117188 192.933594 442.960938 186.910156 443.269531 C 184.285156 443.425781 181.816406 445.433594 181.96875 448.214844 C 182.125 450.6875 184.132812 453.3125 186.910156 453.160156 C 192.933594 452.851562 199.113281 453.003906 205.136719 453.46875 C 207.761719 453.621094 210.230469 450.996094 210.078125 448.523438 C 209.921875 445.742188 207.914062 443.890625 205.136719 443.582031 Z M 236.332031 483.441406 C 235.25 482.824219 233.707031 482.515625 232.625 482.976562 C 227.21875 485.140625 221.96875 487.613281 216.871094 490.546875 C 214.554688 491.785156 213.628906 495.027344 215.171875 497.191406 C 216.71875 499.507812 219.496094 500.28125 221.8125 498.890625 C 226.136719 496.574219 230.460938 494.410156 234.941406 492.558594 C 235.09375 492.558594 235.25 492.402344 235.25 492.402344 C 236.484375 491.9375 237.410156 491.320312 238.183594 490.085938 C 238.800781 489.003906 239.109375 487.457031 238.648438 486.375 C 238.339844 485.296875 237.566406 484.058594 236.332031 483.441406 Z M 257.179688 459.339844 C 258.261719 459.183594 259.496094 458.101562 260.113281 457.023438 C 260.730469 455.941406 261.039062 454.394531 260.578125 453.3125 C 259.648438 450.6875 257.179688 449.296875 254.554688 449.914062 C 250.691406 450.6875 246.675781 451.460938 242.816406 452.234375 C 241.734375 451.769531 240.5 451.769531 239.417969 452.078125 C 236.640625 452.851562 234.941406 455.632812 235.710938 458.414062 C 236.332031 460.882812 238.648438 462.429688 241.117188 462.429688 C 242.351562 462.429688 243.742188 461.964844 245.132812 461.8125 C 249.148438 460.882812 253.164062 460.113281 257.179688 459.339844 Z M 341.34375 501.828125 C 339.027344 501.363281 335.785156 502.597656 335.320312 505.226562 C 334.085938 513.722656 332.078125 521.910156 329.453125 530.101562 C 328.679688 532.574219 330.378906 535.507812 332.851562 536.125 C 335.476562 536.742188 338.101562 535.351562 338.875 532.726562 C 341.5 524.539062 343.507812 516.351562 344.742188 507.851562 C 345.207031 505.226562 344.125 502.445312 341.34375 501.828125 Z M 274.785156 374.984375 C 276.019531 372.664062 275.402344 369.574219 273.085938 368.339844 C 270.152344 366.792969 267.0625 365.25 264.128906 363.703125 C 262.585938 362.929688 261.195312 362.160156 259.648438 361.386719 C 258.878906 361.078125 258.105469 360.613281 257.488281 360.304688 C 257.488281 360.304688 257.332031 360.152344 257.332031 360.152344 C 256.714844 359.070312 255.632812 358.296875 254.398438 357.988281 C 251.15625 357.214844 247.914062 359.53125 247.914062 362.929688 C 247.757812 366.949219 251.929688 368.492188 254.863281 370.039062 C 259.339844 372.355469 263.820312 374.671875 268.296875 376.992188 C 270.304688 378.074219 273.546875 377.453125 274.785156 374.984375 Z M 205.289062 349.488281 C 203.4375 347.636719 200.191406 347.480469 198.339844 349.488281 C 196.488281 351.5 196.488281 354.433594 198.339844 356.441406 C 203.589844 361.851562 209.148438 366.949219 214.863281 371.738281 C 215.945312 372.664062 217.027344 373.128906 218.261719 373.128906 C 219.496094 373.128906 220.886719 372.664062 221.660156 371.738281 C 223.359375 369.882812 223.820312 366.484375 221.660156 364.785156 C 215.945312 359.996094 210.539062 354.898438 205.289062 349.488281 Z M 173.476562 323.84375 C 176.875 324.304688 180.117188 325.078125 183.207031 326.160156 C 183.976562 326.46875 184.75 326.777344 185.675781 327.085938 C 185.675781 327.085938 185.832031 327.085938 185.832031 327.085938 C 186.292969 327.242188 186.601562 327.394531 187.066406 327.550781 C 188.609375 328.324219 190.15625 329.097656 191.546875 329.867188 C 193.707031 331.105469 196.949219 330.488281 198.1875 328.167969 C 199.421875 325.851562 198.804688 322.914062 196.488281 321.527344 C 190.308594 317.816406 183.207031 315.34375 176.101562 314.417969 C 174.710938 314.265625 173.632812 314.109375 172.394531 314.882812 C 171.316406 315.5 170.386719 316.582031 170.078125 317.816406 C 169.769531 319.054688 169.925781 320.445312 170.542969 321.527344 C 171.160156 322.605469 172.242188 323.6875 173.476562 323.84375 Z M 132.550781 320.289062 C 133.015625 317.972656 131.78125 314.726562 129.15625 314.265625 C 119.734375 312.71875 110.160156 311.484375 100.738281 310.402344 C 98.113281 310.09375 95.796875 312.875 95.796875 315.34375 C 95.953125 318.28125 97.960938 319.980469 100.738281 320.289062 C 109.851562 321.214844 117.570312 322.296875 126.527344 323.84375 C 129.15625 323.996094 131.933594 323.070312 132.550781 320.289062 Z M 154.945312 356.289062 C 160.195312 359.6875 165.445312 362.929688 170.695312 366.332031 C 172.859375 367.722656 176.257812 366.792969 177.335938 364.632812 C 178.574219 362.160156 177.953125 359.378906 175.636719 357.988281 C 170.386719 354.589844 165.136719 351.34375 159.886719 347.945312 C 157.722656 346.554688 154.328125 347.480469 153.246094 349.644531 C 151.855469 352.117188 152.628906 354.898438 154.945312 356.289062 Z M 586.738281 419.324219 C 586.582031 416.851562 584.574219 414.226562 581.796875 414.378906 C 572.53125 415.308594 563.109375 416.234375 553.84375 417.160156 C 551.371094 417.46875 548.746094 419.167969 548.902344 422.105469 C 549.054688 424.578125 551.0625 427.203125 553.84375 427.050781 C 563.109375 426.121094 572.53125 425.195312 581.796875 424.269531 C 584.421875 423.957031 586.890625 422.105469 586.738281 419.324219 Z M 596.777344 383.632812 C 596.777344 380.851562 594.460938 378.84375 591.832031 378.691406 C 578.398438 377.761719 564.808594 379.152344 551.992188 383.015625 C 545.96875 384.871094 548.59375 394.296875 554.617188 392.441406 C 566.660156 388.886719 579.171875 387.496094 591.832031 388.425781 C 594.460938 388.734375 596.777344 386.261719 596.777344 383.632812 Z M 631.367188 414.070312 C 630.597656 414.226562 629.980469 414.378906 629.207031 414.378906 C 629.050781 414.378906 628.898438 414.378906 628.898438 414.378906 C 628.589844 414.378906 628.125 414.535156 627.816406 414.535156 C 626.425781 414.6875 624.882812 414.84375 623.492188 414.84375 C 620.558594 414.996094 617.46875 414.84375 614.535156 414.535156 C 613.300781 414.378906 611.910156 415.152344 611.136719 415.925781 C 610.210938 416.851562 609.59375 418.242188 609.75 419.324219 C 609.75 420.558594 610.210938 421.949219 611.136719 422.722656 C 612.21875 423.648438 613.300781 423.960938 614.535156 424.113281 C 621.023438 424.886719 627.507812 424.421875 633.992188 423.339844 C 636.464844 422.878906 638.164062 419.632812 637.390625 417.316406 C 636.621094 414.84375 634.148438 413.609375 631.367188 414.070312 Z M 652.0625 405.109375 C 652.21875 407.582031 654.222656 410.207031 657.003906 410.054688 C 662.871094 409.746094 668.585938 409.4375 674.457031 409.128906 C 677.082031 408.972656 679.550781 406.964844 679.398438 404.183594 C 679.242188 401.710938 677.234375 399.085938 674.457031 399.238281 C 668.585938 399.546875 662.871094 399.855469 657.003906 400.164062 C 654.378906 400.320312 651.90625 402.328125 652.0625 405.109375 Z M 687.117188 384.871094 C 679.550781 384.253906 671.984375 383.789062 664.417969 383.171875 C 661.792969 383.015625 659.320312 385.488281 659.476562 388.113281 C 659.628906 390.894531 661.636719 392.75 664.417969 393.058594 C 671.984375 393.675781 679.550781 394.140625 687.117188 394.757812 C 689.742188 394.914062 692.214844 392.441406 692.0625 389.816406 C 691.90625 387.035156 689.898438 385.179688 687.117188 384.871094 Z M 558.320312 489.3125 C 550.910156 481.125 542.722656 473.863281 533.613281 467.527344 C 531.449219 465.984375 528.054688 467.066406 526.972656 469.226562 C 525.582031 471.699219 526.507812 474.324219 528.671875 475.871094 C 529.753906 476.644531 530.679688 477.261719 531.757812 478.035156 C 532.378906 478.496094 532.839844 478.804688 533.457031 479.269531 C 533.457031 479.269531 533.613281 479.425781 533.613281 479.425781 C 533.765625 479.578125 534.078125 479.734375 534.230469 479.886719 C 536.238281 481.433594 538.246094 483.132812 540.253906 484.832031 C 544.113281 488.230469 547.820312 491.9375 551.371094 495.800781 C 553.070312 497.65625 556.625 497.65625 558.320312 495.800781 C 560.175781 494.101562 560.175781 491.320312 558.320312 489.3125 Z M 555.078125 537.207031 C 554.617188 537.054688 554.308594 536.898438 553.84375 536.742188 C 553.84375 536.742188 553.84375 536.742188 553.6875 536.742188 C 553.378906 536.589844 553.070312 536.433594 552.761719 536.28125 C 551.835938 535.816406 550.910156 535.351562 549.984375 534.890625 C 547.976562 533.964844 546.121094 532.882812 544.269531 531.644531 C 542.414062 530.5625 540.71875 529.328125 539.019531 528.09375 C 538.863281 527.9375 538.710938 527.78125 538.554688 527.78125 C 538.089844 527.472656 537.78125 527.164062 537.320312 526.855469 C 536.394531 526.082031 535.621094 525.3125 534.695312 524.539062 C 532.839844 522.839844 529.597656 522.53125 527.746094 524.539062 C 526.046875 526.390625 525.738281 529.636719 527.746094 531.492188 C 535.003906 538.132812 543.34375 543.234375 552.453125 546.941406 C 554.769531 547.867188 558.011719 545.859375 558.476562 543.542969 C 559.09375 540.296875 557.703125 538.132812 555.078125 537.207031 Z M 615.617188 531.027344 C 614.84375 530.101562 613.300781 529.636719 612.21875 529.636719 C 610.984375 529.636719 609.59375 530.101562 608.820312 531.027344 C 607.894531 531.953125 607.277344 533.191406 607.429688 534.425781 C 607.429688 535.816406 608.050781 536.898438 608.820312 537.824219 C 613.609375 543.851562 618.707031 549.566406 624.109375 555.128906 C 625.964844 556.984375 629.207031 557.136719 631.058594 555.128906 C 632.914062 553.121094 632.914062 550.183594 631.058594 548.175781 C 625.65625 542.769531 620.558594 537.054688 615.617188 531.027344 Z M 606.042969 577.996094 C 602.644531 577.222656 599.246094 576.296875 596.003906 574.90625 C 595.847656 574.90625 595.695312 574.75 595.539062 574.75 C 595.230469 574.597656 594.921875 574.441406 594.613281 574.289062 C 593.6875 573.976562 592.914062 573.515625 592.144531 573.050781 C 590.597656 572.277344 589.054688 571.351562 587.511719 570.425781 C 585.347656 569.035156 581.949219 569.808594 580.871094 572.125 C 579.632812 574.441406 580.25 577.378906 582.566406 578.769531 C 589.054688 582.628906 596.15625 585.566406 603.570312 587.265625 C 606.042969 587.882812 608.976562 586.492188 609.59375 583.867188 C 610.058594 581.550781 608.667969 578.613281 606.042969 577.996094 Z M 665.035156 574.90625 C 663.183594 573.207031 659.9375 572.898438 658.085938 574.90625 C 656.386719 576.757812 656.078125 580.003906 658.085938 581.859375 C 662.410156 585.875 666.425781 590.355469 669.976562 594.992188 C 670.285156 595.300781 670.59375 595.761719 670.902344 596.070312 C 671.675781 597.152344 672.449219 597.925781 673.835938 598.390625 C 675.074219 598.699219 676.617188 598.542969 677.542969 597.925781 C 678.625 597.308594 679.550781 596.226562 679.859375 594.992188 C 680.167969 593.753906 680.167969 592.210938 679.398438 591.28125 C 674.917969 585.257812 670.285156 579.847656 665.035156 574.90625 Z M 560.949219 559.917969 C 556.316406 557.136719 551.835938 554.511719 547.203125 551.730469 C 545.039062 550.496094 541.796875 551.113281 540.5625 553.429688 C 539.328125 555.746094 539.945312 558.683594 542.261719 560.074219 C 546.894531 562.855469 551.371094 565.480469 556.003906 568.261719 C 558.167969 569.496094 561.410156 568.878906 562.644531 566.5625 C 563.882812 564.246094 563.265625 561.308594 560.949219 559.917969 Z M 675.382812 605.1875 C 667.96875 601.324219 659.9375 599.160156 651.753906 598.699219 C 649.128906 598.542969 646.65625 601.015625 646.8125 603.640625 C 646.964844 606.421875 648.972656 608.433594 651.753906 608.585938 C 652.679688 608.585938 653.605469 608.742188 654.378906 608.742188 C 654.535156 608.742188 654.84375 608.742188 654.996094 608.742188 C 655.304688 608.742188 655.769531 608.894531 656.078125 608.894531 C 657.777344 609.203125 659.628906 609.511719 661.328125 610.132812 C 663.027344 610.59375 664.726562 611.214844 666.425781 611.832031 C 666.734375 611.984375 667.195312 612.140625 667.503906 612.292969 C 666.425781 611.675781 667.816406 612.449219 668.125 612.601562 C 668.894531 612.914062 669.667969 613.375 670.59375 613.839844 C 672.910156 615.074219 676 614.457031 677.234375 612.140625 C 678.316406 609.667969 677.699219 606.421875 675.382812 605.1875 Z M 508.75 491.167969 C 509.058594 489.929688 509.058594 488.386719 508.285156 487.457031 C 506.433594 484.832031 504.734375 482.050781 503.5 479.117188 C 503.191406 478.496094 503.035156 477.878906 502.726562 477.261719 C 502.261719 476.027344 501.644531 474.945312 500.410156 474.324219 C 499.328125 473.707031 497.785156 473.398438 496.703125 473.863281 C 495.46875 474.171875 494.386719 474.945312 493.769531 476.179688 C 493.152344 477.261719 492.84375 478.652344 493.304688 479.886719 C 494.851562 484.367188 497.011719 488.539062 499.792969 492.402344 C 500.5625 493.484375 501.335938 494.257812 502.726562 494.71875 C 503.960938 495.027344 505.507812 494.875 506.433594 494.257812 C 507.515625 493.328125 508.441406 492.402344 508.75 491.167969 Z M 516.625 446.671875 C 516.316406 447.90625 516.472656 449.296875 517.089844 450.378906 C 517.707031 451.304688 518.789062 452.386719 520.023438 452.695312 C 524.5 453.3125 529.132812 454.085938 533.613281 454.703125 C 535.003906 454.859375 536.238281 454.859375 537.320312 454.242188 C 538.398438 453.621094 539.328125 452.542969 539.636719 451.304688 C 539.945312 450.070312 539.789062 448.679688 539.171875 447.597656 C 538.554688 446.671875 537.472656 445.589844 536.238281 445.28125 C 531.757812 444.660156 527.125 443.890625 522.648438 443.273438 C 521.257812 443.117188 520.023438 443.117188 518.941406 443.734375 C 517.859375 444.199219 516.933594 445.433594 516.625 446.671875 Z M 421.648438 266.832031 C 421.804688 267.296875 421.957031 267.914062 422.113281 268.378906 C 422.730469 270.539062 423.347656 272.550781 423.964844 274.710938 C 424.273438 275.949219 425.203125 277.03125 426.28125 277.648438 C 427.363281 278.265625 428.90625 278.574219 429.988281 278.109375 C 431.222656 277.800781 432.304688 277.03125 432.921875 275.792969 C 433.539062 274.710938 433.847656 273.320312 433.386719 272.085938 C 432.769531 270.078125 432.152344 268.070312 431.53125 266.058594 C 431.53125 266.058594 431.6875 265.90625 431.6875 265.90625 C 432.304688 264.824219 432.613281 263.277344 432.152344 262.199219 C 431.84375 260.960938 431.070312 259.878906 429.835938 259.261719 C 428.597656 258.644531 427.363281 258.488281 426.128906 258.796875 C 425.046875 258.953125 423.964844 259.726562 423.195312 260.34375 C 422.421875 260.960938 421.957031 261.734375 421.648438 262.660156 C 421.1875 263.742188 421.03125 264.824219 421.339844 266.058594 C 421.496094 266.367188 421.648438 266.523438 421.648438 266.832031 Z M 286.984375 404.183594 C 287.910156 403.257812 288.527344 402.019531 288.375 400.785156 C 288.375 400.320312 288.21875 399.855469 288.21875 399.546875 C 287.910156 398.777344 287.601562 398.003906 286.984375 397.386719 C 286.210938 396.457031 285.285156 395.683594 284.203125 395.066406 C 283.125 394.449219 282.042969 393.984375 280.808594 393.832031 C 280.035156 393.675781 279.261719 393.523438 278.335938 393.523438 C 277.5625 393.523438 276.792969 393.675781 275.863281 393.832031 C 275.246094 393.984375 274.785156 394.140625 274.167969 394.449219 C 273.546875 394.757812 273.085938 394.914062 272.46875 395.222656 C 271.386719 395.996094 270.613281 396.921875 270.152344 398.15625 C 269.84375 399.394531 269.996094 400.9375 270.613281 401.867188 C 271.230469 402.945312 272.3125 403.875 273.546875 404.183594 C 274.785156 404.492188 276.328125 404.492188 277.253906 403.71875 C 277.410156 403.566406 277.5625 403.566406 277.871094 403.410156 C 277.871094 403.410156 278.027344 403.410156 278.027344 403.410156 C 278.179688 403.410156 278.335938 403.410156 278.492188 403.410156 C 278.644531 403.410156 278.644531 403.410156 278.800781 403.410156 C 278.953125 403.410156 279.109375 403.566406 279.261719 403.71875 C 279.417969 403.875 279.726562 404.027344 279.878906 404.335938 C 280.34375 404.800781 280.808594 405.109375 281.425781 405.417969 C 282.042969 405.726562 282.660156 405.882812 283.277344 405.882812 C 284.824219 405.574219 286.210938 404.957031 286.984375 404.183594 Z M 297.640625 448.523438 C 296.558594 447.90625 295.167969 447.597656 293.933594 448.0625 C 291.152344 448.988281 288.375 449.914062 285.59375 450.84375 C 284.359375 451.304688 283.277344 451.921875 282.660156 453.160156 C 282.042969 454.242188 281.734375 455.785156 282.195312 456.867188 C 282.503906 458.101562 283.277344 459.183594 284.511719 459.804688 C 285.59375 460.421875 286.984375 460.730469 288.21875 460.265625 C 291 459.339844 293.78125 458.414062 296.558594 457.484375 C 297.792969 457.023438 298.875 456.402344 299.492188 455.167969 C 300.109375 454.085938 300.421875 452.542969 299.957031 451.460938 C 299.492188 450.222656 298.722656 449.140625 297.640625 448.523438 Z M 365.589844 519.75 C 368.214844 519.59375 370.53125 517.585938 370.53125 514.804688 C 370.53125 513.414062 370.53125 511.871094 370.6875 510.480469 C 370.996094 508.160156 371.769531 505.84375 372.539062 503.679688 C 372.539062 503.679688 372.539062 503.527344 372.539062 503.527344 C 373.15625 502.289062 373.464844 501.054688 373.003906 499.820312 C 372.695312 498.738281 371.769531 497.5 370.6875 496.882812 C 369.605469 496.265625 368.214844 495.957031 366.980469 496.417969 C 365.898438 496.726562 364.507812 497.5 364.046875 498.738281 C 361.730469 503.835938 360.496094 509.242188 360.496094 514.960938 C 360.648438 517.429688 362.8125 519.902344 365.589844 519.75 Z M 438.484375 508.160156 C 437.554688 504.144531 436.785156 500.128906 435.855469 496.109375 C 435.546875 494.875 434.621094 493.792969 433.539062 493.175781 C 432.460938 492.558594 430.914062 492.246094 429.835938 492.710938 C 427.207031 493.636719 425.820312 496.109375 426.4375 498.738281 C 427.363281 502.753906 428.136719 506.769531 429.0625 510.789062 C 429.371094 512.023438 430.296875 513.105469 431.378906 513.722656 C 432.460938 514.339844 434.003906 514.652344 435.085938 514.1875 C 437.710938 513.414062 439.101562 510.789062 438.484375 508.160156 Z M 482.03125 513.878906 C 484.347656 512.332031 485.121094 509.550781 483.730469 507.234375 C 482.496094 504.917969 481.261719 502.445312 480.179688 499.972656 C 479.5625 498.429688 478.945312 497.039062 478.480469 495.492188 C 478.015625 494.257812 477.398438 493.175781 476.164062 492.558594 C 475.082031 491.9375 473.539062 491.628906 472.457031 492.09375 C 471.222656 492.402344 470.140625 493.175781 469.523438 494.410156 C 468.90625 495.492188 468.597656 496.882812 469.058594 498.117188 C 470.757812 503.0625 472.921875 507.699219 475.390625 512.332031 C 476.628906 514.339844 479.871094 515.269531 482.03125 513.878906 Z M 404.199219 249.21875 C 403.582031 248.136719 402.5 247.210938 401.265625 246.902344 C 400.027344 246.59375 398.640625 246.746094 397.558594 247.367188 C 396.632812 247.984375 395.550781 249.066406 395.242188 250.300781 C 394.933594 253.082031 394.625 255.707031 394.777344 258.488281 C 394.933594 261.269531 395.394531 263.898438 396.167969 266.523438 C 396.785156 268.996094 399.71875 270.695312 402.191406 269.921875 C 404.660156 269.148438 406.359375 266.523438 405.589844 263.898438 C 405.28125 262.660156 404.96875 261.269531 404.816406 260.035156 C 404.507812 257.253906 404.507812 254.628906 404.816406 251.847656 C 404.816406 252.15625 404.660156 252.464844 404.660156 252.773438 C 404.96875 251.691406 404.96875 250.457031 404.199219 249.21875 Z M 429.527344 387.1875 C 426.898438 382.707031 421.804688 380.234375 416.707031 379.308594 C 411.609375 378.382812 406.359375 379 401.265625 379.464844 C 398.484375 379.773438 395.550781 380.082031 392.769531 380.390625 C 386.128906 381.164062 378.71875 382.242188 374.546875 387.496094 C 370.222656 393.058594 371.148438 401.402344 375.011719 407.273438 C 378.871094 413.144531 384.894531 417.160156 390.761719 421.023438 L 393.851562 422.722656 C 397.867188 425.660156 403.273438 425.8125 407.90625 424.113281 C 412.539062 422.570312 416.398438 419.324219 419.949219 415.925781 C 423.964844 412.21875 427.671875 408.046875 429.835938 402.945312 C 431.996094 397.847656 432.304688 391.824219 429.527344 387.1875 Z M 429.527344 387.1875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFresh, raw and unprocessed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIngredients from life-giving seeds, fruits, buds and flowers, not a laboratory\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b9bbce e-con-full e-flex e-con e-child\" data-id=\"1b9bbce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5a5c99 elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b5a5c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><path fill=\"#38e53a\" d=\"M 596.910156 645.757812 C 574.335938 671.917969 542.902344 688.753906 511.707031 703.875 C 481.332031 718.601562 449.996094 732.601562 424.277344 754.296875 C 425.332031 758.160156 426.289062 762.082031 426.972656 766.171875 L 427.019531 766.453125 C 427.597656 769.921875 425.230469 773.199219 421.730469 773.773438 C 419.300781 774.175781 416.957031 773.15625 415.5625 771.335938 C 410.179688 764.28125 406.160156 756.398438 403.1875 748.21875 C 400.199219 740.023438 398.042969 731.589844 396.003906 723.179688 C 392.082031 706.335938 389.476562 689.308594 387.871094 672.300781 C 358.90625 656.582031 326.171875 648.933594 294.210938 640.425781 C 260.675781 631.492188 226.578125 620.929688 199.371094 599.53125 C 172.167969 578.128906 152.996094 543.488281 159.289062 509.625 C 161.527344 497.582031 167.15625 485.789062 176.792969 478.128906 C 187.621094 469.515625 202.199219 467.023438 216.082031 467.097656 C 264.996094 467.359375 309.828125 499.359375 335.078125 539.144531 C 353.957031 568.894531 373.46875 607.605469 385.847656 643.789062 C 385.484375 636.253906 385.238281 628.734375 385.082031 621.226562 C 384.777344 604.300781 384.640625 587.386719 385.058594 570.472656 C 385.929688 536.652344 387.996094 502.867188 391.488281 469.234375 C 393.253906 452.421875 395.40625 435.652344 397.902344 418.9375 C 400.367188 402.21875 403.195312 385.554688 406.414062 368.972656 C 407.070312 365.601562 410.359375 363.390625 413.757812 364.042969 C 417.066406 364.671875 419.261719 367.769531 418.78125 371.042969 L 418.773438 371.074219 C 416.3125 387.621094 414.074219 404.195312 412.089844 420.789062 C 410.09375 437.386719 408.554688 454.027344 407.1875 470.675781 C 404.347656 503.964844 402.925781 537.351562 402.679688 570.730469 C 402.617188 604.082031 402.777344 637.628906 406.144531 670.425781 C 407.789062 686.839844 410.386719 703.066406 414.179688 718.921875 C 415.109375 722.890625 416.214844 726.804688 417.285156 730.726562 C 418.386719 734.273438 419.421875 737.84375 420.554688 741.371094 C 424.097656 699.46875 437.339844 649.941406 452.070312 612.210938 C 469.183594 568.371094 507.019531 528.464844 554.976562 518.933594 C 568.589844 516.230469 583.378906 515.910156 595.671875 522.3125 C 606.605469 528.003906 614.402344 538.511719 618.921875 549.910156 C 631.625 581.953125 619.488281 619.59375 596.910156 645.757812 Z M 596.910156 645.757812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#5100ff\" d=\"M 620.734375 259.019531 C 596.574219 293.792969 561.34375 318.945312 522.824219 336.078125 C 509.074219 342.191406 421.136719 384.546875 411.589844 380.875 C 315.207031 343.800781 235.390625 237.28125 245.429688 132.324219 C 247.253906 113.261719 251.800781 94.128906 261.648438 77.671875 C 384.230469 116.964844 514.84375 131.546875 643.171875 120.359375 C 657 165.511719 648.328125 219.3125 620.734375 259.019531 Z M 620.734375 259.019531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#00ccff\" d=\"M 441.738281 641.496094 C 444.445312 633.03125 447.285156 624.867188 450.203125 617.125 C 453.746094 614.863281 457.464844 612.855469 461.226562 611.078125 C 475.179688 604.484375 490.324219 600.445312 503.5625 592.375 C 516.890625 584.246094 525.46875 572.007812 532.921875 558.667969 C 540.140625 545.757812 546.734375 532.261719 557.625 521.910156 C 559.179688 520.429688 560.816406 519.035156 562.511719 517.722656 C 570.59375 516.738281 578.847656 516.835938 586.550781 518.84375 C 576.050781 521.714844 566.761719 529.429688 559.875 537.628906 C 550.503906 548.796875 544.773438 562.417969 537.21875 574.761719 C 529.359375 587.601562 519.726562 597.925781 506.191406 604.957031 C 485.355469 615.78125 455.621094 621.105469 441.738281 641.496094 Z M 389.203125 656.480469 C 383.996094 648.277344 380.15625 639.265625 376.617188 630.261719 C 369.675781 612.589844 363.933594 593.722656 351.792969 578.695312 C 345.285156 570.636719 336.929688 564.355469 327.515625 559.976562 C 316.78125 554.984375 305.277344 552.101562 294.300781 547.730469 C 283.90625 543.585938 275.402344 537.109375 268.113281 528.71875 C 260.761719 520.257812 254.769531 510.761719 248.480469 501.53125 C 239.148438 487.828125 227.953125 474.945312 213.835938 467.113281 C 210.34375 467.164062 206.828125 467.390625 203.351562 467.847656 C 209.0625 470.363281 214.234375 474.359375 218.632812 478.507812 C 226.835938 486.242188 233.308594 495.402344 239.566406 504.695312 C 245.878906 514.070312 252.105469 523.617188 259.929688 531.847656 C 268.15625 540.507812 277.867188 546.757812 288.933594 551.277344 C 299.539062 555.613281 310.890625 558.15625 321.230469 563.136719 C 330.308594 567.507812 337.570312 574.007812 343.367188 582.15625 C 354.730469 598.125 359.796875 617.664062 367.320312 635.492188 C 371.558594 645.535156 376.570312 655.554688 383.589844 664 C 386.234375 667.183594 389.417969 670.101562 392.953125 672.5 L 393.722656 670.464844 C 392.761719 666.503906 391.644531 662.453125 390.449219 658.363281 C 390.03125 657.738281 389.601562 657.113281 389.203125 656.480469 Z M 622.640625 562.664062 C 615.136719 566.574219 608.4375 572.214844 602.851562 578.625 C 591.515625 591.632812 585.441406 607.691406 577.300781 622.636719 C 573.320312 629.945312 568.796875 637.105469 562.738281 642.910156 C 557.089844 648.320312 550.261719 652.484375 543.300781 656.015625 C 528 663.777344 511.707031 669.546875 497.691406 679.613281 C 483.289062 689.964844 470.453125 705.050781 470.375 723.53125 C 470.375 723.785156 470.421875 724 470.484375 724.191406 C 474.152344 722.257812 477.847656 720.371094 481.5625 718.515625 C 481.8125 686.699219 518.988281 675.269531 542.363281 663.640625 C 557.347656 656.1875 570.640625 646.882812 580.324219 633.101562 C 589.566406 619.953125 594.949219 604.675781 603.210938 590.972656 C 608.132812 582.8125 615 574.1875 623.628906 569.335938 C 623.398438 567.101562 623.074219 564.875 622.640625 562.664062 Z M 544.558594 627.3125 C 559.441406 612.25 565.5 591.25 574.503906 572.6875 C 581.761719 557.726562 594.089844 540.808594 610.558594 535.121094 C 608.171875 532.027344 605.46875 529.210938 602.4375 526.789062 C 588.402344 531.445312 577.164062 543.5 569.484375 556.066406 C 558.425781 574.167969 553.515625 595.433594 540.71875 612.597656 C 533.953125 621.664062 525.261719 628.285156 514.953125 632.972656 C 504.554688 637.695312 493.480469 640.71875 482.964844 645.164062 C 463.9375 653.199219 447.710938 666.832031 436.175781 683.820312 C 432.269531 689.578125 428.910156 695.703125 426.148438 702.085938 C 422.796875 719.445312 420.515625 736.535156 419.824219 752.21875 C 420.730469 753.019531 421.726562 753.699219 422.527344 754.191406 C 422.710938 754.300781 423.148438 754.539062 423.691406 754.789062 C 424.996094 753.679688 426.308594 752.578125 427.640625 751.503906 C 427.203125 712.472656 450.320312 673.882812 485.632812 656.265625 C 505.285156 646.457031 528.570312 643.492188 544.558594 627.3125 Z M 324.648438 599.386719 C 314.507812 593.25 302.917969 590.21875 291.980469 585.847656 C 280.964844 581.449219 271.558594 575.355469 264.300781 565.925781 C 257.625 557.25 252.867188 547.328125 247.691406 537.75 C 236.808594 517.597656 221.777344 500.625 201.398438 489.5 C 193.082031 484.960938 183.972656 481.578125 174.722656 479.972656 C 172.304688 482.1875 170.160156 484.65625 168.296875 487.34375 C 177.007812 489.226562 185.300781 492.769531 193.023438 497.171875 C 212.425781 508.230469 226.375 524.566406 236.816406 543.953125 C 241.757812 553.128906 246.347656 562.582031 252.632812 570.960938 C 259.101562 579.589844 267.300781 586.085938 277.15625 590.554688 C 287.492188 595.246094 298.597656 598.046875 308.824219 603 C 317.796875 607.347656 325.671875 613.582031 332.015625 621.226562 C 340.246094 631.152344 345.839844 643.082031 348.203125 655.601562 C 352.398438 656.988281 356.558594 658.449219 360.679688 660.003906 C 359.863281 645.746094 354.90625 631.722656 346.617188 620.015625 C 340.800781 611.800781 333.300781 604.625 324.648438 599.386719 Z M 276.375 604.191406 C 267.292969 599.101562 257.410156 596.933594 247.414062 594.359375 C 237.289062 591.753906 227.480469 588.027344 221.101562 579.359375 C 215.425781 571.648438 212.96875 562.164062 210.3125 553.136719 C 207.734375 544.363281 204.910156 535.550781 199.242188 528.199219 C 194.109375 521.542969 187.214844 516.230469 179.621094 512.597656 C 173.367188 509.605469 166.664062 507.84375 159.839844 507.152344 C 159.652344 507.976562 159.445312 508.796875 159.289062 509.625 C 159.082031 510.738281 158.90625 511.855469 158.753906 512.972656 C 163.40625 514.332031 167.855469 516.25 171.789062 518.484375 C 179.027344 522.589844 185.3125 528.328125 189.746094 535.355469 C 194.605469 543.058594 196.898438 552 199.449219 560.632812 C 201.976562 569.175781 204.777344 578.039062 210.699219 584.941406 C 217.085938 592.382812 226.234375 595.835938 235.519531 598.253906 C 245.1875 600.773438 254.832031 602.78125 263.71875 607.527344 C 272.378906 612.15625 280.011719 618.566406 286.089844 626.238281 C 289.40625 630.421875 292.257812 634.976562 294.53125 639.800781 C 294.65625 640.0625 294.753906 640.335938 294.875 640.597656 C 299.824219 641.914062 304.789062 643.214844 309.753906 644.523438 C 306.8125 637.125 303.730469 629.976562 298.691406 623.4375 C 292.675781 615.628906 285 609.023438 276.375 604.191406 Z M 276.375 604.191406 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffe6\" d=\"M 273.953125 197.359375 C 274.613281 200.097656 270.546875 200.441406 268.808594 200.359375 C 267.289062 200.285156 265.503906 199.746094 264.1875 198.976562 C 263.285156 198.449219 262.089844 197.527344 261.820312 196.425781 C 259.957031 188.71875 259.792969 180.574219 261.367188 172.804688 C 261.585938 171.710938 262.726562 171.234375 263.660156 170.929688 C 265.089844 170.464844 266.734375 170.667969 268.179688 170.957031 C 270.097656 171.34375 274.070312 172.964844 273.546875 175.546875 C 272.058594 182.902344 272.1875 190.078125 273.953125 197.359375 Z M 307 207.335938 C 306.777344 206.355469 306.578125 205.371094 306.402344 204.378906 C 306.375 204.234375 306.359375 204.160156 306.351562 204.113281 C 306.34375 204.058594 306.335938 203.96875 306.3125 203.792969 C 306.257812 203.363281 306.195312 202.9375 306.144531 202.507812 C 305.925781 200.652344 305.804688 198.785156 305.78125 196.917969 C 305.726562 193.179688 306.070312 189.449219 306.773438 185.773438 C 306.988281 184.648438 305.84375 183.339844 305.058594 182.757812 C 303.894531 181.890625 302.128906 181.378906 300.695312 181.367188 C 297.945312 181.34375 294.867188 182.289062 294.296875 185.292969 C 292.785156 193.199219 293.09375 201.25 294.886719 209.085938 C 295.148438 210.242188 296.691406 211.261719 297.65625 211.6875 C 299.042969 212.304688 300.949219 212.5625 302.445312 212.292969 C 305.023438 211.832031 307.679688 210.304688 307 207.335938 Z M 337.261719 225.246094 C 339.910156 224.804688 343.453125 222.558594 342.792969 219.332031 C 342.234375 216.605469 341.988281 213.839844 342.023438 211.058594 C 342.164062 208.511719 342.539062 205.992188 343.171875 203.519531 C 343.507812 202.210938 342.914062 200.617188 342.039062 199.65625 C 341.085938 198.609375 339.441406 197.867188 338.035156 197.78125 C 334.910156 197.59375 331.703125 199.132812 330.878906 202.339844 C 329.335938 208.355469 329.164062 214.84375 330.410156 220.929688 C 331.035156 223.992188 334.246094 225.75 337.261719 225.246094 Z M 377.199219 217.46875 C 375.949219 216.785156 374.359375 216.339844 372.96875 216.09375 C 371.53125 215.835938 369.984375 215.59375 368.53125 215.804688 C 368.015625 215.878906 366.480469 216.011719 366.480469 216.773438 C 366.480469 222.527344 366.480469 228.28125 366.480469 234.035156 C 366.480469 234.839844 367.441406 235.375 368.027344 235.695312 C 369.277344 236.375 370.867188 236.824219 372.257812 237.070312 C 373.695312 237.324219 375.242188 237.566406 376.695312 237.359375 C 377.210938 237.285156 378.746094 237.148438 378.746094 236.386719 C 378.746094 230.632812 378.746094 224.882812 378.746094 219.128906 C 378.746094 218.324219 377.785156 217.789062 377.199219 217.46875 Z M 406.183594 226.269531 C 404.902344 225.433594 403.195312 224.773438 401.6875 224.539062 C 399.921875 224.261719 396.335938 223.976562 396.457031 226.597656 C 396.726562 232.339844 396.996094 238.078125 397.265625 243.820312 C 397.308594 244.785156 398.828125 245.90625 399.476562 246.332031 C 400.757812 247.167969 402.464844 247.828125 403.972656 248.066406 C 405.738281 248.34375 409.324219 248.628906 409.203125 246.003906 C 408.933594 240.265625 408.664062 234.523438 408.398438 228.78125 C 408.351562 227.820312 406.832031 226.695312 406.183594 226.269531 Z M 447.007812 236.125 C 447.003906 235.667969 447 235.210938 447.007812 234.753906 C 447.027344 233.441406 446.691406 232.457031 445.917969 231.371094 C 445.042969 230.128906 443.609375 228.90625 442.238281 228.253906 C 441.066406 227.691406 439.59375 227.082031 438.273438 227.359375 C 437.382812 227.546875 436.191406 228.070312 436.175781 229.175781 C 436.09375 234.628906 436.574219 240.046875 437.804688 245.367188 C 438.117188 246.714844 438.90625 247.894531 439.875 248.863281 C 440.9375 249.929688 442.503906 250.996094 443.972656 251.410156 C 445.039062 251.710938 446.519531 252.0625 447.523438 251.402344 C 448.394531 250.835938 448.851562 249.910156 448.605469 248.847656 C 447.640625 244.667969 447.113281 240.410156 447.007812 236.125 Z M 476.824219 226.050781 C 475.75 224.996094 474.074219 224.003906 472.5625 223.769531 C 471.324219 223.578125 469.777344 223.515625 468.738281 224.363281 C 467.832031 225.101562 467.144531 226.289062 467.421875 227.507812 C 468.023438 230.175781 468.292969 232.894531 468.253906 235.625 C 468.207031 236.503906 468.148438 237.375 468.039062 238.246094 C 467.863281 239.613281 468.234375 240.859375 469.003906 241.996094 C 469.855469 243.257812 471.355469 244.476562 472.78125 245.011719 C 474.070312 245.492188 475.648438 245.890625 476.996094 245.394531 C 478.089844 244.992188 479.203125 244.207031 479.363281 242.941406 C 479.921875 238.5625 479.8125 234.085938 478.839844 229.773438 C 478.507812 228.296875 477.921875 227.128906 476.824219 226.050781 Z M 515.363281 236.070312 C 514.4375 230.707031 514.25 225.246094 514.796875 219.828125 C 514.875 219.089844 512.960938 218.835938 512.695312 218.804688 C 511.28125 218.640625 509.621094 218.851562 508.253906 219.179688 C 506.835938 219.523438 505.3125 219.929688 504.078125 220.738281 C 503.363281 221.210938 502.707031 221.652344 502.617188 222.566406 C 502.066406 227.984375 502.257812 233.445312 503.183594 238.808594 C 503.316406 239.582031 504.78125 239.777344 505.285156 239.835938 C 506.699219 239.996094 508.359375 239.785156 509.726562 239.457031 C 511.144531 239.117188 512.667969 238.707031 513.898438 237.898438 C 514.488281 237.511719 515.511719 236.917969 515.363281 236.070312 Z M 545.085938 212.570312 C 544.664062 211.230469 543.367188 210.128906 542.097656 209.636719 C 540.703125 209.097656 538.804688 209.09375 537.417969 209.652344 C 534.566406 210.792969 532.324219 213.582031 533.324219 216.765625 C 533.546875 217.46875 533.726562 218.183594 533.886719 218.902344 C 534.199219 220.890625 534.273438 222.902344 534.109375 224.910156 C 533.902344 226.335938 533.597656 227.742188 533.148438 229.117188 C 532.722656 230.421875 533.121094 232.125 533.933594 233.195312 C 534.773438 234.300781 536.328125 235.113281 537.703125 235.230469 C 540.972656 235.507812 544.078125 233.730469 545.109375 230.5625 C 547 224.75 546.914062 218.382812 545.085938 212.570312 Z M 578.613281 213.835938 C 577.34375 213.113281 575.960938 212.367188 574.515625 212.09375 C 573.953125 211.988281 572.550781 211.640625 572.234375 212.367188 C 570.054688 217.425781 568.808594 222.804688 568.417969 228.296875 C 568.363281 229.074219 569.875 230.394531 570.296875 230.765625 C 571.464844 231.792969 572.929688 232.730469 574.34375 233.375 C 575.449219 233.878906 576.78125 234.535156 578.019531 234.484375 C 578.777344 234.453125 579.269531 234.351562 579.328125 233.496094 C 579.390625 232.660156 579.476562 231.828125 579.578125 230.996094 C 580.164062 226.757812 581.308594 222.625 583 218.699219 C 583.316406 217.957031 582.546875 217.046875 582.128906 216.570312 C 581.191406 215.496094 579.839844 214.53125 578.613281 213.835938 Z M 608.183594 223.792969 C 606.59375 223.714844 604.902344 223.804688 603.398438 224.355469 C 602.492188 224.6875 600.96875 225.210938 600.628906 226.222656 C 598.621094 232.207031 596.027344 237.976562 592.890625 243.453125 C 592.414062 244.285156 592.992188 245.132812 593.644531 245.617188 C 594.628906 246.34375 596.269531 246.652344 597.445312 246.710938 C 599.03125 246.792969 600.726562 246.703125 602.230469 246.152344 C 603.269531 245.769531 604.417969 245.292969 604.996094 244.28125 C 608.136719 238.804688 610.726562 233.035156 612.738281 227.050781 C 613.550781 224.625 609.890625 223.878906 608.183594 223.792969 Z M 405.234375 326.308594 C 404.570312 320.984375 404.449219 315.617188 404.917969 310.269531 C 405.175781 307.273438 401.414062 306.097656 399.050781 306.476562 C 396.273438 306.921875 393.019531 308.730469 392.75 311.851562 C 392.085938 319.480469 392.617188 327.152344 394.144531 334.652344 C 394.382812 335.828125 395.851562 336.726562 396.871094 337.046875 C 398.265625 337.484375 400.113281 337.382812 401.46875 336.878906 C 404.125 335.894531 406.609375 333.757812 405.984375 330.691406 C 405.6875 329.238281 405.449219 327.773438 405.234375 326.308594 Z M 433.46875 313.214844 C 432.417969 312.453125 430.777344 312.269531 429.542969 312.542969 C 427.96875 312.894531 426.394531 313.65625 425.300781 314.867188 C 424.367188 315.902344 423.414062 317.265625 423.414062 318.722656 C 423.414062 323.039062 423.414062 327.355469 423.414062 331.667969 C 423.414062 332.96875 423.796875 334.175781 424.898438 334.96875 C 425.949219 335.730469 427.59375 335.914062 428.828125 335.640625 C 430.398438 335.289062 431.972656 334.527344 433.066406 333.320312 C 434 332.285156 434.953125 330.917969 434.953125 329.460938 C 434.953125 325.144531 434.953125 320.832031 434.953125 316.515625 C 434.953125 315.214844 434.570312 314.007812 433.46875 313.214844 Z M 459.558594 310.039062 C 458.382812 309.605469 456.910156 309.085938 455.648438 309.398438 C 454.789062 309.609375 454.007812 310.027344 454.007812 311.054688 C 454.007812 315.371094 454.007812 319.683594 454.007812 324 C 454.007812 325.074219 454.976562 326.230469 455.667969 326.917969 C 456.753906 327.996094 458.296875 328.984375 459.730469 329.511719 C 460.90625 329.949219 462.382812 330.46875 463.640625 330.15625 C 464.503906 329.941406 465.28125 329.527344 465.28125 328.5 C 465.28125 324.183594 465.28125 319.867188 465.28125 315.554688 C 465.28125 314.480469 464.3125 313.324219 463.621094 312.636719 C 462.535156 311.558594 460.992188 310.570312 459.558594 310.039062 Z M 495.148438 306.582031 C 495.148438 307.539062 494.851562 308.515625 494.671875 309.453125 C 494.46875 310.503906 494.265625 311.558594 494.0625 312.609375 C 493.660156 314.714844 493.253906 316.820312 492.847656 318.925781 C 492.789062 319.753906 492.472656 320.46875 491.902344 321.070312 C 491.5625 321.347656 491.226562 321.625 490.886719 321.902344 C 489.617188 322.792969 487.929688 322.996094 486.421875 322.976562 C 484.980469 322.957031 483.214844 322.40625 482.066406 321.511719 C 481.261719 320.886719 480.152344 319.523438 480.375 318.371094 C 480.796875 316.179688 481.21875 313.988281 481.640625 311.796875 C 481.851562 310.699219 482.0625 309.601562 482.273438 308.507812 C 482.304688 308.34375 482.34375 308.179688 482.378906 308.011719 C 482.25 307.839844 482.128906 307.660156 482.019531 307.464844 C 481.183594 305.945312 481.457031 304.203125 482.601562 302.898438 C 483.476562 301.90625 484.660156 301.402344 485.910156 301.097656 C 487.820312 300.628906 489.917969 300.785156 491.714844 301.625 C 493.71875 302.566406 495.15625 304.316406 495.148438 306.582031 Z M 486.507812 301.894531 C 486.457031 301.910156 486.40625 301.929688 486.351562 301.949219 C 486.480469 301.921875 486.609375 301.902344 486.738281 301.882812 C 486.660156 301.886719 486.582031 301.890625 486.507812 301.894531 Z M 525.039062 291.515625 C 522.167969 290.359375 518.554688 291.085938 517.335938 294.242188 C 514.929688 300.460938 514.144531 307.058594 514.742188 313.679688 C 514.878906 315.164062 516.066406 316.820312 517.191406 317.707031 C 518.359375 318.628906 520.160156 319.316406 521.675781 319.148438 C 523.144531 318.984375 524.675781 318.417969 525.570312 317.160156 C 526.5 315.855469 526.738281 314.5 526.59375 312.910156 C 526.566406 312.59375 526.550781 312.28125 526.53125 311.964844 C 526.46875 309.132812 526.730469 306.316406 527.308594 303.546875 C 527.675781 302.125 528.109375 300.722656 528.640625 299.351562 C 529.789062 296.375 527.953125 292.6875 525.039062 291.515625 Z M 559.742188 293.859375 C 558.152344 294.078125 556.539062 294.628906 555.226562 295.5625 C 554.054688 296.398438 553.207031 297.328125 552.527344 298.605469 C 550.179688 303.019531 547.832031 307.433594 545.484375 311.851562 C 545.015625 312.730469 545.332031 313.960938 546.058594 314.582031 C 546.921875 315.324219 548.496094 315.433594 549.546875 315.289062 C 551.132812 315.070312 552.75 314.519531 554.0625 313.585938 C 555.234375 312.75 556.082031 311.820312 556.761719 310.542969 C 559.109375 306.125 561.457031 301.710938 563.804688 297.296875 C 564.273438 296.414062 563.957031 295.1875 563.230469 294.5625 C 562.367188 293.824219 560.792969 293.714844 559.742188 293.859375 Z M 371.195312 310.914062 C 371.289062 308.738281 371.492188 306.570312 371.828125 304.417969 C 372.261719 301.664062 369.617188 298.914062 367.390625 297.695312 C 365.9375 296.902344 361.765625 295.402344 361.316406 298.265625 C 360.246094 305.082031 360.328125 312.09375 361.664062 318.863281 C 362.222656 321.703125 364.804688 324.285156 367.511719 325.214844 C 368.554688 325.570312 370.011719 326.007812 371.046875 325.410156 C 371.933594 324.898438 372.453125 323.996094 372.246094 322.933594 C 371.460938 318.972656 371.121094 314.949219 371.195312 310.914062 Z M 343.769531 284.84375 C 342.554688 284.070312 340.746094 283.75 339.335938 284.0625 C 336.003906 284.8125 333.886719 287.304688 333.886719 290.695312 C 333.886719 298.246094 333.886719 305.796875 333.886719 313.347656 C 333.886719 314.71875 335.09375 316.257812 336.179688 316.949219 C 337.398438 317.726562 339.207031 318.046875 340.617188 317.730469 C 343.949219 316.984375 346.066406 314.492188 346.066406 311.101562 C 346.066406 303.550781 346.066406 296 346.066406 288.449219 C 346.066406 287.074219 344.859375 285.539062 343.769531 284.84375 Z M 317.210938 277.949219 C 317.703125 275.476562 313.613281 273.957031 311.832031 273.578125 C 310.394531 273.269531 308.769531 273.027344 307.332031 273.421875 C 306.460938 273.660156 305.265625 274.046875 305.0625 275.078125 C 303.417969 283.347656 304.257812 292.105469 307.519531 299.882812 C 308.570312 302.375 312.015625 303.515625 314.511719 303.699219 C 315.734375 303.789062 320.671875 303.628906 319.609375 301.089844 C 316.519531 293.734375 315.660156 285.777344 317.210938 277.949219 Z M 264.675781 123.558594 C 265.097656 123.421875 265.523438 123.289062 265.949219 123.15625 C 266.609375 122.921875 267.152344 122.53125 267.582031 121.980469 C 269.332031 118.355469 271.082031 114.730469 272.832031 111.101562 C 273.933594 108.820312 270.113281 107.808594 268.554688 107.609375 C 266.976562 107.40625 265.289062 107.355469 263.742188 107.769531 C 263.316406 107.902344 262.890625 108.035156 262.464844 108.167969 C 261.804688 108.402344 261.261719 108.796875 260.832031 109.34375 C 259.082031 112.96875 257.332031 116.597656 255.582031 120.222656 C 254.480469 122.503906 258.300781 123.515625 259.859375 123.714844 C 261.4375 123.917969 263.125 123.96875 264.675781 123.558594 Z M 440.121094 161.867188 C 439.199219 158.238281 438.882812 154.496094 439.164062 150.765625 C 439.207031 150.292969 439.257812 149.820312 439.320312 149.347656 C 439.476562 149.050781 439.425781 148.847656 439.171875 148.726562 C 438.9375 148.488281 438.632812 148.40625 438.261719 148.488281 C 437.089844 148.445312 435.621094 148.917969 434.550781 149.304688 C 433.050781 149.847656 431.542969 150.488281 430.199219 151.355469 C 429.84375 151.597656 429.488281 151.839844 429.132812 152.082031 C 428.636719 152.417969 428.238281 152.84375 427.933594 153.355469 C 427.339844 157.863281 427.539062 162.40625 428.65625 166.820312 C 428.8125 167.4375 430.558594 167.144531 430.773438 167.113281 C 432.191406 166.902344 433.710938 166.363281 435.011719 165.785156 C 436.34375 165.1875 437.746094 164.542969 438.882812 163.613281 C 439.351562 163.226562 440.304688 162.59375 440.121094 161.867188 Z M 406.285156 138.507812 C 404.828125 138.246094 403.15625 138.257812 401.859375 139.089844 C 401.488281 139.378906 401.113281 139.671875 400.738281 139.960938 C 400.058594 140.683594 399.648438 141.535156 399.503906 142.515625 C 398.492188 146.46875 398.324219 150.65625 398.816406 154.699219 C 398.992188 156.152344 400 157.628906 401.105469 158.53125 C 402.285156 159.492188 404.125 160.230469 405.671875 160.144531 C 407.097656 160.0625 408.671875 159.660156 409.640625 158.523438 C 410.613281 157.390625 411.046875 156.058594 410.863281 154.550781 C 410.761719 153.707031 410.707031 152.863281 410.675781 152.015625 C 410.714844 149.71875 411.003906 147.4375 411.578125 145.207031 C 411.914062 143.898438 411.148438 142.089844 410.382812 141.089844 C 409.453125 139.871094 407.804688 138.785156 406.285156 138.507812 Z M 386.0625 135.046875 C 384.765625 134.40625 383.277344 133.941406 381.882812 133.589844 C 380.460938 133.230469 378.992188 132.867188 377.523438 132.808594 C 377.015625 132.789062 375.824219 132.597656 375.539062 133.164062 C 373.65625 136.941406 373.242188 141.320312 374.394531 145.382812 C 374.585938 146.050781 375.386719 146.386719 375.949219 146.664062 C 377.246094 147.300781 378.738281 147.769531 380.132812 148.121094 C 381.550781 148.480469 383.023438 148.839844 384.492188 148.902344 C 384.71875 148.910156 386.605469 149 386.476562 148.546875 C 385.324219 144.484375 385.734375 140.105469 387.617188 136.328125 C 387.851562 135.863281 386.085938 135.054688 386.0625 135.046875 Z M 355.777344 125.605469 C 354.800781 124.636719 353.140625 124.035156 351.789062 123.988281 C 350.1875 123.933594 348.441406 124.199219 347.085938 125.109375 C 346.011719 125.828125 344.808594 126.890625 344.621094 128.257812 C 344.234375 131.132812 343.84375 134.007812 343.453125 136.878906 C 343.28125 137.527344 343.328125 138.148438 343.59375 138.738281 C 343.730469 139.375 344.050781 139.914062 344.5625 140.355469 C 345.542969 141.324219 347.199219 141.925781 348.550781 141.972656 C 350.152344 142.027344 351.898438 141.761719 353.253906 140.851562 C 354.332031 140.128906 355.53125 139.070312 355.71875 137.699219 C 356.109375 134.828125 356.496094 131.953125 356.886719 129.082031 C 357.0625 128.433594 357.015625 127.8125 356.746094 127.222656 C 356.609375 126.585938 356.289062 126.046875 355.777344 125.605469 Z M 469.265625 164.175781 C 469.5 163.792969 469.738281 163.410156 469.976562 163.023438 C 470.339844 162.222656 470.421875 161.398438 470.21875 160.542969 C 469.769531 158.042969 469.316406 155.539062 468.863281 153.039062 C 468.71875 152.386719 468.394531 151.855469 467.898438 151.441406 C 467.476562 150.914062 466.933594 150.539062 466.277344 150.316406 C 465.574219 150.011719 464.847656 149.867188 464.09375 149.882812 C 463.277344 149.789062 462.464844 149.859375 461.664062 150.09375 C 460.203125 150.523438 458.648438 151.246094 457.726562 152.507812 C 457.488281 152.894531 457.25 153.277344 457.015625 153.664062 C 456.652344 154.460938 456.570312 155.289062 456.769531 156.144531 C 457.222656 158.644531 457.671875 161.144531 458.125 163.648438 C 458.273438 164.300781 458.59375 164.832031 459.089844 165.246094 C 459.515625 165.773438 460.054688 166.148438 460.710938 166.371094 C 461.414062 166.675781 462.140625 166.820312 462.898438 166.800781 C 463.714844 166.898438 464.523438 166.828125 465.324219 166.589844 C 466.789062 166.164062 468.339844 165.441406 469.265625 164.175781 Z M 498.792969 146.316406 C 498.46875 145.785156 498.019531 145.378906 497.4375 145.105469 C 496.800781 144.730469 496.117188 144.488281 495.390625 144.386719 C 494.601562 144.167969 493.792969 144.097656 492.96875 144.167969 C 491.480469 144.285156 489.824219 144.605469 488.621094 145.554688 C 488.308594 145.839844 488 146.125 487.6875 146.410156 C 487.175781 146.996094 486.925781 147.679688 486.9375 148.457031 C 487.398438 150.957031 487.855469 153.457031 488.3125 155.957031 C 488.332031 156.546875 488.539062 157.046875 488.929688 157.460938 C 489.25 157.992188 489.703125 158.394531 490.28125 158.671875 C 490.921875 159.046875 491.605469 159.285156 492.332031 159.390625 C 493.121094 159.605469 493.925781 159.679688 494.75 159.609375 C 496.242188 159.492188 497.898438 159.171875 499.101562 158.21875 C 499.410156 157.9375 499.722656 157.652344 500.035156 157.367188 C 500.542969 156.777344 500.792969 156.09375 500.78125 155.320312 C 500.324219 152.820312 499.867188 150.320312 499.410156 147.820312 C 499.390625 147.230469 499.183594 146.726562 498.792969 146.316406 Z M 296.082031 121.933594 C 295.875 120.289062 295.863281 118.632812 296.015625 116.984375 C 296.144531 115.972656 296.332031 114.972656 296.597656 113.984375 C 297.230469 111.625 293 111.753906 291.671875 111.921875 C 290.09375 112.117188 288.453125 112.472656 287.03125 113.207031 C 286.648438 113.425781 286.265625 113.644531 285.882812 113.863281 C 285.300781 114.214844 284.859375 114.691406 284.554688 115.289062 C 283.742188 118.3125 283.496094 121.527344 283.890625 124.632812 C 284 125.5 285.449219 125.855469 286.058594 125.96875 C 287.457031 126.222656 289.167969 126.054688 290.527344 125.726562 C 291.949219 125.386719 293.496094 124.945312 294.679688 124.058594 C 295.359375 123.546875 296.203125 122.902344 296.082031 121.933594 Z M 319.839844 116.386719 C 319.320312 115.71875 318.707031 115.160156 318 114.707031 C 317.382812 114.203125 316.691406 113.816406 315.929688 113.558594 C 314.785156 113.191406 313.289062 112.855469 312.179688 113.511719 C 311.890625 113.734375 311.601562 113.957031 311.3125 114.179688 C 310.820312 114.792969 310.59375 115.492188 310.628906 116.28125 C 310.628906 118.917969 310.628906 121.554688 310.628906 124.191406 C 310.628906 125.542969 311.425781 127.019531 312.246094 128.035156 C 312.765625 128.703125 313.378906 129.261719 314.085938 129.714844 C 314.703125 130.21875 315.394531 130.605469 316.15625 130.867188 C 317.300781 131.230469 318.792969 131.566406 319.902344 130.910156 C 320.195312 130.6875 320.484375 130.464844 320.773438 130.242188 C 321.265625 129.628906 321.492188 128.929688 321.457031 128.140625 C 321.457031 125.503906 321.457031 122.867188 321.457031 120.230469 C 321.457031 118.878906 320.65625 117.402344 319.839844 116.386719 Z M 534.988281 154.324219 C 535.476562 153.832031 535.683594 153.246094 535.613281 152.554688 C 535.191406 150.863281 534.769531 149.167969 534.347656 147.476562 C 534.277344 146.902344 534.058594 146.402344 533.695312 145.972656 C 533.355469 145.394531 532.90625 144.914062 532.347656 144.53125 C 531.722656 144.03125 531.039062 143.640625 530.296875 143.359375 C 529.550781 142.984375 528.761719 142.726562 527.929688 142.589844 C 527.421875 142.535156 526.914062 142.480469 526.40625 142.425781 C 525.527344 142.386719 524.683594 142.535156 523.871094 142.871094 C 523.582031 143.066406 523.289062 143.261719 523 143.457031 C 522.507812 143.945312 522.300781 144.535156 522.371094 145.222656 C 522.792969 146.917969 523.214844 148.609375 523.636719 150.304688 C 523.707031 150.875 523.925781 151.378906 524.289062 151.808594 C 524.628906 152.382812 525.078125 152.863281 525.636719 153.25 C 526.261719 153.75 526.945312 154.140625 527.6875 154.417969 C 528.433594 154.796875 529.222656 155.050781 530.054688 155.191406 C 530.5625 155.246094 531.070312 155.300781 531.578125 155.355469 C 532.457031 155.390625 533.300781 155.242188 534.113281 154.910156 C 534.402344 154.714844 534.695312 154.519531 534.988281 154.324219 Z M 569.160156 151.492188 C 568.71875 149.566406 568.277344 147.640625 567.835938 145.710938 C 567.605469 145.257812 567.277344 144.90625 566.851562 144.648438 C 566.367188 144.238281 565.820312 143.929688 565.207031 143.722656 C 564.480469 143.417969 563.730469 143.207031 562.953125 143.089844 C 562.140625 142.898438 561.316406 142.804688 560.480469 142.804688 C 559.972656 142.828125 559.46875 142.851562 558.964844 142.875 C 558.136719 142.945312 557.355469 143.167969 556.613281 143.535156 C 556.378906 143.722656 556.140625 143.90625 555.902344 144.09375 C 555.542969 144.527344 555.480469 145.003906 555.710938 145.519531 C 556.152344 147.445312 556.59375 149.375 557.035156 151.300781 C 557.261719 151.753906 557.589844 152.109375 558.019531 152.363281 C 558.503906 152.773438 559.050781 153.082031 559.660156 153.292969 C 560.386719 153.59375 561.140625 153.804688 561.917969 153.921875 C 562.726562 154.113281 563.554688 154.210938 564.390625 154.210938 C 564.894531 154.1875 565.398438 154.164062 565.90625 154.140625 C 566.730469 154.066406 567.515625 153.84375 568.253906 153.476562 C 568.492188 153.292969 568.726562 153.105469 568.964844 152.921875 C 569.324219 152.484375 569.390625 152.007812 569.160156 151.492188 Z M 597.179688 156.863281 C 597.476562 156.515625 597.773438 156.167969 598.070312 155.820312 C 598.53125 155.207031 598.785156 154.519531 598.832031 153.757812 C 599.253906 151.503906 598.9375 149.179688 598.183594 147.023438 C 597.953125 146.554688 597.59375 146.246094 597.117188 146.09375 C 596.621094 145.796875 596.070312 145.664062 595.472656 145.691406 C 594.75 145.660156 594.046875 145.75 593.363281 145.960938 C 592.5625 146.113281 591.800781 146.386719 591.078125 146.773438 C 590.601562 147.058594 590.125 147.34375 589.648438 147.625 C 588.84375 148.179688 588.152344 148.851562 587.578125 149.640625 C 587.390625 149.992188 587.199219 150.34375 587.011719 150.695312 C 586.746094 151.339844 586.746094 151.976562 587.019531 152.613281 C 587.113281 152.882812 587.179688 153.15625 587.253906 153.429688 C 587.496094 154.785156 587.507812 156.171875 587.257812 157.53125 C 587.226562 158.050781 587.394531 158.472656 587.765625 158.792969 C 588.046875 159.222656 588.457031 159.492188 588.992188 159.59375 C 589.609375 159.773438 590.230469 159.820312 590.859375 159.730469 C 591.601562 159.71875 592.324219 159.585938 593.027344 159.324219 C 594.53125 158.796875 596.070312 158.027344 597.179688 156.863281 Z M 626.808594 156.003906 C 626.578125 155.550781 626.25 155.195312 625.824219 154.941406 C 625.339844 154.53125 624.792969 154.222656 624.183594 154.011719 C 623.453125 153.710938 622.703125 153.5 621.925781 153.382812 C 621.113281 153.191406 620.289062 153.09375 619.453125 153.09375 C 618.949219 153.117188 618.441406 153.140625 617.9375 153.164062 C 617.113281 153.238281 616.328125 153.460938 615.585938 153.828125 C 615.351562 154.011719 615.113281 154.199219 614.878906 154.382812 C 614.519531 154.820312 614.453125 155.296875 614.683594 155.8125 C 615.125 157.738281 615.566406 159.664062 616.007812 161.59375 C 616.238281 162.046875 616.566406 162.398438 616.992188 162.65625 C 617.476562 163.066406 618.023438 163.375 618.632812 163.582031 C 619.363281 163.886719 620.113281 164.097656 620.890625 164.214844 C 621.703125 164.40625 622.527344 164.5 623.363281 164.5 C 623.867188 164.476562 624.375 164.453125 624.878906 164.429688 C 625.703125 164.359375 626.488281 164.136719 627.226562 163.769531 C 627.464844 163.582031 627.703125 163.398438 627.9375 163.210938 C 628.296875 162.777344 628.363281 162.300781 628.132812 161.785156 C 627.691406 159.859375 627.25 157.929688 626.808594 156.003906 Z M 644.53125 165.839844 C 644.296875 165.371094 643.941406 165.0625 643.460938 164.910156 C 642.964844 164.613281 642.414062 164.480469 641.816406 164.507812 C 641.09375 164.476562 640.390625 164.566406 639.707031 164.777344 C 638.90625 164.929688 638.144531 165.203125 637.421875 165.589844 C 636.945312 165.875 636.46875 166.160156 635.992188 166.441406 C 635.1875 166.996094 634.496094 167.667969 633.921875 168.457031 C 633.734375 168.808594 633.546875 169.160156 633.355469 169.511719 C 633.089844 170.15625 633.089844 170.792969 633.363281 171.429688 C 633.457031 171.699219 633.523438 171.972656 633.597656 172.246094 C 633.839844 173.601562 633.851562 174.988281 633.601562 176.347656 C 633.570312 176.867188 633.738281 177.289062 634.109375 177.609375 C 634.390625 178.039062 634.800781 178.308594 635.335938 178.410156 C 635.953125 178.589844 636.574219 178.636719 637.203125 178.546875 C 637.945312 178.535156 638.667969 178.402344 639.375 178.140625 C 640.875 177.613281 642.414062 176.84375 643.523438 175.679688 C 643.820312 175.332031 644.117188 174.984375 644.414062 174.636719 C 644.875 174.023438 645.128906 173.335938 645.175781 172.574219 C 645.597656 170.320312 645.28125 167.996094 644.53125 165.839844 Z M 644.53125 165.839844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#f3a1ff\" d=\"M 586.761719 265.40625 C 593.726562 269.199219 600.355469 273.136719 606.832031 276.644531 C 601.765625 282.355469 596.378906 287.75 590.722656 292.851562 C 585.804688 290.902344 581.027344 288.921875 576.34375 287.050781 C 566.972656 283.3125 557.980469 280.078125 549.382812 278.636719 C 540.894531 277.144531 532.609375 277.554688 523.765625 279.261719 C 514.988281 281.011719 505.902344 283.929688 496.457031 287.363281 C 487.011719 290.804688 477.125 294.539062 466.503906 297.875 C 455.886719 301.132812 444.234375 303.691406 431.960938 304.28125 C 425.851562 304.578125 419.789062 304.246094 413.871094 303.550781 C 407.933594 302.890625 402.152344 301.777344 396.535156 300.386719 C 385.300781 297.527344 374.75 293.59375 364.742188 289.164062 C 354.746094 284.695312 345.203125 279.84375 336.082031 274.980469 C 326.902344 270.179688 317.996094 265.429688 309.074219 261.203125 C 295.613281 254.851562 282.054688 249.640625 268.199219 247.355469 C 264.71875 240.246094 261.625 232.988281 258.855469 225.632812 C 262.722656 225.320312 266.617188 225.175781 270.519531 225.277344 C 276.359375 225.492188 282.027344 226.113281 287.609375 227.0625 C 298.777344 228.988281 309.527344 232.179688 319.757812 235.9375 C 340.269531 243.414062 358.863281 253.070312 377.101562 260.152344 C 386.226562 263.726562 395.277344 266.859375 404.253906 268.824219 C 408.726562 269.878906 413.179688 270.691406 417.574219 271.125 C 421.972656 271.613281 426.324219 271.765625 430.59375 271.558594 C 447.597656 271.039062 465.949219 264.078125 486.328125 257.636719 C 496.554688 254.484375 507.429688 251.375 519.203125 249.933594 C 522.085938 249.472656 525.175781 249.414062 528.140625 249.160156 C 531.15625 249.011719 534.253906 249.121094 537.292969 249.164062 C 540.375 249.453125 543.460938 249.730469 546.515625 250.160156 C 548.035156 250.4375 549.566406 250.691406 551.066406 251.003906 L 555.507812 252.066406 C 567.207031 255.242188 577.40625 260.289062 586.761719 265.40625 Z M 606.726562 178.066406 C 597.367188 172.953125 587.171875 167.902344 575.472656 164.726562 L 571.03125 163.667969 C 569.53125 163.351562 568 163.097656 566.480469 162.820312 C 563.425781 162.390625 560.339844 162.117188 557.253906 161.824219 C 554.21875 161.785156 551.117188 161.671875 548.105469 161.820312 C 545.136719 162.074219 542.046875 162.132812 539.164062 162.59375 C 527.394531 164.035156 516.519531 167.144531 506.292969 170.296875 C 485.914062 176.738281 467.558594 183.699219 450.554688 184.21875 C 446.289062 184.429688 441.9375 184.273438 437.535156 183.785156 C 433.140625 183.351562 428.691406 182.539062 424.21875 181.484375 C 415.238281 179.519531 406.191406 176.386719 397.0625 172.8125 C 378.828125 165.730469 360.230469 156.074219 339.722656 148.597656 C 329.488281 144.839844 318.742188 141.652344 307.570312 139.722656 C 301.992188 138.773438 296.320312 138.152344 290.484375 137.9375 C 284.6875 137.789062 278.917969 138.136719 273.214844 138.855469 C 267.519531 139.710938 261.898438 140.960938 256.429688 142.707031 C 252.398438 144.101562 248.453125 145.722656 244.65625 147.644531 C 244.582031 152.957031 244.703125 158.265625 245.0625 163.558594 C 245.699219 163.3125 246.332031 163.058594 246.976562 162.835938 C 251.445312 161.394531 256 160.304688 260.621094 159.601562 C 265.265625 158.984375 269.9375 158.671875 274.601562 158.742188 C 293.234375 158.96875 311.214844 165.453125 329.039062 173.863281 C 337.957031 178.089844 346.867188 182.839844 356.042969 187.644531 C 365.167969 192.503906 374.710938 197.359375 384.707031 201.824219 C 394.714844 206.253906 405.265625 210.191406 416.5 213.046875 C 422.113281 214.4375 427.898438 215.550781 433.832031 216.210938 C 439.75 216.90625 445.8125 217.242188 451.925781 216.945312 C 464.195312 216.351562 475.851562 213.792969 486.464844 210.535156 C 497.089844 207.199219 506.976562 203.464844 516.421875 200.023438 C 525.863281 196.59375 534.949219 193.671875 543.730469 191.921875 C 552.574219 190.214844 560.855469 189.804688 569.347656 191.300781 C 577.945312 192.738281 586.9375 195.972656 596.308594 199.710938 C 605.714844 203.472656 615.378906 207.742188 626.109375 211.171875 C 631.28125 212.746094 636.597656 214.023438 642.003906 214.882812 C 642.882812 212.046875 643.683594 209.191406 644.414062 206.316406 C 644.800781 203.460938 645.121094 200.597656 645.363281 197.726562 C 641.300781 196.3125 637.300781 194.636719 633.40625 192.738281 C 624.820312 188.519531 616.074219 183.15625 606.726562 178.066406 Z M 645.699219 118.398438 C 645.285156 120.449219 644.824219 122.492188 644.382812 124.539062 C 644 123.136719 643.597656 121.742188 643.171875 120.359375 C 639.765625 120.65625 636.351562 120.925781 632.9375 121.183594 C 633.265625 119.617188 633.597656 118.046875 633.929688 116.472656 C 634.191406 115.226562 634.441406 113.980469 634.660156 112.730469 C 634.765625 112.140625 634.863281 111.546875 634.953125 110.957031 C 634.972656 110.808594 634.996094 110.648438 635 110.601562 C 635.246094 108.386719 635.375 106.160156 635.222656 103.929688 C 635.210938 103.773438 635.101562 102.941406 635.097656 102.835938 C 635.03125 102.460938 634.960938 102.085938 634.871094 101.710938 C 634.683594 100.902344 634.4375 100.109375 634.152344 99.324219 C 634.082031 99.152344 633.972656 98.882812 633.925781 98.785156 C 633.742188 98.410156 633.550781 98.039062 633.347656 97.671875 C 632.976562 97.007812 632.574219 96.359375 632.144531 95.734375 C 632.007812 95.527344 631.867188 95.324219 631.71875 95.125 C 631.710938 95.117188 631.710938 95.113281 631.703125 95.105469 C 631.480469 94.847656 631.265625 94.582031 631.039062 94.328125 C 630.472656 93.6875 629.871094 93.078125 629.246094 92.496094 C 628.851562 92.125 628.433594 91.777344 628.015625 91.433594 C 627.828125 91.300781 627.347656 90.9375 627.261719 90.878906 C 626.984375 90.691406 626.699219 90.503906 626.414062 90.328125 C 625.628906 89.839844 624.816406 89.394531 623.984375 88.996094 C 623.808594 88.910156 623.378906 88.75 623.292969 88.71875 C 623.15625 88.667969 623.019531 88.617188 622.882812 88.570312 C 622.109375 88.308594 621.320312 88.09375 620.523438 87.925781 C 620.355469 87.890625 620.183594 87.863281 620.015625 87.832031 C 619.84375 87.808594 619.617188 87.78125 619.480469 87.78125 C 618.753906 87.769531 618.03125 87.796875 617.304688 87.804688 C 617.785156 87.785156 617.332031 87.71875 617.015625 87.792969 C 616.988281 87.796875 616.960938 87.804688 616.9375 87.808594 C 616.910156 87.808594 616.878906 87.8125 616.851562 87.8125 C 616.886719 87.8125 616.902344 87.808594 616.933594 87.808594 C 616.566406 87.890625 616.203125 87.960938 615.839844 88.054688 C 615.445312 88.160156 615.0625 88.289062 614.675781 88.410156 C 614.640625 88.421875 614.625 88.425781 614.59375 88.4375 C 613.855469 88.800781 613.164062 89.207031 612.460938 89.640625 C 612.335938 89.71875 612.269531 89.753906 612.199219 89.792969 C 612.144531 89.847656 612.105469 89.882812 612.019531 89.964844 C 611.761719 90.191406 611.5 90.417969 611.253906 90.65625 C 610.683594 91.203125 610.167969 91.785156 609.660156 92.382812 C 609.59375 92.46875 609.527344 92.554688 609.492188 92.609375 C 609.359375 92.808594 609.230469 93.011719 609.09375 93.210938 C 610.1875 95.839844 611.097656 98.535156 611.796875 101.222656 C 613.597656 108.136719 614.371094 115.257812 614.8125 122.390625 C 611.140625 122.601562 607.472656 122.796875 603.800781 122.964844 C 603.574219 119.195312 603.246094 115.46875 602.679688 111.765625 C 601.90625 115.558594 601.375 119.277344 601.003906 123.085938 C 596.996094 123.257812 592.988281 123.40625 588.976562 123.53125 C 589.707031 114.761719 591.242188 105.941406 593.976562 97.652344 C 594.597656 95.761719 595.324219 93.898438 596.160156 92.097656 C 596.125 92.039062 596.09375 91.976562 596.058594 91.917969 C 595.757812 91.4375 595.449219 90.96875 595.128906 90.503906 C 595.1875 90.589844 594.761719 90 594.570312 89.726562 C 594.367188 89.476562 593.925781 88.917969 593.988281 88.988281 C 593.753906 88.714844 593.519531 88.441406 593.277344 88.175781 C 592.6875 87.519531 592.066406 86.886719 591.417969 86.289062 C 591.0625 85.960938 590.695312 85.644531 590.320312 85.335938 C 590.253906 85.28125 590.1875 85.234375 590.15625 85.210938 C 589.332031 84.652344 588.507812 84.113281 587.625 83.65625 C 587.511719 83.597656 586.671875 83.253906 586.742188 83.265625 C 586.589844 83.210938 586.4375 83.152344 586.285156 83.101562 C 585.644531 82.898438 584.992188 82.742188 584.332031 82.617188 C 584.160156 82.597656 583.914062 82.566406 583.785156 82.570312 C 583.382812 82.570312 582.984375 82.542969 582.582031 82.554688 C 582.332031 82.5625 581.921875 82.605469 581.777344 82.617188 C 581.429688 82.679688 581.078125 82.742188 580.734375 82.828125 C 580.429688 82.90625 578.890625 83.445312 579.054688 83.339844 C 577.710938 83.9375 576.417969 84.714844 575.238281 85.597656 C 575.1875 85.660156 574.492188 86.238281 574.46875 86.257812 C 574.070312 86.613281 573.679688 86.984375 573.296875 87.359375 C 572.710938 87.9375 572.152344 88.542969 571.617188 89.164062 C 571.363281 89.453125 571.117188 89.753906 570.875 90.054688 C 570.777344 90.1875 570.472656 90.597656 570.402344 90.695312 C 569.847656 91.472656 569.324219 92.273438 568.824219 93.089844 C 568.574219 93.507812 568.335938 93.914062 568.109375 94.316406 C 569.351562 96.71875 570.53125 99.152344 571.652344 101.601562 C 574.902344 108.714844 577.59375 116.125 578.914062 123.792969 C 574.84375 123.875 570.773438 123.933594 566.703125 123.964844 C 565.785156 119.449219 564.347656 115.011719 562.582031 110.726562 C 561.710938 115.132812 561.203125 119.511719 560.800781 124 C 557.117188 124.007812 553.429688 123.988281 549.742188 123.953125 C 550.566406 114.488281 551.824219 104.949219 555.214844 96.082031 C 555.242188 96.015625 555.273438 95.945312 555.300781 95.875 C 554.675781 94.773438 554.035156 93.679688 553.371094 92.605469 C 552.675781 91.488281 551.925781 90.410156 551.175781 89.328125 C 551.136719 89.273438 551.035156 89.136719 550.949219 89.023438 C 550.65625 88.65625 550.359375 88.292969 550.050781 87.9375 C 549.339844 87.121094 548.589844 86.335938 547.789062 85.605469 C 547.527344 85.363281 547.257812 85.136719 546.988281 84.902344 C 546.898438 84.824219 546.832031 84.761719 546.773438 84.710938 C 546.707031 84.671875 546.628906 84.625 546.527344 84.5625 C 545.75 84.089844 544.992188 83.625 544.1875 83.214844 C 543.980469 83.140625 543.378906 82.890625 543.273438 82.855469 C 542.726562 82.683594 542.171875 82.570312 541.617188 82.429688 C 541.492188 82.394531 541.402344 82.371094 541.324219 82.347656 C 541.242188 82.351562 541.144531 82.351562 541.003906 82.351562 C 540.636719 82.351562 540.269531 82.320312 539.898438 82.320312 C 539.503906 82.320312 539.109375 82.355469 538.714844 82.382812 C 538.574219 82.414062 537.769531 82.519531 537.652344 82.542969 C 536.671875 82.757812 535.714844 83.058594 534.773438 83.402344 C 534.65625 83.464844 533.796875 83.824219 533.742188 83.851562 C 533.21875 84.109375 532.699219 84.382812 532.191406 84.675781 C 530.210938 85.804688 529.019531 86.683594 527.800781 87.726562 C 527.46875 88.015625 527.164062 88.320312 526.839844 88.613281 C 528.96875 92.914062 530.34375 97.664062 531.277344 102.390625 C 532.679688 109.464844 533.859375 116.585938 535.019531 123.714844 C 530.8125 123.609375 526.605469 123.480469 522.398438 123.324219 C 521.394531 117.15625 520.332031 110.996094 519.070312 104.886719 C 518.703125 103.101562 518.257812 101.328125 517.75 99.578125 C 515.84375 102.628906 514.160156 105.902344 512.601562 109.4375 C 512.3125 110.101562 512.273438 110.1875 512.488281 109.699219 C 512.332031 110.078125 512.179688 110.460938 512.03125 110.84375 C 511.882812 111.226562 511.738281 111.609375 511.59375 111.992188 C 511.164062 113.152344 510.765625 114.316406 510.394531 115.492188 C 509.707031 117.65625 509.121094 119.847656 508.632812 122.0625 C 508.585938 122.273438 508.550781 122.484375 508.507812 122.695312 C 504.488281 122.488281 500.46875 122.253906 496.453125 121.996094 C 497.898438 114.191406 500.441406 106.605469 504.054688 99.484375 C 506.046875 95.558594 508.414062 91.710938 511.125 88.117188 C 510.910156 87.949219 510.59375 87.691406 510.507812 87.636719 C 509.832031 87.183594 509.128906 86.804688 508.414062 86.433594 C 508.578125 86.53125 507.613281 86.066406 507.347656 85.980469 C 506.960938 85.851562 506.574219 85.730469 506.183594 85.625 C 505.714844 85.5 505.242188 85.390625 504.765625 85.296875 C 504.644531 85.273438 504.363281 85.242188 504.128906 85.21875 C 502.601562 85.128906 501.101562 85.136719 499.578125 85.257812 C 499.277344 85.304688 498.417969 85.417969 498.222656 85.457031 C 497.71875 85.558594 497.21875 85.675781 496.722656 85.800781 C 495.710938 86.058594 494.710938 86.363281 493.726562 86.707031 C 493.3125 86.851562 492.90625 87.03125 492.492188 87.167969 C 492.445312 87.183594 492.410156 87.195312 492.375 87.203125 C 492.339844 87.222656 492.308594 87.234375 492.265625 87.257812 C 491.289062 87.707031 490.324219 88.167969 489.378906 88.679688 C 487.464844 89.714844 485.667969 90.90625 483.902344 92.171875 C 483.816406 92.234375 483.746094 92.285156 483.6875 92.328125 C 483.625 92.378906 483.554688 92.441406 483.460938 92.523438 C 483.050781 92.871094 482.632812 93.207031 482.226562 93.5625 C 482.089844 93.683594 481.964844 93.8125 481.828125 93.9375 C 482.339844 95.664062 482.773438 97.425781 483.125 99.203125 C 484.574219 106.519531 485.097656 114.039062 486.652344 121.328125 C 482.367188 121.007812 478.078125 120.660156 473.792969 120.285156 C 473.027344 115.660156 472.511719 110.980469 471.765625 106.347656 C 469.125 110.664062 467.097656 114.957031 465.550781 119.519531 C 461.335938 119.113281 457.121094 118.683594 452.910156 118.226562 C 455.332031 110.058594 459.101562 102.25 464.0625 95.386719 C 465.125 93.921875 466.246094 92.515625 467.398438 91.136719 C 467.125 90.621094 466.863281 90.09375 466.558594 89.59375 C 466.242188 89.078125 465.902344 88.582031 465.566406 88.078125 C 465.484375 87.953125 465.429688 87.871094 465.394531 87.816406 C 465.359375 87.773438 465.332031 87.742188 465.277344 87.675781 C 464.542969 86.804688 463.777344 85.964844 462.945312 85.183594 C 462.617188 84.875 462.269531 84.585938 461.925781 84.296875 C 462.046875 84.40625 461.527344 83.976562 461.226562 83.769531 C 460.316406 83.148438 459.371094 82.585938 458.390625 82.085938 C 457.992188 81.878906 457.582031 81.695312 457.171875 81.507812 C 457.027344 81.457031 456.640625 81.300781 456.382812 81.210938 C 455.335938 80.84375 454.269531 80.535156 453.191406 80.28125 C 452.605469 80.144531 452.019531 80.023438 451.425781 79.917969 C 450.882812 79.824219 449.921875 79.777344 451.039062 79.847656 C 449.910156 79.773438 448.796875 79.65625 447.664062 79.640625 C 446.53125 79.625 445.398438 79.664062 444.265625 79.753906 C 443.90625 79.78125 443.550781 79.824219 443.191406 79.863281 C 443.152344 79.878906 442.351562 79.992188 442.027344 80.054688 C 439.769531 80.480469 437.652344 81.203125 435.480469 81.929688 C 435.460938 81.9375 435.457031 81.9375 435.4375 81.945312 C 435.230469 82.039062 435.023438 82.128906 434.816406 82.226562 C 434.347656 82.449219 433.882812 82.679688 433.421875 82.921875 C 432.417969 83.449219 431.4375 84.023438 430.480469 84.628906 C 430.074219 84.886719 429.679688 85.164062 429.285156 85.4375 C 429.824219 86.457031 430.332031 87.484375 430.796875 88.527344 C 434.792969 97.46875 436.625 106.898438 437.949219 116.488281 C 433.695312 115.957031 429.449219 115.394531 425.207031 114.808594 C 424.765625 111.96875 424.25 109.136719 423.609375 106.332031 C 423.011719 103.730469 422.308594 101.152344 421.449219 98.625 C 420.84375 96.839844 420.4375 95.726562 419.886719 94.503906 C 419.808594 94.601562 419.730469 94.699219 419.695312 94.75 C 419.355469 95.207031 419.019531 95.667969 418.691406 96.132812 C 418.035156 97.0625 417.402344 98.015625 416.796875 98.980469 C 415.476562 101.074219 414.273438 103.242188 413.171875 105.460938 C 412.582031 106.652344 412.027344 107.863281 411.488281 109.082031 C 411.425781 109.21875 411.386719 109.3125 411.355469 109.375 C 411.332031 109.4375 411.296875 109.53125 411.234375 109.683594 C 410.996094 110.277344 410.761719 110.871094 410.53125 111.46875 C 410.386719 111.84375 410.265625 112.222656 410.128906 112.597656 C 405.921875 111.953125 401.722656 111.277344 397.527344 110.574219 C 400.238281 102.660156 403.96875 95.058594 408.914062 88.445312 C 410.152344 86.785156 411.46875 85.175781 412.851562 83.632812 C 412.496094 83.246094 412.160156 82.84375 411.789062 82.472656 C 411.007812 81.6875 410.191406 80.933594 409.339844 80.222656 C 409.222656 80.121094 407.773438 79.042969 408.871094 79.828125 C 408.574219 79.617188 408.277344 79.398438 407.972656 79.1875 C 406.417969 78.113281 404.753906 77.171875 403.023438 76.398438 C 402.78125 76.324219 401.757812 75.929688 401.597656 75.875 C 401.148438 75.726562 400.695312 75.59375 400.238281 75.46875 C 399.390625 75.234375 398.535156 75.058594 397.671875 74.898438 C 397.570312 74.890625 396.699219 74.757812 396.570312 74.75 C 396.195312 74.714844 395.816406 74.691406 395.4375 74.675781 C 394.304688 74.621094 393.171875 74.632812 392.039062 74.699219 C 391.648438 74.722656 391.257812 74.761719 390.867188 74.796875 C 390.859375 74.808594 389.871094 74.917969 389.742188 74.941406 C 388.707031 75.125 387.683594 75.351562 386.667969 75.621094 C 385.644531 75.890625 384.632812 76.199219 383.632812 76.550781 C 383.085938 76.742188 382.546875 76.953125 382.007812 77.160156 C 381.972656 77.171875 381.910156 77.199219 381.847656 77.226562 C 380.859375 77.691406 379.890625 78.175781 378.933594 78.679688 C 379.554688 80.429688 380.117188 82.179688 380.609375 83.914062 C 382.839844 91.796875 383.703125 99.960938 383.328125 108.089844 C 379.203125 107.339844 375.085938 106.558594 370.972656 105.753906 C 371 103.921875 370.980469 102.089844 370.867188 100.261719 C 370.582031 95.84375 369.816406 91.414062 368.378906 86.578125 C 367.636719 87.335938 366.902344 88.101562 366.195312 88.894531 C 364.609375 90.671875 363.652344 91.886719 362.675781 93.226562 C 360.4375 96.304688 358.429688 99.527344 356.546875 102.824219 C 352.3125 101.929688 348.078125 101.007812 343.855469 100.054688 C 347.390625 93.515625 351.308594 87.210938 356.140625 81.476562 C 358.296875 78.914062 360.714844 76.519531 363.328125 74.335938 C 362.765625 73.324219 362.148438 72.285156 361.460938 71.183594 C 360.863281 70.222656 360.234375 69.277344 359.574219 68.351562 C 359.53125 68.292969 359.042969 67.644531 358.925781 67.480469 C 358.652344 67.144531 358.382812 66.804688 358.097656 66.476562 C 356.71875 64.859375 355.207031 63.328125 353.546875 61.996094 C 353.496094 61.984375 352.394531 61.1875 352.246094 61.09375 C 351.777344 60.789062 351.296875 60.5 350.8125 60.230469 C 350.320312 59.957031 349.820312 59.71875 349.320312 59.464844 C 349.210938 59.410156 349.125 59.363281 349.054688 59.328125 C 348.96875 59.304688 348.871094 59.277344 348.738281 59.238281 C 347.550781 58.890625 346.394531 58.550781 345.179688 58.285156 C 345.011719 58.25 344.894531 58.222656 344.796875 58.199219 C 344.695312 58.195312 344.570312 58.195312 344.386719 58.1875 C 343.765625 58.160156 343.152344 58.109375 342.53125 58.101562 C 341.703125 58.09375 340.875 58.121094 340.046875 58.183594 C 340 58.1875 339.011719 58.308594 338.847656 58.316406 C 337.726562 58.496094 336.613281 58.734375 335.515625 59.023438 C 334.28125 59.34375 333.0625 59.722656 331.863281 60.148438 C 331.261719 60.363281 330.664062 60.59375 330.070312 60.824219 C 329.878906 60.898438 329.746094 60.949219 329.644531 60.988281 C 329.542969 61.039062 329.410156 61.101562 329.214844 61.195312 C 326.902344 62.296875 324.636719 63.445312 322.460938 64.800781 C 321.824219 65.199219 321.199219 65.617188 320.574219 66.039062 C 325.09375 75.429688 327.417969 85.933594 328.398438 96.425781 C 324.078125 95.378906 319.769531 94.296875 315.464844 93.1875 C 315.453125 93.117188 315.445312 93.046875 315.433594 92.980469 C 315.355469 92.449219 315.273438 91.917969 315.183594 91.390625 C 314.804688 89.109375 314.347656 86.839844 313.804688 84.59375 C 313.304688 82.542969 312.734375 80.507812 312.078125 78.496094 C 311.753906 77.503906 311.40625 76.515625 311.039062 75.535156 C 310.957031 75.3125 310.871094 75.089844 310.785156 74.867188 C 310.65625 75.015625 310.519531 75.15625 310.394531 75.304688 C 310.121094 75.628906 309.855469 75.960938 309.589844 76.292969 C 309.464844 76.46875 309.007812 77.082031 308.960938 77.148438 C 307.578125 79.097656 306.34375 81.148438 305.308594 83.300781 C 305.261719 83.398438 304.976562 84.035156 304.878906 84.234375 C 304.742188 84.582031 304.601562 84.933594 304.472656 85.289062 C 304.113281 86.292969 303.796875 87.3125 303.53125 88.34375 C 303.398438 88.871094 303.289062 89.40625 303.183594 89.9375 C 299.199219 88.855469 295.222656 87.75 291.25 86.617188 C 292.761719 79.648438 296.234375 73.09375 300.847656 67.34375 C 301.980469 65.933594 303.207031 64.601562 304.472656 63.308594 C 304.308594 63.078125 304.140625 62.851562 303.972656 62.621094 C 303.835938 62.457031 303.464844 61.980469 303.382812 61.878906 C 302.738281 61.101562 302.066406 60.339844 301.371094 59.605469 C 300.089844 58.246094 298.722656 56.964844 297.28125 55.777344 C 297.136719 55.660156 296.988281 55.542969 296.839844 55.425781 C 296.773438 55.375 296.671875 55.300781 296.507812 55.175781 C 296.222656 54.980469 295.945312 54.773438 295.660156 54.574219 C 294.714844 53.917969 293.742188 53.296875 292.742188 52.730469 C 292.191406 52.417969 291.636719 52.117188 291.070312 51.839844 C 291.054688 51.832031 289.992188 51.390625 289.921875 51.34375 C 289.050781 51.023438 288.167969 50.742188 287.261719 50.535156 C 286.960938 50.464844 286.652344 50.410156 286.347656 50.355469 C 286.246094 50.347656 286.101562 50.335938 285.847656 50.3125 C 285.234375 50.3125 284.589844 50.335938 283.976562 50.3125 C 283.917969 50.308594 283.875 50.304688 283.828125 50.304688 C 283.425781 50.398438 283.015625 50.460938 282.613281 50.566406 C 282.125 50.695312 281.65625 50.863281 281.175781 51.019531 C 281.121094 51.035156 281.082031 51.046875 281.039062 51.058594 C 280.984375 51.097656 280.914062 51.140625 280.828125 51.191406 C 280.0625 51.65625 279.300781 52.105469 278.550781 52.589844 C 278.347656 52.757812 278.148438 52.929688 277.953125 53.105469 C 277.574219 53.449219 277.207031 53.8125 276.855469 54.183594 C 276.496094 54.558594 276.164062 54.953125 275.824219 55.34375 C 275.773438 55.402344 275.730469 55.449219 275.691406 55.492188 C 275.652344 55.558594 275.605469 55.636719 275.542969 55.742188 C 275.085938 56.488281 274.59375 57.199219 274.171875 57.972656 C 273.917969 58.433594 273.699219 58.910156 273.457031 59.378906 C 273.414062 59.460938 273.378906 59.527344 273.347656 59.585938 C 273.328125 59.652344 273.304688 59.730469 273.273438 59.824219 C 272.945312 60.816406 272.601562 61.796875 272.359375 62.816406 C 272.242188 63.320312 272.144531 63.828125 272.050781 64.339844 C 272.007812 64.582031 271.972656 64.753906 271.949219 64.871094 C 271.949219 64.988281 271.941406 65.167969 271.929688 65.425781 C 271.796875 67.972656 271.820312 70.457031 272.0625 72.992188 C 272.097656 73.28125 272.117188 73.449219 272.128906 73.5625 C 272.191406 73.964844 272.253906 74.367188 272.320312 74.769531 C 272.441406 75.457031 272.570312 76.144531 272.707031 76.828125 C 272.941406 77.972656 273.199219 79.109375 273.480469 80.242188 C 273.578125 80.65625 273.695312 81.0625 273.800781 81.472656 C 269.742188 80.230469 265.691406 78.964844 261.648438 77.671875 C 261.289062 78.273438 260.949219 78.886719 260.605469 79.496094 C 258.796875 70.160156 258.609375 60.640625 263.265625 51.898438 C 268.644531 41.808594 279.507812 35.765625 290.886719 38.566406 C 300.253906 40.871094 308.253906 47.78125 314.058594 55.382812 C 318.578125 52.363281 323.480469 49.902344 328.542969 48.105469 C 334.671875 45.929688 341.144531 45.121094 347.582031 46.09375 C 353.542969 46.992188 358.90625 50.042969 363.371094 54 C 367.558594 57.710938 371.03125 62.34375 373.847656 67.375 C 385.566406 61.414062 399.214844 59.953125 411.46875 66.667969 C 415.472656 68.859375 419.046875 71.832031 422.148438 75.257812 C 426.21875 72.367188 430.710938 70.097656 435.640625 68.726562 C 445.886719 65.867188 457.792969 66.734375 466.890625 72.5625 C 470.898438 75.128906 474.0625 78.445312 476.539062 82.226562 C 479.707031 79.769531 483.15625 77.660156 486.941406 76.050781 C 496.246094 72.09375 507.1875 70.917969 516.171875 76.441406 C 517.417969 77.207031 518.5625 78.066406 519.625 78.996094 C 521.214844 77.636719 522.859375 76.347656 524.609375 75.21875 C 529.1875 72.261719 534.675781 70.234375 540.175781 70.300781 C 545.882812 70.371094 550.933594 72.667969 555.28125 76.234375 C 557.828125 78.320312 559.980469 80.917969 561.875 83.667969 C 564.710938 79.855469 568.183594 76.5625 572.394531 74.324219 C 580.9375 69.785156 590.230469 71.203125 597.660156 77.136719 C 599.582031 78.667969 601.289062 80.433594 602.824219 82.347656 C 605.003906 80.21875 607.558594 78.457031 610.585938 77.25 C 618.265625 74.179688 627.363281 76.273438 633.914062 81.007812 C 641.542969 86.515625 646.496094 94.441406 647.160156 103.929688 C 647.5 108.761719 646.648438 113.679688 645.699219 118.398438 Z M 381.789062 77.253906 C 381.515625 77.378906 381.21875 77.523438 381.789062 77.253906 Z M 419.886719 94.503906 C 419.84375 94.554688 419.800781 94.609375 419.753906 94.664062 C 419.8125 94.59375 419.847656 94.550781 419.886719 94.503906 Z M 616.933594 87.808594 C 617.09375 87.8125 617.214844 87.808594 617.304688 87.804688 C 617.183594 87.804688 617.058594 87.808594 616.9375 87.808594 C 616.9375 87.808594 616.933594 87.808594 616.933594 87.808594 Z M 616.933594 87.808594 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMedicinal flowers and herbs\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProvide maximum nutrients, vitamins and antioxidants to the skin\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c8c88f e-con-full e-flex e-con e-child\" data-id=\"2c8c88f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc057c9 elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"fc057c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><path fill=\"#ffd901\" d=\"M 752.828125 397.445312 C 734.546875 387.023438 712.636719 385.816406 691.480469 385.210938 C 633.308594 383.550781 554.890625 384.757812 487.199219 389.289062 C 554.738281 377.660156 625.300781 365.726562 689.519531 354.550781 C 705.683594 351.679688 722.304688 348.8125 736.359375 340.503906 C 750.5625 332.195312 761.894531 317.242188 761.289062 300.78125 C 760.382812 279.785156 739.683594 263.777344 718.832031 261.058594 C 697.980469 258.339844 677.128906 265.4375 657.332031 272.839844 C 618.953125 287.1875 571.8125 306.671875 525.878906 327.363281 C 568.488281 299.574219 611.25 271.628906 650.988281 245.5 C 664.738281 236.4375 678.636719 227.226562 688.308594 213.933594 C 697.980469 200.644531 702.511719 182.367188 695.257812 167.566406 C 686.042969 148.6875 660.808594 142.191406 640.410156 147.929688 C 620.164062 153.671875 603.84375 168.472656 588.734375 183.121094 C 546.882812 223.601562 492.9375 280.390625 448.816406 331.894531 C 487.800781 275.558594 528.597656 216.804688 565.464844 163.035156 C 574.835938 149.441406 584.203125 135.546875 588.132812 119.6875 C 592.058594 103.828125 589.339844 85.097656 577.101562 74.226562 C 561.386719 60.179688 535.546875 63.804688 518.929688 76.792969 C 502.308594 89.78125 492.789062 109.566406 484.328125 128.898438 C 459.699219 184.632812 429.628906 261.8125 407.871094 328.269531 C 411.347656 255.46875 415.425781 178.289062 418.597656 108.511719 C 419.355469 92.199219 420.109375 75.28125 414.972656 59.726562 C 410.4375 44.015625 398.199219 29.667969 382.03125 26.648438 C 361.332031 22.871094 341.238281 39.636719 333.984375 59.421875 C 326.730469 79.207031 329.148438 101.109375 332.171875 121.953125 C 340.328125 179.648438 354.53125 256.679688 370.398438 322.679688 C 347.734375 258.039062 324.164062 190.371094 302.402344 129.050781 C 296.964844 113.644531 291.222656 97.785156 280.644531 85.25 C 270.070312 72.714844 253.296875 63.953125 237.28125 67.277344 C 216.730469 71.65625 204.339844 94.765625 205.097656 115.761719 C 205.851562 136.753906 216.277344 156.085938 226.855469 174.363281 C 251.332031 216.503906 284.875 269.515625 318.269531 318 C 276.265625 277.066406 233.351562 235.230469 193.765625 196.867188 C 181.980469 185.386719 169.890625 173.757812 154.78125 167.265625 C 139.671875 160.769531 121.085938 160.46875 108.242188 170.585938 C 91.773438 183.726562 91.019531 209.707031 100.992188 228.28125 C 110.960938 246.859375 129.09375 259.398438 146.621094 271.027344 C 195.277344 303.046875 262.363281 343.375 322.347656 375.242188 C 258.886719 349.566406 192.554688 322.378906 132.117188 298.0625 C 116.855469 291.871094 101.292969 285.675781 84.824219 285.375 C 68.351562 285.074219 50.824219 291.71875 42.816406 305.917969 C 32.390625 324.191406 41.609375 348.660156 57.925781 362.101562 C 74.246094 375.542969 95.703125 380.378906 116.25 384.457031 C 156.445312 392.460938 206.757812 400.769531 256.621094 407.414062 C 205.851562 408.621094 154.628906 409.832031 107.035156 411.039062 C 90.566406 411.492188 73.792969 411.945312 58.683594 418.136719 C 43.574219 424.328125 29.972656 437.46875 28.3125 453.78125 C 26.046875 474.777344 44.328125 493.503906 64.574219 499.246094 C 84.824219 504.984375 106.429688 501.058594 127.128906 496.527344 C 184.09375 484.140625 259.792969 464.355469 324.617188 443.8125 C 261.757812 471.453125 195.878906 500 136.195312 526.128906 C 121.238281 532.773438 105.824219 539.570312 94.039062 551.050781 C 82.253906 562.527344 74.851562 579.746094 79.382812 595.457031 C 85.277344 615.695312 109.148438 626.265625 130.152344 624 C 151.15625 621.734375 169.589844 609.804688 186.964844 598.023438 C 228.0625 569.929688 279.738281 531.71875 326.578125 494.109375 C 287.445312 542.59375 246.953125 592.433594 210.082031 638.199219 C 199.808594 651.035156 189.382812 664.175781 184.246094 679.734375 C 179.109375 695.292969 180.46875 714.171875 191.800781 725.953125 C 206.304688 741.207031 232.445312 739.546875 249.972656 727.765625 C 267.5 716.132812 278.378906 696.953125 288.351562 678.375 C 315.851562 627.023438 349.699219 556.488281 375.988281 493.808594 C 356.195312 559.355469 335.34375 627.929688 316.609375 690.308594 C 311.921875 706.015625 307.089844 722.175781 308.296875 738.488281 C 309.503906 754.800781 317.664062 771.714844 332.773438 778.511719 C 351.964844 787.121094 375.535156 775.792969 387.320312 758.273438 C 399.105469 740.90625 402.128906 719.003906 404.246094 698.160156 C 409.382812 649.675781 413.613281 587.148438 415.125 528.242188 C 424.945312 586.089844 434.765625 645.148438 444.132812 699.519531 C 446.855469 715.679688 449.875 732.296875 458.1875 746.339844 C 466.496094 760.539062 481.457031 771.867188 497.773438 771.261719 C 518.777344 770.355469 534.792969 749.816406 537.664062 728.972656 C 540.535156 708.128906 533.433594 687.285156 526.03125 667.5 C 510.464844 625.664062 489.011719 573.707031 466.347656 524.164062 C 493.242188 572.648438 520.4375 621.734375 545.824219 667.199219 C 553.832031 681.546875 562.140625 696.199219 574.683594 706.769531 C 587.222656 717.34375 605.203125 723.234375 620.316406 717.039062 C 639.957031 709.1875 648.117188 684.417969 643.886719 663.875 C 639.65625 643.183594 626.054688 625.964844 612.457031 609.804688 C 575.136719 565.097656 522.402344 507.25 474.203125 459.371094 C 527.539062 502.265625 583.296875 547.273438 634.214844 588.054688 C 647.058594 598.324219 660.203125 608.746094 675.769531 613.882812 C 691.332031 619.015625 710.21875 617.65625 722.003906 606.179688 C 737.265625 591.527344 735.453125 565.550781 723.664062 548.03125 C 711.878906 530.507812 692.84375 519.632812 674.257812 509.816406 C 631.195312 487.011719 574.683594 459.519531 520.742188 435.960938 C 578.007812 448.648438 636.480469 461.484375 690.425781 473.265625 C 706.441406 476.738281 722.910156 480.214844 739.078125 477.796875 C 755.246094 475.378906 771.5625 465.863281 777.003906 450.460938 C 784.257812 430.523438 771.109375 407.867188 752.828125 397.445312 Z M 416.785156 425.6875 L 399.558594 429.464844 L 395.480469 428.40625 C 395.179688 429.617188 394.726562 430.671875 394.421875 431.882812 L 387.019531 416.929688 C 385.207031 417.683594 383.394531 418.4375 381.730469 419.34375 L 381.277344 413.605469 L 385.660156 401.070312 C 383.847656 400.316406 382.03125 399.558594 380.21875 398.957031 L 389.132812 388.835938 L 393.0625 387.324219 C 392.457031 385.511719 391.703125 383.699219 391.097656 381.738281 L 399.863281 381.738281 L 410.441406 388.230469 C 411.496094 386.570312 412.707031 385.058594 413.761719 383.398438 L 417.238281 388.082031 L 420.109375 401.070312 C 422.074219 400.769531 423.886719 400.464844 425.851562 400.011719 L 423.585938 413.304688 L 421.167969 416.625 C 422.679688 417.835938 424.1875 419.042969 425.699219 420.25 Z M 416.785156 425.6875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#f47c06\" d=\"M 399.863281 315.128906 C 403.035156 336.878906 403.640625 359.535156 401.375 381.585938 L 385.808594 381.585938 C 384.753906 377.960938 383.695312 374.035156 382.636719 370.257812 C 383.695312 352.738281 383.089844 335.21875 380.523438 318 C 379.164062 309.089844 377.347656 299.875 375.535156 290.964844 C 371.605469 271.480469 367.375 251.390625 368.28125 230.398438 C 368.734375 218.164062 370.851562 206.382812 372.96875 194.902344 C 374.328125 187.050781 375.6875 179.648438 376.59375 172.25 C 378.707031 153.972656 377.652344 134.789062 373.722656 116.96875 C 371.910156 109.113281 369.644531 101.410156 367.226562 93.40625 C 364.203125 83.136719 360.878906 72.414062 358.914062 61.234375 C 357.101562 50.8125 356.800781 40.84375 357.707031 31.480469 C 364.050781 27.855469 371.152344 25.894531 378.40625 26.347656 C 376.441406 35.40625 376.292969 46.28125 378.40625 57.761719 C 380.21875 67.882812 383.089844 77.398438 386.113281 87.667969 C 388.53125 95.671875 391.097656 104.128906 392.910156 112.738281 C 397.292969 132.675781 398.351562 154.125 396.085938 174.515625 C 395.179688 182.667969 393.667969 190.824219 392.308594 198.527344 C 390.191406 209.855469 388.378906 220.429688 387.925781 231.304688 C 387.171875 249.730469 390.949219 267.855469 394.875 287.035156 C 396.539062 296.097656 398.503906 305.613281 399.863281 315.128906 Z M 230.480469 386.570312 C 249.972656 394.273438 270.371094 396.992188 290.015625 399.710938 C 298.929688 400.917969 308.296875 402.128906 317.210938 403.941406 C 334.136719 407.261719 351.058594 412.398438 367.226562 419.195312 C 371.304688 419.496094 375.234375 419.648438 379.011719 419.949219 L 384.148438 405.148438 C 364.050781 395.785156 342.445312 388.683594 320.839844 384.605469 C 311.46875 382.792969 301.800781 381.433594 292.582031 380.226562 C 273.242188 377.660156 254.808594 375.089844 237.582031 368.292969 C 227.460938 364.367188 218.089844 358.929688 208.117188 353.34375 C 201.167969 349.414062 194.066406 345.335938 186.664062 341.710938 C 168.078125 332.800781 147.527344 326.757812 127.28125 324.34375 C 118.519531 323.285156 109.753906 322.832031 101.445312 322.53125 C 90.714844 322.078125 80.742188 321.625 70.621094 319.960938 C 59.136719 318 48.863281 314.375 41.003906 309.542969 C 38.132812 316.1875 37.679688 323.585938 38.890625 330.835938 C 47.351562 334.765625 56.871094 337.785156 67.296875 339.445312 C 78.476562 341.257812 89.65625 341.863281 100.386719 342.316406 C 108.847656 342.769531 116.855469 343.070312 124.863281 343.976562 C 142.996094 346.09375 161.429688 351.53125 178.050781 359.535156 C 184.851562 362.859375 191.347656 366.484375 198.296875 370.410156 C 208.722656 376.148438 219.148438 382.039062 230.480469 386.570312 Z M 597.953125 652.546875 C 591.605469 646.960938 585.714844 641.671875 579.972656 635.933594 C 567.128906 622.792969 556.25 607.085938 548.390625 590.472656 C 545.21875 583.675781 542.347656 576.574219 539.476562 569.175781 C 535.246094 558.300781 530.863281 547.125 524.820312 536.550781 C 514.546875 518.425781 500.34375 503.472656 486.742188 488.972656 C 480.550781 482.328125 474.050781 475.53125 468.160156 468.582031 C 456.976562 455.445312 447.003906 440.792969 438.847656 425.386719 C 435.824219 422.667969 432.953125 419.949219 430.082031 417.382812 L 416.785156 425.6875 C 426.605469 445.625 438.847656 464.65625 453.199219 481.421875 C 459.394531 488.824219 466.042969 495.769531 472.539062 502.566406 C 485.988281 516.765625 498.679688 530.207031 507.898438 546.367188 C 513.1875 555.730469 517.265625 565.851562 521.34375 576.574219 C 524.214844 583.976562 527.238281 591.527344 530.714844 599.082031 C 539.476562 617.65625 551.714844 635.328125 566.070312 649.980469 C 572.265625 656.324219 578.761719 662.0625 585.109375 667.652344 C 593.117188 674.75 600.671875 681.394531 607.472656 688.949219 C 615.175781 697.707031 620.917969 706.921875 623.941406 715.679688 C 630.4375 712.207031 635.425781 706.921875 638.898438 700.425781 C 634.820312 692.121094 629.230469 683.8125 622.128906 675.808594 C 614.421875 667.046875 606.113281 659.644531 597.953125 652.546875 Z M 751.46875 277.972656 C 742.25 279.03125 732.582031 281.597656 722.757812 285.675781 C 712.183594 290.058594 702.511719 295.496094 693.144531 300.628906 C 685.742188 304.707031 678.789062 308.636719 671.539062 312.109375 C 654.917969 319.8125 636.480469 324.945312 618.199219 326.910156 C 610.644531 327.664062 603.089844 327.96875 595.234375 328.269531 C 583.597656 328.722656 571.511719 329.175781 559.574219 331.289062 C 539.023438 335.066406 520.289062 343.375 502.003906 351.53125 C 493.695312 355.304688 485.234375 359.082031 476.621094 362.253906 C 460.453125 368.445312 443.378906 372.976562 426.152344 375.695312 C 422.679688 377.660156 419.050781 379.472656 415.726562 381.285156 L 419.050781 396.539062 C 441.113281 393.972656 463.171875 388.535156 483.722656 380.679688 C 492.636719 377.207031 501.550781 373.277344 510.011719 369.503906 C 527.84375 361.5 544.765625 353.945312 563.046875 350.625 C 573.777344 348.660156 584.503906 348.207031 595.988281 347.90625 C 603.84375 347.601562 612.15625 347.300781 620.316406 346.394531 C 640.863281 344.28125 661.414062 338.539062 680 329.929688 C 688.007812 326.15625 695.5625 321.925781 702.964844 317.847656 C 712.332031 312.714844 721.097656 307.730469 730.464844 303.800781 C 741.195312 299.421875 751.921875 297.15625 761.136719 297.003906 C 759.777344 289.90625 756.304688 283.410156 751.46875 277.972656 Z M 347.429688 482.480469 C 342.898438 490.9375 338.96875 499.699219 335.042969 508.304688 C 326.882812 526.128906 319.175781 542.894531 307.691406 557.394531 C 300.894531 565.851562 293.035156 573.402344 284.726562 581.257812 C 278.984375 586.695312 273.089844 592.285156 267.5 598.476562 C 253.597656 613.578125 241.8125 631.554688 233.65625 650.28125 C 230.179688 658.285156 227.15625 666.59375 224.4375 674.449219 C 220.8125 684.566406 217.488281 693.933594 212.953125 703.144531 C 207.816406 713.566406 201.320312 722.328125 194.367188 728.519531 C 199.960938 733.203125 206.910156 735.769531 214.164062 736.675781 C 220.359375 729.726562 225.949219 721.421875 230.632812 711.90625 C 235.617188 701.632812 239.394531 691.214844 243.023438 681.09375 C 245.894531 673.089844 248.460938 665.6875 251.785156 658.285156 C 259.191406 641.523438 269.617188 625.511719 282.15625 611.917969 C 287.292969 606.328125 292.734375 601.195312 298.476562 595.757812 C 306.9375 587.753906 315.699219 579.445312 323.253906 569.929688 C 336.25 553.617188 344.863281 534.890625 353.023438 516.765625 C 356.800781 508.457031 360.726562 500 364.957031 491.996094 C 372.96875 476.738281 382.789062 462.089844 393.96875 448.648438 C 395.328125 444.871094 396.691406 441.246094 398.050781 437.621094 L 385.355469 428.40625 C 370.699219 444.417969 357.707031 462.996094 347.429688 482.480469 Z M 347.429688 482.480469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#fffa00\" d=\"M 95.550781 192.035156 C 97.0625 184.933594 100.234375 178.289062 105.523438 173.15625 C 110.960938 180.554688 119.121094 187.804688 128.945312 193.996094 C 137.707031 199.285156 146.773438 203.511719 156.445312 208.042969 C 164.148438 211.519531 172.007812 215.292969 179.710938 219.523438 C 197.542969 229.492188 214.3125 242.78125 228.214844 258.039062 C 233.804688 264.230469 238.792969 270.574219 243.628906 276.765625 C 250.730469 285.828125 257.378906 294.285156 265.234375 301.6875 C 278.683594 314.527344 294.699219 323.738281 311.621094 333.40625 C 319.78125 338.085938 328.089844 342.921875 336.097656 348.054688 C 344.105469 353.191406 351.8125 358.929688 359.21875 364.972656 C 355.136719 355.609375 350.605469 346.394531 345.316406 337.785156 C 340.632812 329.929688 335.496094 322.226562 330.507812 314.675781 C 319.476562 298.214844 307.996094 280.996094 300.894531 261.359375 C 296.664062 249.882812 294.246094 238.101562 291.828125 226.621094 C 290.164062 218.917969 288.652344 211.519531 286.691406 204.269531 C 281.703125 186.445312 273.542969 169.078125 263.269531 154.125 C 258.738281 147.476562 253.75 141.285156 248.460938 134.640625 C 241.664062 126.183594 234.710938 117.574219 228.667969 107.90625 C 223.078125 98.996094 218.996094 89.78125 216.277344 80.871094 C 220.8125 75.132812 226.703125 70.601562 233.503906 68.335938 C 235.015625 77.398438 239.09375 87.515625 245.289062 97.484375 C 250.730469 106.09375 257.074219 113.949219 263.722656 122.253906 C 269.011719 128.75 274.449219 135.546875 279.4375 142.796875 C 291.070312 159.5625 300.136719 179.042969 305.726562 198.832031 C 307.996094 206.835938 309.65625 214.839844 311.167969 222.542969 C 313.433594 233.71875 315.699219 244.292969 319.476562 254.5625 C 325.824219 271.933594 336.097656 287.339844 346.976562 303.652344 C 352.117188 311.355469 357.554688 319.507812 362.390625 327.664062 C 373.570312 346.546875 382.636719 367.386719 388.832031 388.683594 L 385.960938 389.894531 C 386.265625 390.195312 386.71875 390.648438 387.019531 390.949219 L 376.746094 402.730469 C 373.269531 401.070312 369.644531 399.410156 366.015625 397.597656 C 353.625 385.210938 339.875 374.035156 325.371094 364.671875 C 317.816406 359.6875 309.65625 355.003906 301.800781 350.625 C 284.574219 340.65625 266.746094 330.535156 251.636719 316.035156 C 242.71875 307.578125 235.316406 298.0625 228.0625 289 C 223.078125 282.808594 218.542969 276.917969 213.40625 271.175781 C 201.015625 257.433594 186.058594 245.5 170.042969 236.742188 C 162.941406 232.8125 155.6875 229.492188 147.980469 226.015625 C 138.160156 221.488281 128.035156 216.804688 118.367188 210.914062 C 109.601562 205.175781 101.746094 198.832031 95.550781 192.035156 Z M 387.171875 442.757812 C 390.191406 440.039062 393.0625 437.46875 395.933594 434.75 L 388.984375 420.703125 C 386.566406 421.609375 384.300781 422.515625 382.03125 423.421875 L 380.976562 408.773438 C 358.765625 408.167969 336.25 410.285156 314.792969 415.117188 C 305.425781 417.230469 296.058594 419.796875 287.144531 422.367188 C 268.257812 427.652344 250.578125 432.636719 231.992188 433.390625 C 221.113281 433.695312 210.386719 432.636719 199.054688 431.429688 C 191.195312 430.523438 183.035156 429.765625 174.726562 429.3125 C 154.175781 428.40625 132.871094 431.125 113.230469 437.015625 C 104.769531 439.585938 96.609375 442.605469 88.75 445.625 C 78.777344 449.402344 69.410156 453.027344 59.4375 455.445312 C 48.105469 458.3125 37.226562 458.917969 28.160156 457.710938 C 28.160156 464.957031 30.730469 471.90625 34.808594 477.949219 C 44.027344 478.25 54 477.191406 64.273438 474.625 C 75.304688 471.90625 85.730469 467.828125 95.851562 464.050781 C 103.710938 461.03125 111.265625 458.164062 118.972656 455.898438 C 136.5 450.609375 155.535156 448.34375 173.972656 449.101562 C 181.527344 449.402344 189.082031 450.15625 196.9375 451.0625 C 208.570312 452.273438 220.507812 453.632812 232.746094 453.179688 C 253.597656 452.421875 273.394531 446.835938 292.582031 441.546875 C 301.347656 439.132812 310.414062 436.5625 319.175781 434.601562 C 335.949219 430.824219 353.324219 428.859375 370.699219 428.710938 C 356.496094 435.203125 342.898438 443.058594 330.207031 451.820312 C 322.347656 457.257812 314.644531 463.296875 307.390625 468.886719 C 291.976562 480.96875 277.320312 492.296875 260.398438 499.847656 C 250.425781 504.226562 240.152344 507.25 229.121094 510.421875 C 221.566406 512.535156 213.558594 514.800781 205.851562 517.671875 C 186.511719 524.617188 167.777344 535.039062 151.757812 547.878906 C 144.808594 553.464844 138.460938 559.355469 132.269531 565.097656 C 124.410156 572.347656 117.15625 579.292969 108.847656 585.183594 C 99.480469 592.132812 89.65625 596.816406 80.742188 599.078125 C 83.613281 605.875 88.449219 611.3125 94.492188 615.390625 C 103.105469 612.21875 112.019531 607.386719 120.632812 601.195312 C 129.851562 594.550781 138.007812 586.847656 145.867188 579.597656 C 152.0625 573.855469 157.804688 568.417969 164.148438 563.285156 C 178.351562 551.804688 195.125 542.441406 212.5 536.25 C 219.601562 533.679688 226.855469 531.566406 234.5625 529.453125 C 245.742188 526.28125 257.375 522.957031 268.558594 517.972656 C 287.597656 509.515625 303.914062 496.828125 319.628906 484.59375 C 326.730469 479.003906 334.136719 473.265625 341.691406 468.128906 C 355.589844 458.011719 371.003906 449.554688 387.171875 442.757812 Z M 776.703125 425.386719 C 767.785156 422.96875 757.8125 421.609375 747.238281 421.609375 C 735.90625 421.609375 724.722656 422.96875 714.148438 424.328125 C 705.835938 425.386719 697.828125 426.292969 689.820312 426.746094 C 671.535156 427.652344 652.5 425.386719 634.820312 420.25 C 627.566406 418.136719 620.464844 415.570312 613.0625 412.851562 C 602.183594 408.925781 590.851562 404.847656 578.761719 402.277344 C 558.363281 398.050781 537.816406 398.652344 517.871094 399.410156 C 508.804688 399.710938 499.4375 400.011719 490.371094 399.863281 C 473.144531 399.558594 455.464844 397.292969 438.542969 393.214844 C 434.613281 393.667969 430.535156 394.121094 426.757812 394.574219 L 424.1875 409.980469 C 424.644531 410.132812 425.097656 410.285156 425.699219 410.285156 L 423.886719 412.699219 C 440.507812 427.5 459.09375 440.339844 478.585938 450.609375 C 487.046875 454.992188 495.960938 459.070312 504.421875 462.84375 C 522.253906 471 539.023438 478.550781 553.679688 490.03125 C 562.140625 496.675781 569.695312 504.53125 577.554688 512.835938 C 582.992188 518.578125 588.734375 524.46875 594.777344 530.054688 C 610.039062 543.953125 627.871094 555.730469 646.605469 563.886719 C 654.613281 567.363281 662.925781 570.230469 670.933594 573.101562 C 681.054688 576.574219 690.574219 580.050781 699.640625 584.429688 C 710.066406 589.566406 718.832031 596.058594 725.027344 603.007812 C 729.710938 597.417969 732.277344 590.472656 733.183594 583.222656 C 726.234375 577.027344 717.925781 571.441406 708.40625 566.757812 C 698.128906 561.773438 687.703125 557.996094 677.429688 554.523438 C 669.421875 551.65625 661.867188 549.085938 654.464844 545.914062 C 637.691406 538.664062 621.675781 528.09375 608.074219 515.707031 C 602.484375 510.570312 597.347656 505.136719 591.757812 499.394531 C 583.75 490.9375 575.4375 482.328125 565.769531 474.625 C 549.296875 461.636719 530.5625 453.179688 512.582031 445.023438 C 504.269531 441.246094 495.808594 437.320312 487.800781 433.242188 C 478.886719 428.558594 470.125 423.273438 461.660156 417.382812 C 471.179688 418.589844 480.699219 419.34375 490.21875 419.496094 C 499.890625 419.648438 509.410156 419.34375 518.777344 419.042969 C 538.269531 418.4375 556.855469 417.683594 574.984375 421.460938 C 585.5625 423.726562 595.835938 427.351562 606.566406 431.277344 C 613.96875 433.996094 621.675781 436.714844 629.683594 439.132812 C 649.476562 444.871094 670.78125 447.289062 691.179688 446.382812 C 699.945312 445.929688 708.707031 444.871094 717.019531 443.8125 C 727.59375 442.453125 737.566406 441.246094 747.839844 441.246094 C 759.476562 441.246094 770.203125 443.058594 778.816406 446.53125 C 779.875 439.585938 779.117188 432.335938 776.703125 425.386719 Z M 411.042969 379.773438 L 419.65625 391.707031 C 438.847656 380.527344 456.828125 366.785156 472.539062 351.378906 C 479.339844 344.582031 485.835938 337.484375 492.183594 330.6875 C 505.328125 316.1875 517.871094 302.59375 533.28125 292.324219 C 542.347656 286.28125 552.019531 281.597656 562.445312 276.613281 C 569.546875 273.140625 576.949219 269.667969 584.203125 265.589844 C 602.183594 255.46875 618.804688 242.027344 632.402344 226.621094 C 638.296875 219.976562 643.582031 213.027344 648.570312 206.382812 C 655.066406 197.925781 661.109375 189.917969 668.214844 182.519531 C 676.371094 174.210938 685.136719 167.867188 693.597656 164.09375 C 689.667969 157.898438 683.925781 153.367188 677.277344 150.347656 C 669.269531 155.03125 661.414062 161.222656 654.007812 168.773438 C 646.152344 176.929688 639.351562 185.839844 632.855469 194.300781 C 627.71875 200.945312 622.882812 207.289062 617.59375 213.332031 C 605.507812 227.074219 590.546875 239.007812 574.53125 248.070312 C 567.882812 251.84375 561.234375 255.015625 553.984375 258.492188 C 543.558594 263.476562 532.679688 268.761719 522.402344 275.558594 C 505.027344 287.1875 491.125 302.292969 477.679688 317.09375 C 471.632812 323.738281 465.289062 330.6875 458.789062 337.03125 C 446.550781 349.113281 432.800781 359.835938 418.144531 369.199219 C 426.757812 356.210938 434.3125 342.46875 440.355469 328.269531 C 444.132812 319.507812 447.457031 310.449219 450.78125 301.6875 C 457.582031 283.261719 463.929688 266.042969 474.355469 250.636719 C 480.398438 241.574219 487.652344 233.570312 495.355469 225.109375 C 500.644531 219.222656 506.234375 213.179688 511.222656 206.683594 C 524.066406 190.523438 534.339844 171.796875 541.140625 152.460938 C 544.011719 144.15625 546.429688 135.695312 548.542969 127.539062 C 551.261719 117.269531 553.984375 107.453125 557.761719 98.089844 C 562.140625 87.214844 567.882812 78.152344 574.382812 71.507812 C 568.488281 67.277344 561.386719 65.164062 554.132812 64.859375 C 548.390625 72.109375 543.40625 80.871094 539.476562 90.6875 C 535.246094 101.261719 532.222656 111.984375 529.503906 122.40625 C 527.238281 130.5625 525.273438 138.265625 522.554688 145.816406 C 516.511719 163.035156 507.140625 179.800781 495.808594 194.300781 C 491.125 200.191406 485.988281 205.777344 480.699219 211.667969 C 472.84375 220.277344 464.835938 229.1875 457.882812 239.308594 C 446.097656 256.679688 438.996094 275.859375 432.199219 294.589844 C 429.023438 303.046875 425.851562 311.957031 422.226562 320.265625 C 415.425781 336.125 406.660156 351.53125 396.539062 365.726562 C 395.480469 369.652344 394.273438 373.429688 393.214844 377.054688 L 406.511719 385.363281 C 408.023438 383.699219 409.53125 381.738281 411.042969 379.773438 Z M 498.078125 702.992188 C 493.996094 695.59375 490.066406 688.644531 486.742188 681.246094 C 479.039062 664.628906 474.050781 646.203125 472.085938 627.777344 C 471.332031 620.226562 471.03125 612.671875 470.726562 604.820312 C 470.273438 593.191406 469.820312 581.105469 467.707031 569.175781 C 464.078125 548.632812 455.617188 529.753906 447.609375 511.628906 C 443.984375 503.324219 440.054688 494.714844 436.882812 486.253906 C 430.6875 470.09375 426.304688 453.027344 423.585938 435.65625 C 421.773438 432.183594 419.808594 428.558594 417.996094 425.234375 L 402.734375 428.558594 C 402.734375 429.011719 402.882812 429.464844 402.882812 430.070312 L 399.863281 429.3125 C 392.308594 450.15625 387.320312 472.207031 385.207031 494.261719 C 384.300781 503.777344 383.847656 513.441406 383.542969 522.804688 C 382.789062 542.289062 381.882812 560.867188 376.746094 578.539062 C 373.722656 588.960938 369.191406 598.777344 364.503906 609.199219 C 361.179688 616.449219 357.855469 623.851562 354.988281 631.554688 C 347.734375 650.886719 343.652344 671.878906 343.050781 692.269531 C 342.746094 701.03125 343.199219 709.789062 343.652344 718.25 C 344.105469 728.972656 344.5625 738.941406 343.804688 749.210938 C 342.898438 760.839844 340.179688 771.261719 336.097656 779.570312 C 343.050781 781.835938 350.453125 781.535156 357.402344 779.722656 C 360.578125 770.960938 362.691406 761.144531 363.449219 750.570312 C 364.203125 739.242188 363.75 728.066406 363.296875 717.34375 C 362.84375 708.882812 362.542969 700.878906 362.691406 692.875 C 363.144531 674.597656 366.921875 655.871094 373.421875 638.5 C 376.140625 631.402344 379.164062 624.605469 382.484375 617.355469 C 387.320312 606.78125 392.308594 595.757812 395.632812 583.976562 C 401.523438 563.886719 402.28125 543.347656 403.1875 523.5625 C 403.640625 514.5 403.941406 505.136719 404.847656 496.074219 C 405.753906 485.953125 407.417969 475.984375 409.683594 466.015625 C 412.101562 475.230469 414.972656 484.441406 418.296875 493.203125 C 421.773438 502.113281 425.699219 511.023438 429.476562 519.484375 C 437.484375 537.304688 444.890625 554.222656 448.214844 572.496094 C 450.179688 583.222656 450.480469 593.945312 450.933594 605.421875 C 451.234375 613.277344 451.539062 621.585938 452.292969 629.742188 C 454.410156 650.28125 460.152344 670.824219 468.613281 689.402344 C 472.390625 697.40625 476.621094 704.957031 480.699219 712.359375 C 485.835938 721.722656 490.824219 730.484375 494.601562 740 C 498.984375 750.722656 501.25 761.445312 501.25 770.660156 C 508.503906 769.601562 515 766.128906 520.4375 761.292969 C 519.382812 752.082031 516.8125 742.414062 512.882812 732.597656 C 508.652344 722.175781 503.363281 712.359375 498.078125 702.992188 Z M 498.078125 702.992188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#00d4d2\" d=\"M 476.773438 400.917969 C 476.773438 442.453125 443.078125 476.136719 401.523438 476.136719 C 359.972656 476.136719 326.277344 442.453125 326.277344 400.917969 C 326.277344 359.382812 359.972656 325.703125 401.523438 325.703125 C 443.078125 325.703125 476.773438 359.382812 476.773438 400.917969 Z M 476.773438 400.917969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#aaf2c7\" d=\"M 347.28125 424.480469 C 345.769531 424.933594 343.804688 424.632812 342.597656 423.875 C 341.238281 423.121094 340.179688 421.761719 339.726562 420.25 C 338.367188 415.71875 337.003906 411.191406 335.644531 406.660156 C 335.191406 404.996094 335.496094 403.335938 336.25 401.976562 C 337.003906 400.617188 338.515625 399.558594 339.875 399.105469 C 341.386719 398.652344 343.351562 398.957031 344.5625 399.710938 C 345.921875 400.464844 346.976562 401.824219 347.429688 403.335938 C 348.792969 407.867188 350.152344 412.398438 351.511719 416.929688 C 351.964844 418.589844 351.664062 420.25 350.90625 421.609375 C 350.152344 422.96875 348.792969 423.875 347.28125 424.480469 Z M 361.9375 438.226562 C 360.878906 436.867188 359.972656 435.355469 359.066406 433.84375 C 358.3125 432.484375 356.800781 431.429688 355.441406 430.976562 C 353.929688 430.523438 351.964844 430.824219 350.753906 431.578125 C 349.394531 432.484375 348.339844 433.695312 347.886719 435.203125 C 347.582031 436.867188 347.734375 438.527344 348.488281 439.886719 C 349.847656 442.152344 351.359375 444.265625 352.871094 446.382812 C 354.230469 448.042969 355.589844 449.703125 357.253906 451.214844 C 358.460938 452.273438 359.972656 453.027344 361.632812 453.027344 C 363.144531 453.027344 364.957031 452.421875 366.015625 451.214844 C 367.074219 450.007812 367.828125 448.496094 367.828125 446.835938 C 367.828125 445.171875 367.226562 443.664062 366.015625 442.453125 C 364.355469 441.246094 363.144531 439.886719 361.9375 438.226562 Z M 399.257812 457.859375 C 397.746094 457.859375 396.234375 457.710938 394.875 457.558594 C 392.308594 457.105469 389.738281 456.652344 387.320312 455.898438 C 385.960938 455.445312 384.601562 454.992188 383.242188 454.386719 C 382.941406 454.234375 382.789062 454.234375 382.484375 454.085938 C 381.730469 453.78125 381.125 453.480469 380.371094 453.027344 C 377.5 451.515625 373.570312 452.121094 371.910156 455.292969 C 370.398438 458.160156 371.003906 462.089844 374.175781 463.75 C 382.03125 467.828125 390.496094 469.941406 399.410156 470.246094 C 402.582031 470.394531 405.753906 467.375 405.605469 464.050781 C 405.300781 460.578125 402.734375 458.011719 399.257812 457.859375 Z M 434.917969 444.265625 C 433.253906 444.417969 431.894531 445.023438 430.535156 446.078125 C 430.234375 446.382812 429.929688 446.53125 429.628906 446.835938 C 427.816406 448.195312 425.699219 449.402344 423.585938 450.308594 C 421.621094 451.0625 419.65625 451.667969 417.542969 452.121094 C 416.03125 452.421875 414.519531 453.78125 413.914062 454.992188 C 413.160156 456.351562 412.855469 458.3125 413.308594 459.671875 C 413.761719 461.183594 414.671875 462.542969 416.179688 463.296875 C 417.691406 464.050781 419.203125 464.203125 420.867188 463.902344 C 427.664062 462.542969 434.011719 459.21875 439.300781 454.6875 C 440.507812 453.632812 441.113281 451.820312 441.113281 450.308594 C 441.113281 448.796875 440.507812 446.984375 439.300781 445.929688 C 438.089844 445.023438 436.578125 444.265625 434.917969 444.265625 Z M 463.929688 419.648438 C 463.171875 418.4375 461.660156 417.078125 460.300781 416.777344 C 458.789062 416.476562 456.976562 416.476562 455.617188 417.382812 C 455.164062 417.683594 454.710938 417.984375 454.410156 418.289062 C 453.804688 418.890625 453.351562 419.648438 453.050781 420.554688 C 452.445312 421.761719 451.839844 422.96875 450.933594 424.179688 C 450.027344 425.234375 449.121094 426.292969 447.910156 427.199219 C 447.761719 427.199219 447.761719 427.351562 447.609375 427.351562 C 446.25 428.257812 445.191406 429.464844 444.738281 430.976562 C 444.285156 432.484375 444.585938 434.449219 445.34375 435.65625 C 446.25 437.015625 447.457031 438.074219 448.96875 438.527344 C 450.480469 438.828125 452.292969 438.828125 453.652344 437.921875 C 455.921875 436.414062 458.035156 434.601562 459.699219 432.484375 C 460.753906 431.277344 461.660156 430.070312 462.417969 428.710938 C 463.171875 427.351562 463.929688 425.839844 464.382812 424.328125 C 464.683594 423.574219 464.683594 422.667969 464.53125 421.914062 C 464.683594 421.15625 464.382812 420.402344 463.929688 419.648438 Z M 463.171875 380.378906 C 461.660156 377.507812 457.429688 376.449219 454.710938 378.113281 C 451.839844 379.925781 450.933594 383.550781 452.445312 386.570312 C 452.898438 387.324219 453.199219 388.082031 453.503906 388.835938 C 454.410156 391.402344 455.164062 393.972656 455.617188 396.539062 C 455.617188 397.144531 455.769531 397.746094 455.769531 398.351562 C 455.921875 400.011719 456.375 401.523438 457.582031 402.730469 C 458.640625 403.789062 460.453125 404.542969 461.964844 404.542969 C 463.625 404.542969 465.136719 403.941406 466.347656 402.730469 C 467.402344 401.523438 468.308594 400.011719 468.160156 398.351562 C 467.855469 392.160156 466.195312 385.964844 463.171875 380.378906 Z M 427.511719 357.117188 C 428.421875 357.421875 429.476562 357.722656 430.382812 358.023438 C 432.046875 358.78125 433.707031 359.835938 435.371094 360.894531 C 437.183594 362.253906 438.695312 363.914062 440.054688 365.726562 C 440.960938 366.933594 443.078125 367.539062 444.4375 367.539062 C 445.949219 367.539062 447.761719 366.933594 448.816406 365.726562 C 449.875 364.519531 450.632812 363.007812 450.632812 361.347656 C 450.632812 360.742188 450.480469 360.289062 450.480469 359.6875 C 450.179688 358.628906 449.726562 357.722656 448.96875 356.96875 C 444.585938 351.226562 437.9375 347.148438 430.988281 345.1875 C 429.476562 344.734375 427.664062 345.035156 426.304688 345.789062 C 425.097656 346.546875 423.734375 348.054688 423.433594 349.414062 C 422.527344 352.738281 424.1875 356.210938 427.511719 357.117188 Z M 388.378906 351.679688 C 389.738281 352.4375 391.550781 352.890625 393.0625 352.285156 C 395.480469 351.378906 398.050781 350.625 400.617188 350.320312 C 403.640625 350.019531 406.660156 350.019531 409.683594 350.472656 C 409.382812 350.472656 409.078125 350.320312 408.625 350.320312 C 410.136719 350.472656 411.648438 350.472656 413.007812 349.71875 C 414.21875 348.960938 415.578125 347.453125 415.878906 346.09375 C 416.179688 344.582031 416.179688 342.769531 415.273438 341.410156 C 414.519531 340.203125 413.160156 338.84375 411.648438 338.539062 C 408.023438 338.085938 404.246094 337.785156 400.617188 338.238281 C 396.839844 338.691406 393.367188 339.296875 389.890625 340.65625 C 388.378906 341.257812 387.019531 342.015625 386.265625 343.523438 C 385.507812 344.882812 385.207031 346.847656 385.660156 348.207031 C 385.960938 349.414062 386.867188 350.925781 388.378906 351.679688 Z M 359.21875 378.714844 C 362.542969 379.472656 365.867188 377.808594 366.773438 374.488281 C 367.074219 373.582031 367.375 372.824219 367.679688 371.917969 C 368.433594 370.410156 369.339844 368.898438 370.246094 367.386719 C 371.457031 365.878906 372.664062 364.667969 374.175781 363.460938 C 374.78125 363.007812 375.234375 362.707031 375.839844 362.253906 C 377.199219 361.5 378.253906 360.140625 378.707031 358.628906 C 379.164062 357.117188 378.859375 355.15625 378.105469 353.945312 C 376.292969 351.226562 372.664062 349.867188 369.644531 351.679688 C 362.542969 356.0625 357.101562 363.160156 354.835938 371.164062 C 354.078125 374.335938 356.042969 378.113281 359.21875 378.714844 Z M 368.433594 406.507812 C 367.980469 405.449219 367.828125 404.394531 367.527344 403.335938 C 367.375 402.277344 367.375 401.222656 367.527344 400.011719 C 367.828125 398.804688 368.132812 397.597656 368.585938 396.386719 C 369.191406 395.027344 369.339844 393.667969 369.039062 392.160156 C 368.585938 390.800781 367.527344 389.136719 366.167969 388.535156 C 364.808594 387.777344 362.996094 387.324219 361.484375 387.929688 C 359.972656 388.382812 358.460938 389.289062 357.855469 390.800781 C 356.195312 394.425781 355.136719 398.351562 355.289062 402.277344 C 355.441406 406.355469 356.496094 410.132812 358.460938 413.605469 C 359.972656 416.476562 364.203125 417.53125 366.921875 415.871094 C 369.792969 414.058594 370.851562 410.433594 369.191406 407.414062 C 368.734375 407.261719 368.585938 406.808594 368.433594 406.507812 Z M 388.226562 427.5 C 386.113281 425.839844 383.996094 424.027344 382.183594 421.914062 C 381.125 420.855469 379.3125 420.101562 377.800781 420.101562 C 376.292969 420.101562 374.476562 420.703125 373.421875 421.914062 C 371.152344 424.480469 371.003906 428.105469 373.421875 430.671875 C 377.652344 435.054688 382.484375 438.980469 387.773438 442 C 389.132812 442.757812 390.949219 443.058594 392.457031 442.605469 C 393.820312 442.152344 395.480469 441.09375 396.085938 439.734375 C 397.597656 436.867188 396.839844 432.9375 393.820312 431.277344 C 392.003906 430.21875 390.042969 428.859375 388.226562 427.5 Z M 422.375 435.808594 C 423.734375 434.902344 424.792969 433.695312 425.246094 432.183594 C 425.550781 431.429688 425.550781 430.523438 425.398438 429.765625 C 425.398438 429.011719 425.097656 428.257812 424.644531 427.5 C 423.734375 426.140625 422.527344 425.085938 421.015625 424.632812 C 419.355469 424.328125 417.691406 424.328125 416.332031 425.234375 C 415.273438 425.992188 414.066406 426.59375 412.855469 427.046875 C 411.949219 427.351562 410.894531 427.804688 409.984375 427.953125 C 408.476562 428.40625 407.117188 429.464844 406.359375 430.824219 C 405.90625 431.578125 405.605469 432.335938 405.605469 433.089844 C 405.453125 433.84375 405.453125 434.75 405.753906 435.507812 C 406.207031 437.015625 407.117188 438.375 408.625 439.132812 C 410.136719 439.886719 411.800781 440.1875 413.308594 439.734375 C 415.125 439.28125 416.9375 438.527344 418.75 437.773438 C 419.808594 437.320312 421.167969 436.5625 422.375 435.808594 Z M 440.808594 419.949219 C 446.550781 413.152344 448.96875 404.089844 446.550781 395.332031 C 445.644531 392.160156 442.171875 390.042969 438.996094 391.101562 C 435.824219 392.160156 433.859375 395.332031 434.765625 398.652344 C 434.917969 399.257812 435.070312 400.011719 435.21875 400.617188 C 435.371094 401.675781 435.371094 402.882812 435.21875 403.941406 C 434.917969 405.300781 434.613281 406.660156 434.160156 408.019531 C 433.558594 409.074219 432.953125 410.285156 432.199219 411.191406 C 431.140625 412.398438 430.382812 413.90625 430.382812 415.570312 C 430.382812 417.078125 430.988281 418.890625 432.199219 419.949219 C 434.464844 422.0625 438.542969 422.667969 440.808594 419.949219 Z M 431.894531 377.054688 C 431.746094 375.394531 431.140625 374.035156 430.082031 372.675781 C 425.398438 367.238281 418.449219 364.21875 411.347656 363.765625 C 408.171875 363.613281 405 366.785156 405.152344 369.957031 C 405.300781 373.429688 407.871094 375.996094 411.347656 376.148438 C 411.648438 376.148438 411.800781 376.148438 412.101562 376.148438 C 413.308594 376.300781 414.519531 376.753906 415.726562 377.207031 C 416.9375 377.808594 417.996094 378.414062 419.050781 379.167969 C 419.808594 379.925781 420.714844 380.679688 421.320312 381.433594 C 422.226562 382.644531 424.1875 383.246094 425.699219 383.246094 C 427.210938 383.246094 429.023438 382.644531 430.082031 381.433594 C 431.140625 380.226562 432.046875 378.714844 431.894531 377.054688 Z M 375.988281 382.945312 C 375.234375 384.910156 374.78125 387.023438 374.476562 389.136719 C 374.328125 390.648438 375.234375 392.460938 376.292969 393.519531 C 377.347656 394.574219 379.160156 395.332031 380.671875 395.332031 C 382.335938 395.332031 383.847656 394.726562 385.054688 393.519531 C 385.355469 393.066406 385.660156 392.613281 385.960938 392.308594 C 386.414062 391.554688 386.71875 390.800781 386.71875 389.894531 C 386.867188 388.835938 387.171875 387.929688 387.472656 386.871094 C 387.925781 385.964844 388.53125 384.910156 389.132812 384.003906 C 389.738281 383.246094 390.496094 382.492188 391.402344 381.738281 C 392.308594 380.980469 393.367188 380.378906 394.421875 379.925781 C 395.78125 379.320312 396.839844 377.507812 397.292969 376.300781 C 397.746094 374.789062 397.445312 372.824219 396.691406 371.617188 C 395.78125 370.257812 394.574219 369.199219 393.0625 368.746094 C 392.457031 368.746094 392.003906 368.597656 391.402344 368.597656 C 390.34375 368.597656 389.285156 368.898438 388.226562 369.503906 C 384.300781 371.164062 381.277344 374.183594 378.707031 377.507812 C 377.652344 379.167969 376.746094 380.980469 375.988281 382.945312 Z M 402.429688 418.136719 C 403.640625 417.382812 405 415.871094 405.300781 414.511719 C 405.605469 413 405.605469 411.191406 404.699219 409.832031 C 403.792969 408.472656 402.582031 407.414062 401.070312 406.960938 C 400.769531 406.808594 400.316406 406.660156 400.015625 406.660156 C 399.257812 406.355469 398.652344 405.902344 398.050781 405.449219 C 397.445312 404.996094 396.992188 404.394531 396.386719 403.789062 C 395.933594 403.035156 395.480469 402.429688 395.179688 401.675781 C 395.027344 401.070312 394.726562 400.464844 394.121094 399.863281 C 393.667969 399.257812 393.0625 398.652344 392.457031 398.199219 C 391.097656 397.445312 389.132812 397.144531 387.773438 397.597656 C 386.265625 398.050781 384.902344 398.957031 384.148438 400.464844 C 383.394531 401.824219 382.941406 403.636719 383.542969 405.148438 C 384.753906 408.320312 386.566406 411.339844 389.132812 413.757812 C 391.703125 416.023438 394.726562 417.835938 398.050781 418.742188 C 399.257812 419.195312 401.070312 418.890625 402.429688 418.136719 Z M 424.339844 398.351562 C 423.734375 397.746094 423.132812 397.292969 422.375 397.144531 C 421.621094 396.691406 420.867188 396.539062 419.957031 396.539062 C 418.296875 396.539062 416.785156 397.144531 415.578125 398.351562 C 414.519531 399.558594 413.914062 400.917969 413.761719 402.582031 C 413.761719 402.730469 413.613281 403.035156 413.613281 403.183594 C 413.460938 403.335938 413.460938 403.488281 413.308594 403.636719 C 413.160156 403.789062 413.007812 403.941406 412.855469 404.089844 C 412.554688 404.242188 412.253906 404.542969 411.800781 404.695312 C 411.042969 405.148438 410.441406 405.601562 410.136719 406.355469 C 409.53125 406.960938 409.230469 407.714844 409.078125 408.472656 C 408.777344 409.226562 408.777344 410.132812 408.929688 410.886719 C 408.929688 411.644531 409.230469 412.398438 409.683594 413.152344 C 410.589844 414.511719 411.800781 415.570312 413.308594 416.023438 C 413.914062 416.023438 414.367188 416.171875 414.972656 416.171875 C 416.03125 416.171875 417.085938 415.871094 418.144531 415.265625 C 419.355469 414.8125 420.410156 413.90625 421.320312 413.152344 C 422.226562 412.398438 423.132812 411.191406 423.734375 410.285156 C 423.886719 409.980469 424.1875 409.679688 424.339844 409.226562 C 424.792969 408.472656 425.097656 407.566406 425.398438 406.660156 C 425.851562 405.449219 426.003906 404.089844 426.003906 402.730469 C 426.003906 401.824219 425.851562 401.070312 425.398438 400.316406 C 425.398438 399.558594 424.945312 398.957031 424.339844 398.351562 Z M 340.328125 389.589844 C 341.992188 389.589844 343.503906 388.988281 344.710938 387.777344 C 345.769531 386.570312 346.523438 385.058594 346.523438 383.398438 C 346.523438 382.644531 346.675781 381.886719 346.675781 381.285156 C 346.976562 379.925781 347.28125 378.566406 347.734375 377.355469 C 348.035156 376.601562 348.488281 375.847656 348.941406 375.089844 C 349.699219 373.730469 350 371.917969 349.546875 370.410156 C 349.09375 369.050781 348.035156 367.386719 346.675781 366.785156 C 345.316406 366.027344 343.503906 365.574219 341.992188 366.179688 C 340.480469 366.632812 339.121094 367.539062 338.367188 369.050781 C 335.644531 373.429688 334.285156 378.566406 334.285156 383.699219 C 334.285156 385.210938 335.042969 387.023438 336.097656 388.082031 C 337.003906 388.988281 338.667969 389.742188 340.328125 389.589844 Z M 340.328125 389.589844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPure, wild nature in every drop\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYour skin gets everything it needs - in the purest form of nature\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6892ed1 e-con-full e-flex e-con e-parent\" data-id=\"6892ed1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4831762 e-con-full e-flex e-con e-child\" data-id=\"4831762\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-baf465e e-con-full e-flex e-con e-child\" data-id=\"baf465e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/boskapszczola.pl\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/oleozel-swiezo-ukrecony-v3.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00cf998 e-con-full e-flex e-con e-child\" data-id=\"00cf998\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef15230 elementor-widget elementor-widget-heading\" data-id=\"ef15230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FRESHNESS = EFFECTIVENESS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b96acec elementor-widget elementor-widget-text-editor\" data-id=\"b96acec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Small production batches guarantee that you get a cosmetic always freshly coined, with full potency. Powerfully bioactive. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3aae9a elementor-arrows-yes elementor-pagination-type-bullets elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"b3aae9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slajdy\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-d60e152\">\n\t\t\t\t\t\t\t<a class=\"elementor-testimonial__header\" href=\"https:\/\/boskapszczola.pl\/en\/about-me\/\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2024\/11\/zalozycielka.jpg\" alt=\"Made by Natalia Martin @boska.pszczola\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Made by Natalia Martin @boska.pszczola<\/span><span class=\"elementor-testimonial__title\">12.5K followers<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Read More\"><\/div>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4810768 e-flex e-con-boxed e-con e-parent\" data-id=\"4810768\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bb9809a e-con-full e-flex e-con e-child\" data-id=\"bb9809a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d8194f e-con-full e-flex e-con e-child\" data-id=\"1d8194f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3479d21 elementor-widget elementor-widget-image\" data-id=\"3479d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-300x300.png\" class=\"attachment-medium size-medium wp-image-15391\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-300x300.png 300w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-1024x1024.png 1024w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-150x150.png 150w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-768x768.png 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-600x600.png 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2-100x100.png 100w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-2.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6967bb7 elementor-widget elementor-widget-heading\" data-id=\"6967bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A GLOW YOU'LL LOVE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-170760c elementor-widget elementor-widget-text-editor\" data-id=\"170760c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Just a mini drop applied to wet skin is enough to work magic. After just the first use, your skin will be soft and nourished, and after a month you&#8217;ll be radiant, and chances are you&#8217;ll fall in love with your own skin all over again. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9471804 e-flex e-con-boxed e-con e-parent\" data-id=\"9471804\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18e6267 e-con-full e-flex e-con e-child\" data-id=\"18e6267\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1968062 elementor-widget elementor-widget-rating\" data-id=\"1968062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"4.7\" role=\"img\" aria-label=\"Rated 4.7 out of 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\" style=\"--e-rating-icon-marked-width: 70%;\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-962b9f9 elementor-widget elementor-widget-heading\" data-id=\"962b9f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TRUE STORIES AND REMARKABLE RESULTS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed792c7 elementor-widget elementor-widget-text-editor\" data-id=\"ed792c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>They speak for themselves. And your transformation will be next. <\/p><p>So many women have already chosen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da8d216 elementor-widget elementor-widget-counter\" data-id=\"da8d216\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1092\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9ceeb3 e-con-full e-flex e-con e-child\" data-id=\"d9ceeb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d30fc5d elementor-arrows-yes elementor-pagination-type-bullets elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"d30fc5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slajdy\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-d60e152\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/03\/Projekt-bez-nazwy-9.jpg\" alt=\"Justyna Galat @justynagalat_kosmetolog\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Justyna Galat @justynagalat_kosmetolog<\/span><span class=\"elementor-testimonial__title\">COSMETOLOGIST<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Read More\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"I fell in love with them immediately. The oleo-gel and serum soothe the skin wonderfully - including sensitive and very demanding skin.\"\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9babc82 elementor-arrows-yes elementor-pagination-type-bullets elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"9babc82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slajdy\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-d60e152\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/Projekt-bez-nazwy-9.jpg\" alt=\"Paulina Gruszecka @zacznijodzdrowia.pl\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Paulina Gruszecka @zacznijodzdrowia.pl<\/span><span class=\"elementor-testimonial__title\">HOLISTIC CLINICAL NUTRITIONIST<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Read More\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Cosmetics from divine bee are not only ultra healthy, but what they have done to my skin is another dimension of wow effect!\"\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2465dba elementor-arrows-yes elementor-pagination-type-bullets elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"2465dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slajdy\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-d60e152\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/Projekt-bez-nazwy-9-kopia.jpg\" alt=\"Agata Tomaszewska @satya.gliwice\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Agata Tomaszewska @satya.gliwice<\/span><span class=\"elementor-testimonial__title\">PHYSIOTHERAPIST, MASSAGE THERAPIST KOBIDO<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Read More\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"My skin loves Wildflowers oleo gel. It's my regular beauty product in the bathroom and also in my massage room.\"\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10221bc e-con-full e-flex e-con e-child\" data-id=\"10221bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b785fb elementor-widget elementor-widget-image\" data-id=\"4b785fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-300x300.png\" class=\"attachment-medium size-medium wp-image-15389\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-300x300.png 300w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-1024x1024.png 1024w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-150x150.png 150w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-768x768.png 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-600x600.png 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS-100x100.png 100w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/02\/EKOCUDA-BEAUTY-AWARDS.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1155c8a e-flex e-con-boxed e-con e-parent\" data-id=\"1155c8a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba07b49 elementor-widget elementor-widget-woocommerce-photo-reviews\" data-id=\"ba07b49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-photo-reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"woocommerce-photo-reviews-shortcode-1\" class=\"woocommerce-photo-reviews-shortcode woocommerce-photo-reviews-shortcode-popup-review\" data-wcpr_image=\"\" data-wcpr_verified=\"\" data-wcpr_rating=\"\" data-wcpr_slide=\"\"  data-reviews_shortcode=\"{&quot;comments_per_page&quot;:&quot;5&quot;,&quot;cols&quot;:&quot;5&quot;,&quot;cols_mobile&quot;:&quot;2&quot;,&quot;cols_gap&quot;:&quot;15&quot;,&quot;use_single_product&quot;:&quot;&quot;,&quot;products&quot;:&quot;&quot;,&quot;products_status&quot;:&quot;publish&quot;,&quot;grid_bg_color&quot;:&quot;&quot;,&quot;grid_item_bg_color&quot;:&quot;&quot;,&quot;grid_item_border_color&quot;:&quot;#dddddd&quot;,&quot;text_color&quot;:&quot;#000&quot;,&quot;star_color&quot;:&quot;#ffb600&quot;,&quot;product_cat&quot;:&quot;&quot;,&quot;order&quot;:&quot;desc&quot;,&quot;orderby&quot;:&quot;comment_date&quot;,&quot;show_product&quot;:&quot;on&quot;,&quot;filter&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;on&quot;,&quot;pagination_ajax&quot;:&quot;on&quot;,&quot;pagination_next&quot;:&quot;&quot;,&quot;pagination_pre&quot;:&quot;&quot;,&quot;loadmore_button&quot;:&quot;&quot;,&quot;filter_default_image&quot;:&quot;&quot;,&quot;filter_default_verified&quot;:&quot;&quot;,&quot;filter_default_rating&quot;:&quot;&quot;,&quot;pagination_position&quot;:&quot;center&quot;,&quot;conditional_tag&quot;:&quot;&quot;,&quot;masonry_popup&quot;:&quot;review&quot;,&quot;image_popup&quot;:&quot;&quot;,&quot;ratings&quot;:&quot;5&quot;,&quot;mobile&quot;:&quot;on&quot;,&quot;style&quot;:&quot;masonry&quot;,&quot;is_slide&quot;:&quot;&quot;,&quot;enable_box_shadow&quot;:&quot;&quot;,&quot;full_screen_mobile&quot;:&quot;on&quot;,&quot;style_mobile&quot;:&quot;&quot;,&quot;overall_rating&quot;:&quot;&quot;,&quot;rating_count&quot;:&quot;&quot;,&quot;only_images&quot;:&quot;on&quot;,&quot;area_border_color&quot;:&quot;&quot;,&quot;area_bg_color&quot;:&quot;&quot;,&quot;button_color&quot;:&quot;&quot;,&quot;button_bg_color&quot;:&quot;&quot;,&quot;button_border_color&quot;:&quot;&quot;,&quot;rating_count_bar_color&quot;:&quot;#ffb600&quot;,&quot;verified_color&quot;:&quot;#000000&quot;,&quot;hide_rating_count_if_empty&quot;:&quot;on&quot;,&quot;hide_filters_if_empty&quot;:&quot;off&quot;,&quot;is_elementor&quot;:&quot;yes&quot;,&quot;wpml_all_languages&quot;:&quot;off&quot;,&quot;pll_all_languages&quot;:&quot;off&quot;,&quot;language&quot;:&quot;en&quot;}\"><div class=\"shortcode-wcpr-pagination\">\r\n\t <span class=\"wcpr-page-numbers wcpr-current\">1<\/span>        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/15350?wcpr_page=2\"\r\n           class=\"wcpr-page-numbers\">2<\/a>\r\n\t\t            <span class=\"wcpr-page-numbers wcpr-no-page\">...<\/span>\r\n\t\t\t        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/15350?wcpr_page=14\"\r\n           class=\"wcpr-page-numbers\">14<\/a>\r\n\t\t<\/div>\r\n <div class=\"shortcode-wcpr-masonry-style shortcode-wcpr-grid shortcode-wcpr-masonry-5-col shortcode-wcpr-masonry-popup-review\" data-wcpr_columns=\"5\"><div id=\"shortcode-comment-13761\" class=\"shortcode-wcpr-grid-item\"><div class=\"shortcode-wcpr-content\">            <div class=\"shortcode-reviews-images-container\">\r\n                <div class=\"shortcode-reviews-images-wrap-left\">\r\n\t\t\t\t\t                <\/div>\r\n\t\t\t\t<div class=\"shortcode-reviews-images-wrap-right\"><img loading=\"lazy\" decoding=\"async\" class=\"shortcode-reviews-images\" loading=\"lazy\" data-original_src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/20260505_195052-scaled.jpg\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/20260505_195052-scaled.jpg\" alt=\"Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml photo review\" title=\"Click to view full screen\" width=\"225\" height=\"300\"><\/div>            <\/div>\r\n\t\t\t<div class=\"shortcode-review-content-container\">            <div class=\"shortcode-review-content-container-top\">\r\n                <div class=\"shortcode-review-content-container-top-left\">\r\n\t\t\t\t\t                <\/div>\r\n                <div class=\"shortcode-review-content-container-top-right\">\r\n\t\t\t\t\t                        <div style=\"display: none\">\r\n\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/c8d26d53297169b13a4b81e0b4ff0a064adebe6c1667dbd53e0b27af6c0f7cad?s=60&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/c8d26d53297169b13a4b81e0b4ff0a064adebe6c1667dbd53e0b27af6c0f7cad?s=120&#038;d=blank&#038;r=g 2x' class='avatar avatar-60 photo' height='60' width='60' \/>                        <\/div>\r\n\t\t\t\t\t\t                    <div class=\"shortcode-wcpr-comment-author\">\r\n\t\t\t\t\t\tMarta                    <\/div>\r\n                    <div class=\"wcpr-review-rating\">\r\n\t\t\t\t\t\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:100%\">Rated <strong class=\"rating\">5<\/strong> out of 5<\/span><\/div><\/div>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div>\r\n\t\t\t\t<div lang=\"pl\">            <\/div>\r\n\t\t\t        <div class=\"shortcode-wcpr-review-content\"><div class=\"shortcode-wcpr-review-content-short\">Nie wiem kt\u00f3ra to ju\u017c buteleczka. Zreszt\u0105 jak i pozosta\u0142ych kosmetyk\u00f3w Natalii. Przesta\u0142am ju\u017c liczy\u0107. Wszystkie s\u0105 moimi ulubionymi. Naturalnych prod<span class=\"shortcode-wcpr-read-more\" title=\"Read more\">...More<\/span><\/div><div class=\"shortcode-wcpr-review-content-full\">Nie wiem kt\u00f3ra to ju\u017c buteleczka. Zreszt\u0105 jak i pozosta\u0142ych kosmetyk\u00f3w Natalii. Przesta\u0142am ju\u017c liczy\u0107. Wszystkie s\u0105 moimi ulubionymi. Naturalnych produkt\u00f3w u\u017cywam ju\u017c od ponad 16 lat, sprawdzi\u0142am mn\u00f3stwo r\u00f3\u017cnych. Jestem bardzo wymagaj\u0105ca, je\u015bli chodzi o dob\u00f3r kosmetyk\u00f3w do piel\u0119gnacji swojej sk\u00f3ry. Produkty Natalii w pe\u0142ni spe\u0142niaj\u0105 moje kryteria. S\u0105 fantastyczne. To prawdziwy majstersztyk,  mistrzostwo. Uwielbiam swoj\u0105 sk\u00f3r\u0119, kiedy je stosuj\u0119. Zapewniaj\u0105 pe\u0142en komfort. Nie jestem w stanie nawet wybra\u0107 jednego. Poprzeczka zosta\u0142a zawieszona bardzo wysoko dla konkurencjii. Dzi\u0119kuj\u0119 Ci Natalio za Twoje arcydzie\u0142a i za Twoj\u0105 mi\u0142o\u015b\u0107 do natury.<\/div><\/div>\r\n\t\t            <div>\r\n\t\t\t\t<\/div>            <\/div>\r\n\t\t\t<\/div>    <div class=\"shortcode-wcpr-single-product-summary-content-wrapper\" style=\"display: none;\">\r\n        <div class=\"shortcode-wcpr-single-product-summary-content-container\" style=\"border-top: 1px solid;\">\r\n            <div class=\"shortcode-wcpr-single-product-summary-content\">\r\n\t\t\t\t<div class=\"shortcode-wcpr-single-product-summary-image\"><img src = \"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-150x150.jpg\" loading=\"lazy\"><\/div>                <div class=\"shortcode-wcpr-single-product-summary-meta\">\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-title\">\r\n                        <a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia-kopia\/\"\r\n                           target=\"_blank\">Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml<\/a>\r\n                    <\/div>\r\n\t\t\t\t\t                    <div class=\"shortcode-wcpr-single-product-summary-meta-reviews\">\r\n\t\t\t\t\t\t<div class=\"woocommerce-photo-reviews-rating-html-shortcode\">\r\n\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:94.6%\">Rated <strong class=\"rating\">4.73<\/strong> out of 5<\/span><\/div><\/div><span class=\"woocommerce-photo-reviews-review-count-container\">(<span class=\"woocommerce-photo-reviews-review-count\">11<\/span>)<\/span><\/div>\r\n                    <\/div>\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-price\">\r\n                        <p class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\">98,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/span><\/p>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div class=\"shortcode-wcpr-single-product-summary-meta-shop\">\r\n\t\t\t\t<p class=\"product woocommerce add_to_cart_inline \" style=\"\"><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia-kopia\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14072\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"14072\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14072\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/p>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t<\/div><\/div><div id=\"shortcode-comment-13348\" class=\"shortcode-wcpr-grid-item\"><div class=\"shortcode-wcpr-content\">            <div class=\"shortcode-reviews-images-container\">\r\n                <div class=\"shortcode-reviews-images-wrap-left\">\r\n\t\t\t\t\t                <\/div>\r\n\t\t\t\t<div class=\"shortcode-reviews-images-wrap-right\"><img loading=\"lazy\" decoding=\"async\" class=\"shortcode-reviews-images\" loading=\"lazy\" data-original_src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/IMG_4321-scaled.jpeg\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/IMG_4321-scaled.jpeg\" alt=\"Regenerating oil with turmeric, dandelion and vit. E - 100 ml photo review\" title=\"Click to view full screen\" width=\"225\" height=\"300\"><\/div>            <\/div>\r\n\t\t\t<div class=\"shortcode-review-content-container\">            <div class=\"shortcode-review-content-container-top\">\r\n                <div class=\"shortcode-review-content-container-top-left\">\r\n\t\t\t\t\t                <\/div>\r\n                <div class=\"shortcode-review-content-container-top-right\">\r\n\t\t\t\t\t                        <div style=\"display: none\">\r\n\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/648ababa3b3eee2f0fb1533b8ed25702dacb038375bd98c3b37d8f91ad52bd7e?s=60&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/648ababa3b3eee2f0fb1533b8ed25702dacb038375bd98c3b37d8f91ad52bd7e?s=120&#038;d=blank&#038;r=g 2x' class='avatar avatar-60 photo' height='60' width='60' \/>                        <\/div>\r\n\t\t\t\t\t\t                    <div class=\"shortcode-wcpr-comment-author\">\r\n\t\t\t\t\t\tGosia                    <\/div>\r\n                    <div class=\"wcpr-review-rating\">\r\n\t\t\t\t\t\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:100%\">Rated <strong class=\"rating\">5<\/strong> out of 5<\/span><\/div><\/div>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div>\r\n\t\t\t\t<div lang=\"pl\">            <\/div>\r\n\t\t\t        <div class=\"shortcode-wcpr-review-content\">Jestem zachwycona tymi produktami! I jak wida\u0107 po pustych opakowaniach - bardzo si\u0119 sprawdzi\u0142y!<\/div>\r\n\t\t            <div>\r\n\t\t\t\t<\/div>            <\/div>\r\n\t\t\t<\/div>    <div class=\"shortcode-wcpr-single-product-summary-content-wrapper\" style=\"display: none;\">\r\n        <div class=\"shortcode-wcpr-single-product-summary-content-container\" style=\"border-top: 1px solid;\">\r\n            <div class=\"shortcode-wcpr-single-product-summary-content\">\r\n\t\t\t\t<div class=\"shortcode-wcpr-single-product-summary-image\"><img src = \"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-150x150.jpg\" loading=\"lazy\"><\/div>                <div class=\"shortcode-wcpr-single-product-summary-meta\">\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-title\">\r\n                        <a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/regenerating-oil-with-turmeric-dandelion-and-vit-e-100-ml\/\"\r\n                           target=\"_blank\">Regenerating oil with turmeric, dandelion and vit. E - 100 ml<\/a>\r\n                    <\/div>\r\n\t\t\t\t\t                    <div class=\"shortcode-wcpr-single-product-summary-meta-reviews\">\r\n\t\t\t\t\t\t<div class=\"woocommerce-photo-reviews-rating-html-shortcode\">\r\n\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:99.4%\">Rated <strong class=\"rating\">4.97<\/strong> out of 5<\/span><\/div><\/div><span class=\"woocommerce-photo-reviews-review-count-container\">(<span class=\"woocommerce-photo-reviews-review-count\">64<\/span>)<\/span><\/div>\r\n                    <\/div>\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-price\">\r\n                        <p class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\">20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/span><\/p>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div class=\"shortcode-wcpr-single-product-summary-meta-shop\">\r\n\t\t\t\t<p class=\"product woocommerce add_to_cart_inline \" style=\"\"><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/regenerating-oil-with-turmeric-dandelion-and-vit-e-100-ml\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13115\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"13115\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Regenerating oil with turmeric, dandelion and vit. E - 100 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13115\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/p>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t<\/div><\/div><div id=\"shortcode-comment-12764\" class=\"shortcode-wcpr-grid-item\"><div class=\"shortcode-wcpr-content\">            <div class=\"shortcode-reviews-images-container\">\r\n                <div class=\"shortcode-reviews-images-wrap-left\">\r\n\t\t\t\t\t                <\/div>\r\n\t\t\t\t<div class=\"shortcode-reviews-images-wrap-right\"><img loading=\"lazy\" decoding=\"async\" class=\"shortcode-reviews-images\" loading=\"lazy\" data-original_src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/03\/Projekt-bez-nazwy-10.jpg\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2026\/03\/Projekt-bez-nazwy-10.jpg\" alt=\"Berry serum - a plant-based alternative to retinol - 30 ml. photo review\" title=\"Click to view full screen\" width=\"300\" height=\"225\"><\/div>            <\/div>\r\n\t\t\t<div class=\"shortcode-review-content-container\">            <div class=\"shortcode-review-content-container-top\">\r\n                <div class=\"shortcode-review-content-container-top-left\">\r\n\t\t\t\t\t                <\/div>\r\n                <div class=\"shortcode-review-content-container-top-right\">\r\n\t\t\t\t\t                        <div style=\"display: none\">\r\n\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/6991f408934201fe77ddf1c5b5181e6e9e00455ec90f551e3bbd0bea17e1952f?s=60&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/6991f408934201fe77ddf1c5b5181e6e9e00455ec90f551e3bbd0bea17e1952f?s=120&#038;d=blank&#038;r=g 2x' class='avatar avatar-60 photo' height='60' width='60' \/>                        <\/div>\r\n\t\t\t\t\t\t                    <div class=\"shortcode-wcpr-comment-author\">\r\n\t\t\t\t\t\tMarta                    <\/div>\r\n                    <div class=\"wcpr-review-rating\">\r\n\t\t\t\t\t\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:100%\">Rated <strong class=\"rating\">5<\/strong> out of 5<\/span><\/div><\/div>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div>\r\n\t\t\t\t<div lang=\"pl\">            <\/div>\r\n\t\t\t        <div class=\"shortcode-wcpr-review-content\"><div class=\"shortcode-wcpr-review-content-short\">Youth nectar - genialny! Na mnie dzia\u0142a \u015bwietnie, robi ma\u0142e cuda- sk\u00f3ra nawil\u017cona, ukojona, promienna... Dlatego wracam po kolejny! Polecam \ud83d\ude42 \u017b\u00f3\u0142ty n<span class=\"shortcode-wcpr-read-more\" title=\"Read more\">...More<\/span><\/div><div class=\"shortcode-wcpr-review-content-full\">Youth nectar - genialny! Na mnie dzia\u0142a \u015bwietnie, robi ma\u0142e cuda- sk\u00f3ra nawil\u017cona, ukojona, promienna... Dlatego wracam po kolejny! Polecam \ud83d\ude42 \u017b\u00f3\u0142ty nektar te\u017c jest fajny, ale mnie troch\u0119 uczula,ze wzgl\u0119du na inny sk\u0142ad i moje alergie.<\/div><\/div>\r\n\t\t            <div>\r\n\t\t\t\t<\/div>            <\/div>\r\n\t\t\t<\/div>    <div class=\"shortcode-wcpr-single-product-summary-content-wrapper\" style=\"display: none;\">\r\n        <div class=\"shortcode-wcpr-single-product-summary-content-container\" style=\"border-top: 1px solid;\">\r\n            <div class=\"shortcode-wcpr-single-product-summary-content\">\r\n\t\t\t\t<div class=\"shortcode-wcpr-single-product-summary-image\"><img src = \"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami-150x150.jpg\" loading=\"lazy\"><\/div>                <div class=\"shortcode-wcpr-single-product-summary-meta\">\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-title\">\r\n                        <a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml\/\"\r\n                           target=\"_blank\">Berry serum - a plant-based alternative to retinol - 30 ml.<\/a>\r\n                    <\/div>\r\n\t\t\t\t\t                    <div class=\"shortcode-wcpr-single-product-summary-meta-reviews\">\r\n\t\t\t\t\t\t<div class=\"woocommerce-photo-reviews-rating-html-shortcode\">\r\n\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:96.6%\">Rated <strong class=\"rating\">4.83<\/strong> out of 5<\/span><\/div><\/div><span class=\"woocommerce-photo-reviews-review-count-container\">(<span class=\"woocommerce-photo-reviews-review-count\">40<\/span>)<\/span><\/div>\r\n                    <\/div>\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-price\">\r\n                        <p class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\">20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/span><\/p>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div class=\"shortcode-wcpr-single-product-summary-meta-shop\">\r\n\t\t\t\t<p class=\"product woocommerce add_to_cart_inline \" style=\"\"><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13104\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"13104\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Berry serum - a plant-based alternative to retinol - 30 ml.&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13104\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/p>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t<\/div><\/div><div id=\"shortcode-comment-12666\" class=\"shortcode-wcpr-grid-item\"><div class=\"shortcode-wcpr-content\">            <div class=\"shortcode-reviews-images-container\">\r\n                <div class=\"shortcode-reviews-images-wrap-left\">\r\n\t\t\t\t\t                <\/div>\r\n\t\t\t\t<div class=\"shortcode-reviews-images-wrap-right\"><img loading=\"lazy\" decoding=\"async\" class=\"shortcode-reviews-images\" loading=\"lazy\" data-original_src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/unnamed.jpg\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/unnamed.jpg\" alt=\"Regenerating oil with turmeric, dandelion and vit. E - 100 ml photo review\" title=\"Click to view full screen\" width=\"225\" height=\"300\"><\/div>            <\/div>\r\n\t\t\t<div class=\"shortcode-review-content-container\">            <div class=\"shortcode-review-content-container-top\">\r\n                <div class=\"shortcode-review-content-container-top-left\">\r\n\t\t\t\t\t                <\/div>\r\n                <div class=\"shortcode-review-content-container-top-right\">\r\n\t\t\t\t\t                        <div style=\"display: none\">\r\n\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5cbfb4a9ae253cbc3d49a8edf051c06ccca5442775d718ac616616a736592857?s=60&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5cbfb4a9ae253cbc3d49a8edf051c06ccca5442775d718ac616616a736592857?s=120&#038;d=blank&#038;r=g 2x' class='avatar avatar-60 photo' height='60' width='60' \/>                        <\/div>\r\n\t\t\t\t\t\t                    <div class=\"shortcode-wcpr-comment-author\">\r\n\t\t\t\t\t\tDominika W.                    <\/div>\r\n                    <div class=\"wcpr-review-rating\">\r\n\t\t\t\t\t\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:100%\">Rated <strong class=\"rating\">5<\/strong> out of 5<\/span><\/div><\/div>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div>\r\n\t\t\t\t<div lang=\"pl\">            <\/div>\r\n\t\t\t        <div class=\"shortcode-wcpr-review-content\"><div class=\"shortcode-wcpr-review-content-short\">Przecudne kosmetyki! Wszystkie produkty stworzone przez Natali\u0119 s\u0105 wspania\u0142e i \u015bwietne dla mojej sk\u00f3ry. Od roku, kiedy odkry\u0142am Bosk\u0105 Pszczo\u0142\u0119, prakty<span class=\"shortcode-wcpr-read-more\" title=\"Read more\">...More<\/span><\/div><div class=\"shortcode-wcpr-review-content-full\">Przecudne kosmetyki! Wszystkie produkty stworzone przez Natali\u0119 s\u0105 wspania\u0142e i \u015bwietne dla mojej sk\u00f3ry. Od roku, kiedy odkry\u0142am Bosk\u0105 Pszczo\u0142\u0119, praktycznie nie u\u017cywam innych kosmetyk\u00f3w! Sk\u00f3ra po kosmetykach Natalii jest cudownie mi\u0119kka, nawil\u017cona, nawet teraz zim\u0105 nie stwarza \u017cadnych problem\u00f3w. Kosmetyki maj\u0105 rewelacyjny, naturalny sk\u0142ad, dobr\u0105 konsystencj\u0119, znakomite opakowania (zar\u00f3wno pod k\u0105tem wizualnym jak i u\u017cytkowym). Jedyne, do czego mo\u017cna si\u0119 przyczepi\u0107, to to, \u017ce ci\u0119\u017cko wydoby\u0107 resztki kosmetyk\u00f3w z opakowa\u0144, \u017ceby nie zmarnowa\u0107 ani kropli! Ale na to te\u017c mam swoje sposoby. Najcz\u0119\u015bciej u\u017cywam oleo\u017celu i serum jagodowego, po kt\u00f3re ci\u0105gle wracam, ale z czystym sumieniem mog\u0119 poleci\u0107 tonik (ten cudny zapach!) oraz balsam do ust. Staram si\u0119 te\u017c zarazi\u0107 mi\u0142o\u015bci\u0105 do Boskiej Pszczo\u0142y najbli\u017csze mi kobiety, obdarowuj\u0105c je pr\u00f3bkami (pi\u0119knie zapakowanymi w malutkie s\u0142oiczki). Dzi\u0119kuj\u0119, Natalio, za Twoj\u0105 prac\u0119!<\/div><\/div>\r\n\t\t            <div>\r\n\t\t\t\t<\/div>            <\/div>\r\n\t\t\t<\/div>    <div class=\"shortcode-wcpr-single-product-summary-content-wrapper\" style=\"display: none;\">\r\n        <div class=\"shortcode-wcpr-single-product-summary-content-container\" style=\"border-top: 1px solid;\">\r\n            <div class=\"shortcode-wcpr-single-product-summary-content\">\r\n\t\t\t\t<div class=\"shortcode-wcpr-single-product-summary-image\"><img src = \"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-150x150.jpg\" loading=\"lazy\"><\/div>                <div class=\"shortcode-wcpr-single-product-summary-meta\">\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-title\">\r\n                        <a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/regenerating-oil-with-turmeric-dandelion-and-vit-e-100-ml\/\"\r\n                           target=\"_blank\">Regenerating oil with turmeric, dandelion and vit. E - 100 ml<\/a>\r\n                    <\/div>\r\n\t\t\t\t\t                    <div class=\"shortcode-wcpr-single-product-summary-meta-reviews\">\r\n\t\t\t\t\t\t<div class=\"woocommerce-photo-reviews-rating-html-shortcode\">\r\n\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:99.4%\">Rated <strong class=\"rating\">4.97<\/strong> out of 5<\/span><\/div><\/div><span class=\"woocommerce-photo-reviews-review-count-container\">(<span class=\"woocommerce-photo-reviews-review-count\">64<\/span>)<\/span><\/div>\r\n                    <\/div>\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-price\">\r\n                        <p class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\">20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/span><\/p>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div class=\"shortcode-wcpr-single-product-summary-meta-shop\">\r\n\t\t\t\t<p class=\"product woocommerce add_to_cart_inline \" style=\"\"><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/regenerating-oil-with-turmeric-dandelion-and-vit-e-100-ml\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13115\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"13115\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Regenerating oil with turmeric, dandelion and vit. E - 100 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13115\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/p>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t<\/div><\/div><div id=\"shortcode-comment-12664\" class=\"shortcode-wcpr-grid-item\"><div class=\"shortcode-wcpr-content\">            <div class=\"shortcode-reviews-images-container\">\r\n                <div class=\"shortcode-reviews-images-wrap-left\">\r\n\t\t\t\t\t                <\/div>\r\n\t\t\t\t<div class=\"shortcode-reviews-images-wrap-right\"><img loading=\"lazy\" decoding=\"async\" class=\"shortcode-reviews-images\" loading=\"lazy\" data-original_src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/unnamed-3.jpg\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/unnamed-3.jpg\" alt=\"Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml photo review\" title=\"Click to view full screen\" width=\"162\" height=\"300\"><\/div>            <\/div>\r\n\t\t\t<div class=\"shortcode-review-content-container\">            <div class=\"shortcode-review-content-container-top\">\r\n                <div class=\"shortcode-review-content-container-top-left\">\r\n\t\t\t\t\t                <\/div>\r\n                <div class=\"shortcode-review-content-container-top-right\">\r\n\t\t\t\t\t                        <div style=\"display: none\">\r\n\t\t\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5cbfb4a9ae253cbc3d49a8edf051c06ccca5442775d718ac616616a736592857?s=60&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5cbfb4a9ae253cbc3d49a8edf051c06ccca5442775d718ac616616a736592857?s=120&#038;d=blank&#038;r=g 2x' class='avatar avatar-60 photo' height='60' width='60' \/>                        <\/div>\r\n\t\t\t\t\t\t                    <div class=\"shortcode-wcpr-comment-author\">\r\n\t\t\t\t\t\tIwona                    <\/div>\r\n                    <div class=\"wcpr-review-rating\">\r\n\t\t\t\t\t\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:100%\">Rated <strong class=\"rating\">5<\/strong> out of 5<\/span><\/div><\/div>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div>\r\n\t\t\t\t<div lang=\"pl\">            <\/div>\r\n\t\t\t        <div class=\"shortcode-wcpr-review-content\"><div class=\"shortcode-wcpr-review-content-short\">Kosmetyki \"Boskiej Pszczoly\" sa moim odkryciem dziesieciolecia! Uwielbiam naturalne produkty, a kosmetyki tworzone na bierzaco przez Pani Natalie, to <span class=\"shortcode-wcpr-read-more\" title=\"Read more\">...More<\/span><\/div><div class=\"shortcode-wcpr-review-content-full\">Kosmetyki \"Boskiej Pszczoly\" sa moim odkryciem dziesieciolecia! Uwielbiam naturalne produkty, a kosmetyki tworzone na bierzaco przez Pani Natalie, to jest cos niesamowitego! Rewelacyjnym pomyslem sa male probki, ktore mozna zamowic, zanim zdecydujemy sie na pelnowymiarowe produkty. Ja tak wlasnie zrobilam, a jak widac na zdjeciu, mam juz wlasny zestaw tych cudeniek. Pojemnosc wymiarowch produktiw jesc duza, a do codziennej pielegnacji potrzeba naprawde malenkiej ilosci, wiec kosmetyki starcza na baaardzo dlugo. Skora po kosmetykach jest nawilzona, odswiezona i poprostu boska. Mgielka w sprayu dziala cuda! Po uzyciu, nie potrzeba juz nic wiecej. Skora promienieje! Kto jeszcze nie sprobowal - bardzo polecam<\/div><\/div>\r\n\t\t            <div>\r\n\t\t\t\t<\/div>            <\/div>\r\n\t\t\t<\/div>    <div class=\"shortcode-wcpr-single-product-summary-content-wrapper\" style=\"display: none;\">\r\n        <div class=\"shortcode-wcpr-single-product-summary-content-container\" style=\"border-top: 1px solid;\">\r\n            <div class=\"shortcode-wcpr-single-product-summary-content\">\r\n\t\t\t\t<div class=\"shortcode-wcpr-single-product-summary-image\"><img src = \"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-150x150.jpg\" loading=\"lazy\"><\/div>                <div class=\"shortcode-wcpr-single-product-summary-meta\">\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-title\">\r\n                        <a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia-kopia\/\"\r\n                           target=\"_blank\">Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml<\/a>\r\n                    <\/div>\r\n\t\t\t\t\t                    <div class=\"shortcode-wcpr-single-product-summary-meta-reviews\">\r\n\t\t\t\t\t\t<div class=\"woocommerce-photo-reviews-rating-html-shortcode\">\r\n\t<div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:94.6%\">Rated <strong class=\"rating\">4.73<\/strong> out of 5<\/span><\/div><\/div><span class=\"woocommerce-photo-reviews-review-count-container\">(<span class=\"woocommerce-photo-reviews-review-count\">11<\/span>)<\/span><\/div>\r\n                    <\/div>\r\n                    <div class=\"shortcode-wcpr-single-product-summary-meta-price\">\r\n                        <p class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\">98,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/span><\/p>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n\t\t\t            <div class=\"shortcode-wcpr-single-product-summary-meta-shop\">\r\n\t\t\t\t<p class=\"product woocommerce add_to_cart_inline \" style=\"\"><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia-kopia\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14072\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"14072\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14072\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/p>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t<\/div><\/div><\/div><div class=\"shortcode-wcpr-pagination\">\r\n\t <span class=\"wcpr-page-numbers wcpr-current\">1<\/span>        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/15350?wcpr_page=2\"\r\n           class=\"wcpr-page-numbers\">2<\/a>\r\n\t\t            <span class=\"wcpr-page-numbers wcpr-no-page\">...<\/span>\r\n\t\t\t        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/15350?wcpr_page=14\"\r\n           class=\"wcpr-page-numbers\">14<\/a>\r\n\t\t<\/div>\r\n<div class=\"wcpr-shortcode-overlay\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9387edc elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"9387edc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e9573e\" data-id=\"2e9573e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d9c52 e-flex e-con-boxed e-con e-parent\" data-id=\"f4d9c52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1963f46 e-con-full e-flex e-con e-child\" data-id=\"1963f46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7f5a3d elementor-widget elementor-widget-heading\" data-id=\"a7f5a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">YOUR SKIN WILL THANK YOU<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f69fa4 elementor-widget elementor-widget-text-editor\" data-id=\"4f69fa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Saturated with the power of plants, medicinal herbs and life-giving vitamins, it will flourish like never before, and you will not want to put anything else on your divine body<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-7995f79 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"7995f79\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d285862 elementor-widget elementor-widget-heading\" data-id=\"d285862\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BESTSELLERS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-788067b elementor-widget elementor-widget-text-editor\" data-id=\"788067b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>from a wild meadow<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82060ba elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"82060ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e71b1d1\" data-id=\"e71b1d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5a08d5 elementor-grid-mobile-1 elementor-grid-tablet-2 elementor-grid-4 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"a5a08d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4 \"><ul class=\"products elementor-grid columns-4\">\n<li class=\"desktop-align-left tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-single-variable ast-product-tabs-layout-horizontal product type-product post-13115 status-publish first instock product_cat-natural-cosmetics product_tag-face-wash product_tag-preservative-free product_tag-to-moisturize-your-face has-post-thumbnail taxable shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/regenerating-oil-with-turmeric-dandelion-and-vit-e-100-ml\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-600x731.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Regenerating oil with turmeric, dandelion and vit. E - 100 ml\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Oleozel_ekocuda.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2022\/11\/wildflowers-2-600x731.jpg\" class=\"show-on-hover\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2022\/11\/wildflowers-2-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2022\/11\/wildflowers-2-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2022\/11\/wildflowers-2-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2022\/11\/wildflowers-2-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2022\/11\/wildflowers-2.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><h2 class=\"woocommerce-loop-product__title\">Regenerating oil with turmeric, dandelion and vit. E &#8211; 100 ml<\/h2><div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:99.4%\">Rated <strong class=\"rating\">4.97<\/strong> out of 5<\/span><\/div><\/div>\n\t<span class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\"><bdi>20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/regenerating-oil-with-turmeric-dandelion-and-vit-e-100-ml\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13115\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"13115\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Regenerating oil with turmeric, dandelion and vit. E - 100 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13115\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/li>\n<li class=\"desktop-align-left tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-single-variable ast-product-tabs-layout-horizontal product type-product post-13104 status-publish instock product_cat-natural-cosmetics product_tag-as-of product_tag-cream-serum product_tag-face product_tag-overnight product_tag-under-eye has-post-thumbnail taxable shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami-600x731.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Berry serum - a plant-based alternative to retinol - 30 ml.\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/Nektar-z-jagodami.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/1-4-600x731.jpg\" class=\"show-on-hover\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/1-4-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/1-4-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/1-4-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/1-4-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/12\/1-4.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><h2 class=\"woocommerce-loop-product__title\">Berry serum &#8211; a plant-based alternative to retinol &#8211; 30 ml.<\/h2><div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:96.6%\">Rated <strong class=\"rating\">4.83<\/strong> out of 5<\/span><\/div><\/div>\n\t<span class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\"><bdi>20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13104\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"13104\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Berry serum - a plant-based alternative to retinol - 30 ml.&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13104\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/li>\n<li class=\"desktop-align-left tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-single-variable ast-product-tabs-layout-horizontal product type-product post-14072 status-publish instock product_cat-natural-cosmetics has-post-thumbnail taxable shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia-kopia\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-600x731.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/mgielka-z-aloesem.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/Into-the-trees-na-lipie-600x731.jpg\" class=\"show-on-hover\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/Into-the-trees-na-lipie-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/Into-the-trees-na-lipie-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/Into-the-trees-na-lipie-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/Into-the-trees-na-lipie-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/05\/Into-the-trees-na-lipie.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><h2 class=\"woocommerce-loop-product__title\">Into the trees &#8211; prebiotic mist with aloe vera and poplar buds &#8211; 100 ml<\/h2><div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:94.6%\">Rated <strong class=\"rating\">4.73<\/strong> out of 5<\/span><\/div><\/div>\n\t<span class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\"><bdi>98,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia-kopia\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14072\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"14072\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Into the trees - prebiotic mist with aloe vera and poplar buds - 100 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14072\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/li>\n<li class=\"desktop-align-left tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-single-variable ast-product-tabs-layout-horizontal product type-product post-13431 status-publish last instock product_cat-natural-cosmetics has-post-thumbnail taxable shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/1-2-600x731.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Cherry Kisses - vegan lip balm with clover flowers - 15 ml\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/1-2-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/1-2-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/1-2-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/1-2-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/1-2.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"731\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/3-2-600x731.jpg\" class=\"show-on-hover\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/3-2-600x731.jpg 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/3-2-246x300.jpg 246w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/3-2-840x1024.jpg 840w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/3-2-768x936.jpg 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/03\/3-2.jpg 960w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><h2 class=\"woocommerce-loop-product__title\">Cherry Kisses &#8211; vegan lip balm with clover flowers &#8211; 15 ml<\/h2><div class=\"review-rating\"><div class=\"star-rating\"><span style=\"width:100%\">Rated <strong class=\"rating\">5.00<\/strong> out of 5<\/span><\/div><\/div>\n\t<span class=\"price\">From&nbsp;<span class=\"woocommerce-Price-amount amount\"><bdi>56,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#122;&#322;<\/span><\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/boskapszczola.pl\/en\/produkt\/berry-serum-a-plant-based-alternative-to-retinol-30-ml-kopia\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13431\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button cfvsw_ajax_add_to_cart \" data-product_id=\"13431\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Cherry Kisses - vegan lip balm with clover flowers - 15 ml&rdquo;\" rel=\"nofollow\" data-add_to_cart_text=\"Add to Cart\" data-select_options_text=\"Select options\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13431\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e23f358 e-flex e-con-boxed e-con e-parent\" data-id=\"e23f358\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;curve&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M1000,4.3V0H0v4.3C0.9,23.1,126.7,99.2,500,100S1000,22.7,1000,4.3z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64327dc e-con-full e-flex e-con e-child\" data-id=\"64327dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e9d9f0 elementor-widget elementor-widget-image\" data-id=\"6e9d9f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-1024x1024.png\" class=\"attachment-large size-large wp-image-13025\" alt=\"\" srcset=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-1024x1024.png 1024w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-300x300.png 300w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-150x150.png 150w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-768x768.png 768w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-600x600.png 600w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post-100x100.png 100w, https:\/\/boskapszczola.pl\/wp-content\/uploads\/2025\/01\/Giveaway-with-Tablet-Mockup-Instagram-Post.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af37ca4 e-con-full e-flex e-con e-child\" data-id=\"af37ca4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9416e7 elementor-widget elementor-widget-heading\" data-id=\"a9416e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Catch a cool dose of knowledge and flourish<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-560d216 elementor-button-align-start elementor-mobile-button-align-center elementor-widget elementor-widget-form\" data-id=\"560d216\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New form\" aria-label=\"New form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"15350\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"560d216\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-70 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Your e-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_49e6d43 elementor-col-70 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_49e6d43]\" id=\"form-field-field_49e6d43\" class=\"elementor-field elementor-size-md  elementor-acceptance-field\" required=\"required\" checked=\"checked\">\n\t\t\t\t<label for=\"form-field-field_49e6d43\">I agree to send discounts and promotions, sales and marketing information, including an ebook, electronically to the email address provided<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DOWNLOAD EBOOK<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>rating: 4.90 | 12.5K+ followers LET YOUR SKIN BLOOM WITH HERBS &amp; FLOWERS Enjoy insanely soft and radiant skin, just like 1092+ of my customers Discover your ritual FEED YOUR SKIN WITH HERBS 100% natural, herbal skincare Sheer goodness for your skin. No artificial fragrances, preservatives or dyes Fresh, raw and unprocessed Ingredients from life-giving [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12766,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-15350","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boska pszczo\u0142a - 100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142<\/title>\n<meta name=\"description\" content=\"Fresh, raw, organic, highly bioactive, skin flora-enhancing, handmade, fully plant-based essences from meadows and wildflowers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boskapszczola.pl\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boska pszczo\u0142a - 100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\" \/>\n<meta property=\"og:description\" content=\"Fresh, raw, organic, highly bioactive, skin flora-enhancing, handmade, fully plant-based essences from meadows and wildflowers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boskapszczola.pl\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T09:45:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/03\/wildflowers1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/\",\"url\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/\",\"name\":\"Boska pszczo\u0142a - 100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boskapszczola.pl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/wildflowers1.jpg\",\"datePublished\":\"2026-02-23T19:41:40+00:00\",\"dateModified\":\"2026-04-29T09:45:06+00:00\",\"description\":\"Fresh, raw, organic, highly bioactive, skin flora-enhancing, handmade, fully plant-based essences from meadows and wildflowers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boskapszczola.pl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/wildflowers1.jpg\",\"contentUrl\":\"https:\\\/\\\/boskapszczola.pl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/wildflowers1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/boskapszczola.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boska pszczo\u0142a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/#website\",\"url\":\"https:\\\/\\\/boskapszczola.pl\\\/\",\"name\":\"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\",\"description\":\"\u015awie\u017co ukr\u0119cone kosmetyki z dzikiej \u0142\u0105ki\",\"publisher\":{\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boskapszczola.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/#organization\",\"name\":\"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\",\"url\":\"https:\\\/\\\/boskapszczola.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boskapszczola.pl\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/cropped-cropped-logo_2.png\",\"contentUrl\":\"https:\\\/\\\/boskapszczola.pl\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/cropped-cropped-logo_2.png\",\"width\":414,\"height\":194,\"caption\":\"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142\"},\"image\":{\"@id\":\"https:\\\/\\\/boskapszczola.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boska pszczo\u0142a - 100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142","description":"Fresh, raw, organic, highly bioactive, skin flora-enhancing, handmade, fully plant-based essences from meadows and wildflowers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boskapszczola.pl\/en\/","og_locale":"en_US","og_type":"article","og_title":"Boska pszczo\u0142a - 100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142","og_description":"Fresh, raw, organic, highly bioactive, skin flora-enhancing, handmade, fully plant-based essences from meadows and wildflowers.","og_url":"https:\/\/boskapszczola.pl\/en\/","og_site_name":"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142","article_modified_time":"2026-04-29T09:45:06+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/03\/wildflowers1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boskapszczola.pl\/en\/","url":"https:\/\/boskapszczola.pl\/en\/","name":"Boska pszczo\u0142a - 100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142","isPartOf":{"@id":"https:\/\/boskapszczola.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boskapszczola.pl\/en\/#primaryimage"},"image":{"@id":"https:\/\/boskapszczola.pl\/en\/#primaryimage"},"thumbnailUrl":"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/03\/wildflowers1.jpg","datePublished":"2026-02-23T19:41:40+00:00","dateModified":"2026-04-29T09:45:06+00:00","description":"Fresh, raw, organic, highly bioactive, skin flora-enhancing, handmade, fully plant-based essences from meadows and wildflowers.","breadcrumb":{"@id":"https:\/\/boskapszczola.pl\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boskapszczola.pl\/en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boskapszczola.pl\/en\/#primaryimage","url":"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/03\/wildflowers1.jpg","contentUrl":"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2023\/03\/wildflowers1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/boskapszczola.pl\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/boskapszczola.pl\/en\/"},{"@type":"ListItem","position":2,"name":"Boska pszczo\u0142a"}]},{"@type":"WebSite","@id":"https:\/\/boskapszczola.pl\/#website","url":"https:\/\/boskapszczola.pl\/","name":"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142","description":"\u015awie\u017co ukr\u0119cone kosmetyki z dzikiej \u0142\u0105ki","publisher":{"@id":"https:\/\/boskapszczola.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boskapszczola.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/boskapszczola.pl\/#organization","name":"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142","url":"https:\/\/boskapszczola.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/boskapszczola.pl\/#\/schema\/logo\/image\/","url":"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2018\/07\/cropped-cropped-logo_2.png","contentUrl":"https:\/\/boskapszczola.pl\/wp-content\/uploads\/2018\/07\/cropped-cropped-logo_2.png","width":414,"height":194,"caption":"100% naturalne, ro\u015blinne kosmetyki z \u0142\u0105k i zi\u00f3\u0142"},"image":{"@id":"https:\/\/boskapszczola.pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/pages\/15350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/comments?post=15350"}],"version-history":[{"count":3,"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/pages\/15350\/revisions"}],"predecessor-version":[{"id":16360,"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/pages\/15350\/revisions\/16360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/media\/12766"}],"wp:attachment":[{"href":"https:\/\/boskapszczola.pl\/en\/wp-json\/wp\/v2\/media?parent=15350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}